{"id":12086,"date":"2026-01-12T12:08:17","date_gmt":"2026-01-12T12:08:17","guid":{"rendered":"https:\/\/przedszkolefairplay.info.pl\/placowki\/non-public-sports-language-nursery-preschool\/"},"modified":"2026-03-02T12:08:02","modified_gmt":"2026-03-02T12:08:02","slug":"non-public-sports-language-nursery-preschool","status":"publish","type":"placowki","link":"https:\/\/przedszkolefairplay.info.pl\/en\/facilities\/non-public-sports-language-nursery-preschool\/","title":{"rendered":"Non-Public Sports &amp; Language Nursery\u2013Preschool"},"content":{"rendered":"<style>.kb-row-layout-id8372_91c893-b5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_91c893-b5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_91c893-b5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:140px;padding-bottom:32px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8372_91c893-b5{background-image:url('https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_366737023-Przekonwertowany-01-13-9.svg');background-size:cover;background-position:0% 100%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id8372_91c893-b5 > .kt-row-layout-overlay{opacity:0.56;background:radial-gradient(ellipse at right top,rgba(255,255,255,0.84) undefined%,rgba(255,255,255,0) 39%);}@media all and (max-width: 1024px){.kb-row-layout-id8372_91c893-b5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_91c893-b5 > .kt-row-column-wrap{padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}}.main-navigation .primary-menu-container > ul > li.menu-item.current-menu-item > a{  background: #B78EF065;}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_91c893-b5 alignnone kt-row-has-bg wp-block-kadence-rowlayout\" id=\"baner-glowny\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column8372_fcc446-3f > .kt-inside-inner-col,.kadence-column8372_fcc446-3f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_fcc446-3f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_fcc446-3f > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_fcc446-3f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_fcc446-3f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_fcc446-3f{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_fcc446-3f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_fcc446-3f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_fcc446-3f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_a25724-a8, .wp-block-kadence-advancedheading.kt-adv-heading8372_a25724-a8[data-kb-block=\"kb-adv-heading8372_a25724-a8\"]{max-width:991px;line-height:1.3;font-style:normal;text-shadow:1px 1px 30px #ffffff;}.wp-block-kadence-advancedheading.kt-adv-heading8372_a25724-a8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_a25724-a8[data-kb-block=\"kb-adv-heading8372_a25724-a8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_a25724-a8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_a25724-a8[data-kb-block=\"kb-adv-heading8372_a25724-a8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8372_a25724-a8, .wp-block-kadence-advancedheading.kt-adv-heading8372_a25724-a8[data-kb-block=\"kb-adv-heading8372_a25724-a8\"]{text-shadow:1px 1px 30px #ffffff;font-size:42px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8372_a25724-a8, .wp-block-kadence-advancedheading.kt-adv-heading8372_a25724-a8[data-kb-block=\"kb-adv-heading8372_a25724-a8\"]{text-shadow:1px 1px 30px #ffffff;}}<\/style>\n<h1 class=\"kt-adv-heading8372_a25724-a8 placowka-header wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_a25724-a8\">Non-Public Sports &amp; Language Nursery\u2013Preschool Wieliczka, Lednica G\u00f3rna 207<\/h1>\n\n\n<style>.kadence-column8372_e00978-d5 > .kt-inside-inner-col{display:flex;}.kadence-column8372_e00978-d5 > .kt-inside-inner-col,.kadence-column8372_e00978-d5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_e00978-d5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_e00978-d5 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column8372_e00978-d5 > .kt-inside-inner-col > *, .kadence-column8372_e00978-d5 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_e00978-d5 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_e00978-d5 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column8372_e00978-d5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_e00978-d5{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_e00978-d5 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column8372_e00978-d5 > .kt-inside-inner-col > *, .kadence-column8372_e00978-d5 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_e00978-d5 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_e00978-d5 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column8372_e00978-d5 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column8372_e00978-d5 > .kt-inside-inner-col > *, .kadence-column8372_e00978-d5 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_e00978-d5 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_e00978-d5 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_e00978-d5 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column8372_ddb480-60 > .kt-inside-inner-col{display:flex;}.kadence-column8372_ddb480-60 > .kt-inside-inner-col,.kadence-column8372_ddb480-60 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_ddb480-60 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_ddb480-60 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column8372_ddb480-60 > .kt-inside-inner-col > *, .kadence-column8372_ddb480-60 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_ddb480-60 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_ddb480-60 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column8372_ddb480-60{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_ddb480-60{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_ddb480-60 > .kt-inside-inner-col{align-items:center;}.kadence-column8372_ddb480-60 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_ddb480-60{position:relative;}.kadence-column8372_ddb480-60, .kt-inside-inner-col > .kadence-column8372_ddb480-60:not(.specificity){margin-top:10px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_ddb480-60{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_ddb480-60{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_ddb480-60 > .kt-inside-inner-col{align-items:center;}}@media all and (max-width: 1024px){.kadence-column8372_ddb480-60 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column8372_ddb480-60 > .kt-inside-inner-col > *, .kadence-column8372_ddb480-60 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_ddb480-60 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_ddb480-60 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_ddb480-60{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_ddb480-60{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_ddb480-60 > .kt-inside-inner-col{align-items:center;}.kadence-column8372_ddb480-60 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column8372_ddb480-60 > .kt-inside-inner-col > *, .kadence-column8372_ddb480-60 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_ddb480-60 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_ddb480-60 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_ddb480-60 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns8372_2ace11-47{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns8372_2ace11-47 .kt-button{font-weight:normal;font-style:normal;}.kt-btns8372_2ace11-47 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns8372_2ace11-47 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns8372_2ace11-47 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_2ace11-47 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns8372_2ace11-47 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns8372_2ace11-47 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_2ace11-47 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8372_2ace11-47\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn8372_d9f54a-ee.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn8372_d9f54a-ee.kb-button{padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn8372_d9f54a-ee.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_d9f54a-ee.kb-button:focus{color:var(--global-palette9, #ffffff);border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8372_d9f54a-ee.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_d9f54a-ee.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8372_d9f54a-ee.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_d9f54a-ee.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn8372_d9f54a-ee kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"#zapisz\"><span class=\"kt-btn-inner-text\">Enroll your child<\/span><\/a><\/div>\n\n\n<style>.kadence-column8372_c802aa-f1 > .kt-inside-inner-col{display:flex;}.kadence-column8372_c802aa-f1{max-width:45px;margin-left:auto;margin-right:auto;}.wp-block-kadence-column.kb-section-dir-horizontal:not(.kb-section-md-dir-vertical)>.kt-inside-inner-col>.kadence-column8372_c802aa-f1{-webkit-flex:0 1 45px;flex:0 1 45px;max-width:unset;margin-left:unset;margin-right:unset;}.kadence-column8372_c802aa-f1 > .kt-inside-inner-col,.kadence-column8372_c802aa-f1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_c802aa-f1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_c802aa-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_c802aa-f1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_c802aa-f1{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c802aa-f1{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c802aa-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_c802aa-f1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_c802aa-f1{z-index:2;position:relative;}.kadence-column8372_c802aa-f1, .kt-inside-inner-col > .kadence-column8372_c802aa-f1:not(.specificity){margin-left:-71px;}@media all and (min-width: 1025px){.wp-block-kadence-column.kb-section-dir-horizontal>.kt-inside-inner-col>.kadence-column8372_c802aa-f1{-webkit-flex:0 1 45px;flex:0 1 45px;max-width:unset;margin-left:unset;margin-right:unset;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_c802aa-f1{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c802aa-f1{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c802aa-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_c802aa-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_c802aa-f1{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c802aa-f1{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c802aa-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.wp-block-kadence-column.kb-section-sm-dir-vertical:not(.kb-section-sm-dir-horizontal):not(.kb-section-sm-dir-specificity)>.kt-inside-inner-col>.kadence-column8372_c802aa-f1{max-width:45px;-webkit-flex:1;flex:1;margin-left:auto;margin-right:auto;}.kadence-column8372_c802aa-f1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_c802aa-f1 btn-icon\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons8372_932d93-f6 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons8372_932d93-f6{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons8372_932d93-f6 alignnone\"><style>.kt-svg-item-8372_fa6dd5-c2 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-8372_fa6dd5-c2 .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:0px;margin-left:-75px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-8372_fa6dd5-c2\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_a3d3f8-28, .wp-block-kadence-advancedheading.kt-adv-heading8372_a3d3f8-28[data-kb-block=\"kb-adv-heading8372_a3d3f8-28\"]{margin-left:-30px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_a3d3f8-28 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_a3d3f8-28[data-kb-block=\"kb-adv-heading8372_a3d3f8-28\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_a3d3f8-28 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_a3d3f8-28[data-kb-block=\"kb-adv-heading8372_a3d3f8-28\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8372_a3d3f8-28, .wp-block-kadence-advancedheading.kt-adv-heading8372_a3d3f8-28[data-kb-block=\"kb-adv-heading8372_a3d3f8-28\"]{margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8372_a3d3f8-28, .wp-block-kadence-advancedheading.kt-adv-heading8372_a3d3f8-28[data-kb-block=\"kb-adv-heading8372_a3d3f8-28\"]{margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}}<\/style>\n<p class=\"kt-adv-heading8372_a3d3f8-28 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_a3d3f8-28\">We raise children in the spirit of fair play \u2013 with movement, joy and passion<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id8372_1a930d-e9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_1a930d-e9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_1a930d-e9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id8372_1a930d-e9{background-image:url('https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_366737023-Przekonwertowany-01-14.svg');background-size:auto;background-position:64% 0%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id8372_1a930d-e9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_1a930d-e9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_1a930d-e9 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_1a930d-e9 alignnone kt-row-has-bg wp-block-kadence-rowlayout\" id=\"wprowadzenie\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column8372_1a949e-97 > .kt-inside-inner-col,.kadence-column8372_1a949e-97 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_1a949e-97 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_1a949e-97 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_1a949e-97 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_1a949e-97 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_1a949e-97{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_1a949e-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_1a949e-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_1a949e-97\"><div class=\"kt-inside-inner-col\"><style>.kadence-column8372_86574c-87 > .kt-inside-inner-col{padding-right:10px;}.kadence-column8372_86574c-87 > .kt-inside-inner-col,.kadence-column8372_86574c-87 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_86574c-87 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_86574c-87 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_86574c-87 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_86574c-87 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_86574c-87{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_86574c-87 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_86574c-87 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_86574c-87 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id8372_514087-12 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}@media all and (max-width: 767px){.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap{padding-top:40px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id8372_514087-12 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_514087-12 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column8372_9a4ad2-5a > .kt-inside-inner-col,.kadence-column8372_9a4ad2-5a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_9a4ad2-5a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_9a4ad2-5a > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_9a4ad2-5a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_9a4ad2-5a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_9a4ad2-5a{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_9a4ad2-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_9a4ad2-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_9a4ad2-5a inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-image8372_f5b696-74 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image8372_f5b696-74 img.kb-img, .kb-image8372_f5b696-74 .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;object-position:28.000000000000004% 61%;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_f5b696-74 size-full kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_320819860.webp\" alt=\"\" class=\"kb-img wp-image-7953\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_320819860.webp 1920w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_320819860-300x200.webp 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_320819860-1024x683.webp 1024w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_320819860-768x512.webp 768w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_320819860-1536x1024.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_91853a-2c > .kt-inside-inner-col,.kadence-column8372_91853a-2c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_91853a-2c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_91853a-2c > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_91853a-2c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_91853a-2c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_91853a-2c{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_91853a-2c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_91853a-2c > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_91853a-2c inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-image8372_250a64-54 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image8372_250a64-54 img.kb-img, .kb-image8372_250a64-54 .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;object-position:39% 50%;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_250a64-54 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-port23\"><img loading=\"lazy\" decoding=\"async\" width=\"870\" height=\"580\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_415403998.webp\" alt=\"\" class=\"kb-img wp-image-8067\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_415403998.webp 870w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_415403998-300x200.webp 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_415403998-768x512.webp 768w\" sizes=\"auto, (max-width: 870px) 100vw, 870px\" \/><\/div><\/figure>\n\n\n<style>.kadence-column8372_918eeb-a5 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column8372_918eeb-a5 > .kt-inside-inner-col{box-shadow:0px 0px 60px 5px rgba(0, 0, 0, 0.2);}.kadence-column8372_918eeb-a5 > .kt-inside-inner-col,.kadence-column8372_918eeb-a5 > .kt-inside-inner-col:before{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kadence-column8372_918eeb-a5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_918eeb-a5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_918eeb-a5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_918eeb-a5 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column8372_918eeb-a5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_918eeb-a5{z-index:4;position:relative;}.kadence-column8372_918eeb-a5, .kt-inside-inner-col > .kadence-column8372_918eeb-a5:not(.specificity){margin-top:-150px;margin-right:120px;margin-left:-370px;}@media all and (max-width: 1024px){.kadence-column8372_918eeb-a5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_918eeb-a5, .kt-inside-inner-col > .kadence-column8372_918eeb-a5:not(.specificity){margin-top:0px;margin-right:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column8372_918eeb-a5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_918eeb-a5, .kt-inside-inner-col > .kadence-column8372_918eeb-a5:not(.specificity){margin-right:0px;margin-left:0px;}}@media (min-width:1024px) and (max-width:1400px) {.kadence-column8372_918eeb-a5 {  margin-right: 20px !important;  margin-left:-110%!important;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_918eeb-a5\"><div class=\"kt-inside-inner-col\">\n<p class=\"wp-block-paragraph\">Our facility is located in Lednica G\u00f3rna in a newly constructed building with a total area of approx. 500 sq m. There are playgrounds next to the facility with designated safety zones and properly selected equipment for both nursery and preschool children.  <br\/><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_c5527f-c7 > .kt-inside-inner-col{display:flex;}.kadence-column8372_c5527f-c7 > .kt-inside-inner-col,.kadence-column8372_c5527f-c7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_c5527f-c7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_c5527f-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_c5527f-c7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_c5527f-c7{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c5527f-c7{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c5527f-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_c5527f-c7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_c5527f-c7{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_c5527f-c7{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c5527f-c7{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c5527f-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_c5527f-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_c5527f-c7{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c5527f-c7{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c5527f-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_c5527f-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_c5527f-c7\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_4eab30-66, .wp-block-kadence-advancedheading.kt-adv-heading8372_4eab30-66[data-kb-block=\"kb-adv-heading8372_4eab30-66\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left;font-size:49px;line-height:1.3;font-weight:700;font-style:normal;font-family:'Plus Jakarta Sans';}.wp-block-kadence-advancedheading.kt-adv-heading8372_4eab30-66 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_4eab30-66[data-kb-block=\"kb-adv-heading8372_4eab30-66\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_4eab30-66 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_4eab30-66[data-kb-block=\"kb-adv-heading8372_4eab30-66\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8372_4eab30-66, .wp-block-kadence-advancedheading.kt-adv-heading8372_4eab30-66[data-kb-block=\"kb-adv-heading8372_4eab30-66\"]{font-size:49px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8372_4eab30-66, .wp-block-kadence-advancedheading.kt-adv-heading8372_4eab30-66[data-kb-block=\"kb-adv-heading8372_4eab30-66\"]{font-size:30px;}}<\/style>\n<h3 class=\"kt-adv-heading8372_4eab30-66 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_4eab30-66\">About us<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_1d5228-15, .wp-block-kadence-advancedheading.kt-adv-heading8372_1d5228-15[data-kb-block=\"kb-adv-heading8372_1d5228-15\"]{max-width:556px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_1d5228-15 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_1d5228-15[data-kb-block=\"kb-adv-heading8372_1d5228-15\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_1d5228-15 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_1d5228-15[data-kb-block=\"kb-adv-heading8372_1d5228-15\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8372_1d5228-15, .wp-block-kadence-advancedheading.kt-adv-heading8372_1d5228-15[data-kb-block=\"kb-adv-heading8372_1d5228-15\"]{max-width:2000px;}}<\/style>\n<p class=\"kt-adv-heading8372_1d5228-15 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_1d5228-15\">On the ground floor of the building, three nursery rooms have been created. Pastel colors and carefully selected, certified toys make every child\u2019s time enjoyable. Qualified caregivers with extensive experience and training, including first aid courses, take care of your little ones with the utmost attention. Time spent in our nursery includes engaging movement and music activities, both guided and free play, during which children learn the principles of functioning in a social group, fairy tale therapy, educational activities adapted to developmental stages, learning independence and taking their first steps in the education system \u2013 with the possibility to continue up to the age of 6 thanks to the preschool unit located on the first floor.     <br\/><\/p>\n\n\n<style>.kadence-column8372_cb0a68-aa > .kt-inside-inner-col{display:flex;}.kadence-column8372_cb0a68-aa > .kt-inside-inner-col,.kadence-column8372_cb0a68-aa > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_cb0a68-aa > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_cb0a68-aa > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column8372_cb0a68-aa > .kt-inside-inner-col > *, .kadence-column8372_cb0a68-aa > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_cb0a68-aa > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_cb0a68-aa > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column8372_cb0a68-aa{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_cb0a68-aa{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_cb0a68-aa > .kt-inside-inner-col{align-items:center;}.kadence-column8372_cb0a68-aa > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_cb0a68-aa{position:relative;}.kadence-column8372_cb0a68-aa, .kt-inside-inner-col > .kadence-column8372_cb0a68-aa:not(.specificity){margin-top:10px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_cb0a68-aa{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_cb0a68-aa{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_cb0a68-aa > .kt-inside-inner-col{align-items:center;}}@media all and (max-width: 1024px){.kadence-column8372_cb0a68-aa > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column8372_cb0a68-aa > .kt-inside-inner-col > *, .kadence-column8372_cb0a68-aa > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_cb0a68-aa > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_cb0a68-aa > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_cb0a68-aa{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_cb0a68-aa{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_cb0a68-aa > .kt-inside-inner-col{align-items:center;}.kadence-column8372_cb0a68-aa > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column8372_cb0a68-aa > .kt-inside-inner-col > *, .kadence-column8372_cb0a68-aa > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_cb0a68-aa > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_cb0a68-aa > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_cb0a68-aa kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns8372_517a47-7a{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns8372_517a47-7a .kt-button{font-weight:normal;font-style:normal;}.kt-btns8372_517a47-7a .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns8372_517a47-7a .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns8372_517a47-7a .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_517a47-7a .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns8372_517a47-7a .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns8372_517a47-7a .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_517a47-7a .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8372_517a47-7a\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn8372_e23052-b1.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn8372_e23052-b1.kb-button{padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn8372_e23052-b1.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_e23052-b1.kb-button:focus{color:var(--global-palette9, #ffffff);border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8372_e23052-b1.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_e23052-b1.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8372_e23052-b1.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_e23052-b1.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn8372_e23052-b1 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"#zapisz\"><span class=\"kt-btn-inner-text\">Enroll your child<\/span><\/a><\/div>\n\n\n<style>.kadence-column8372_b04e56-10 > .kt-inside-inner-col{display:flex;}.kadence-column8372_b04e56-10{max-width:45px;margin-left:auto;margin-right:auto;}.wp-block-kadence-column.kb-section-dir-horizontal:not(.kb-section-md-dir-vertical)>.kt-inside-inner-col>.kadence-column8372_b04e56-10{-webkit-flex:0 1 45px;flex:0 1 45px;max-width:unset;margin-left:unset;margin-right:unset;}.kadence-column8372_b04e56-10 > .kt-inside-inner-col,.kadence-column8372_b04e56-10 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_b04e56-10 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_b04e56-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_b04e56-10 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_b04e56-10{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b04e56-10{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b04e56-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_b04e56-10 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_b04e56-10{z-index:2;position:relative;}.kadence-column8372_b04e56-10, .kt-inside-inner-col > .kadence-column8372_b04e56-10:not(.specificity){margin-left:-71px;}@media all and (min-width: 1025px){.wp-block-kadence-column.kb-section-dir-horizontal>.kt-inside-inner-col>.kadence-column8372_b04e56-10{-webkit-flex:0 1 45px;flex:0 1 45px;max-width:unset;margin-left:unset;margin-right:unset;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_b04e56-10{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b04e56-10{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b04e56-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_b04e56-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_b04e56-10{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b04e56-10{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b04e56-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.wp-block-kadence-column.kb-section-sm-dir-vertical:not(.kb-section-sm-dir-horizontal):not(.kb-section-sm-dir-specificity)>.kt-inside-inner-col>.kadence-column8372_b04e56-10{max-width:45px;-webkit-flex:1;flex:1;margin-left:auto;margin-right:auto;}.kadence-column8372_b04e56-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_b04e56-10 btn-icon\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons8372_b1cabf-b1 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons8372_b1cabf-b1{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons8372_b1cabf-b1 alignnone\"><style>.kt-svg-item-8372_976458-c8 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-8372_976458-c8 .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:0px;margin-left:-75px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-8372_976458-c8\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id8372_904fb2-73 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_904fb2-73 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_904fb2-73 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, calc(45% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(55% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id8372_904fb2-73 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_904fb2-73 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_904fb2-73 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_904fb2-73 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column8372_006856-ba > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column8372_006856-ba > .kt-inside-inner-col,.kadence-column8372_006856-ba > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_006856-ba > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_006856-ba > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_006856-ba > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_006856-ba > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_006856-ba{z-index:5;position:relative;}@media all and (max-width: 1024px){.kadence-column8372_006856-ba > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_006856-ba > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}.kadence-column8372_006856-ba button.splide__arrow.splide__arrow--prev.slick-prev {\r    background: white;\r    color: black;\r    opacity: 100 !important;\r    width: 47px;\r    border-radius: 101px;\r        box-shadow: 0px 4px 22.9px 0px rgba(0, 0, 0, 0.12);\r}\r.kadence-column8372_006856-ba button.splide__arrow.splide__arrow--next.slick-next {\r    background: white;\r    color: black;\r    opacity: 100 !important;\r    width: 47px;\r    border-radius: 101px;\r        box-shadow: 0px 4px 22.9px 0px rgba(0, 0, 0, 0.12);\r}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_006856-ba\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_0c288b-86, .wp-block-kadence-advancedheading.kt-adv-heading8372_0c288b-86[data-kb-block=\"kb-adv-heading8372_0c288b-86\"]{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_0c288b-86 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_0c288b-86[data-kb-block=\"kb-adv-heading8372_0c288b-86\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_0c288b-86 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_0c288b-86[data-kb-block=\"kb-adv-heading8372_0c288b-86\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_0c288b-86 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_0c288b-86\">Thanks to the funding received, the tuition fee for the 2025\/2026 school year is 299 PLN and this amount is guaranteed for the entire school year.<br\/><br\/>In preschool groups, we follow the national core curriculum while ensuring the comprehensive development of your children in line with their individual predispositions, helping them discover new talents and interests. We stimulate intellectual development during educational activities using the learning-through-play method, as well as physical development through sports and daily movement activities. We believe that such a holistic approach is the best way to prepare a young person for life in the modern world.  <\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_0d9497-82 > .kt-inside-inner-col,.kadence-column8372_0d9497-82 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_0d9497-82 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_0d9497-82 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_0d9497-82 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_0d9497-82 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_0d9497-82{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_0d9497-82 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_0d9497-82 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_0d9497-82 container-image\"><div class=\"kt-inside-inner-col\"><style>.kb-image8372_813160-aa .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image8372_813160-aa img.kb-img, .kb-image8372_813160-aa .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_813160-aa size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"945\" height=\"945\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/lednica.png\" alt=\"\" class=\"kb-img wp-image-8375\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/lednica.png 945w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/lednica-300x300.png 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/lednica-150x150.png 150w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/lednica-768x768.png 768w\" sizes=\"auto, (max-width: 945px) 100vw, 945px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id8372_c53eff-08 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_c53eff-08 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_c53eff-08 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, calc(45% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(55% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id8372_c53eff-08 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_c53eff-08 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_c53eff-08 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_c53eff-08 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column8372_20dfad-a8 > .kt-inside-inner-col,.kadence-column8372_20dfad-a8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_20dfad-a8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_20dfad-a8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_20dfad-a8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_20dfad-a8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_20dfad-a8{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_20dfad-a8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_20dfad-a8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_20dfad-a8 container-image\"><div class=\"kt-inside-inner-col\"><style>.kb-image8372_2ead50-54 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image8372_2ead50-54 img.kb-img, .kb-image8372_2ead50-54 .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_2ead50-54 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"870\" height=\"580\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_246553435.webp\" alt=\"\" class=\"kb-img wp-image-8064\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_246553435.webp 870w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_246553435-300x200.webp 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_246553435-768x512.webp 768w\" sizes=\"auto, (max-width: 870px) 100vw, 870px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_db936e-24 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column8372_db936e-24 > .kt-inside-inner-col,.kadence-column8372_db936e-24 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_db936e-24 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_db936e-24 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_db936e-24 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_db936e-24 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_db936e-24{z-index:5;position:relative;}@media all and (max-width: 1024px){.kadence-column8372_db936e-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_db936e-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}.kadence-column8372_db936e-24 button.splide__arrow.splide__arrow--prev.slick-prev {\r    background: white;\r    color: black;\r    opacity: 100 !important;\r    width: 47px;\r    border-radius: 101px;\r        box-shadow: 0px 4px 22.9px 0px rgba(0, 0, 0, 0.12);\r}\r.kadence-column8372_db936e-24 button.splide__arrow.splide__arrow--next.slick-next {\r    background: white;\r    color: black;\r    opacity: 100 !important;\r    width: 47px;\r    border-radius: 101px;\r        box-shadow: 0px 4px 22.9px 0px rgba(0, 0, 0, 0.12);\r}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_db936e-24\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_d170e6-32, .wp-block-kadence-advancedheading.kt-adv-heading8372_d170e6-32[data-kb-block=\"kb-adv-heading8372_d170e6-32\"]{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_d170e6-32 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_d170e6-32[data-kb-block=\"kb-adv-heading8372_d170e6-32\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_d170e6-32 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_d170e6-32[data-kb-block=\"kb-adv-heading8372_d170e6-32\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_d170e6-32 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_d170e6-32\">All of this is done with your children\u2019s well-being in mind, so that they feel comfortable, relaxed and safe. Colorful classrooms, healthy and tasty meals, and carefully selected, qualified staff ready to offer help and support in every situation await your little ones. <br\/><br\/>Our team consists of carefully selected teachers, childcare providers and external instructors who pass on ethical and moral values while caring for children\u2019s psychophysical development in every age group. Our main goal is to instill in children the habit of applying the principles of \u201cfair play\u201d in everyday and sports life \u2013 hence the name of our facility. With us, children learn cooperation, respect for others and acquire basic social skills among their peers.  <\/p>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id8372_0f3e5c-1d{margin-top:0px;margin-bottom:-20px;}.kb-row-layout-id8372_0f3e5c-1d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_0f3e5c-1d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_0f3e5c-1d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, calc(45% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)))minmax(0, calc(55% - ((var(--global-kb-gap-none, 0rem ) * 1 )\/2)));}.kb-row-layout-id8372_0f3e5c-1d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_0f3e5c-1d > .kt-row-column-wrap{padding-top:40px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_0f3e5c-1d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_0f3e5c-1d alignnone wp-block-kadence-rowlayout\" id=\"social-media\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column8372_7bfc2e-23 > .kt-inside-inner-col{display:flex;}.kadence-column8372_7bfc2e-23 > .kt-inside-inner-col,.kadence-column8372_7bfc2e-23 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_7bfc2e-23 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_7bfc2e-23 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_7bfc2e-23 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_7bfc2e-23{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_7bfc2e-23{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_7bfc2e-23 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_7bfc2e-23 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_7bfc2e-23{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_7bfc2e-23{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_7bfc2e-23{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_7bfc2e-23 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_7bfc2e-23 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_7bfc2e-23{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_7bfc2e-23{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_7bfc2e-23 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_7bfc2e-23 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_7bfc2e-23\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_eff1da-99, .wp-block-kadence-advancedheading.kt-adv-heading8372_eff1da-99[data-kb-block=\"kb-adv-heading8372_eff1da-99\"]{max-width:444px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left;font-size:49px;line-height:1.3;font-weight:700;font-style:normal;font-family:'Plus Jakarta Sans';}.wp-block-kadence-advancedheading.kt-adv-heading8372_eff1da-99 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_eff1da-99[data-kb-block=\"kb-adv-heading8372_eff1da-99\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_eff1da-99 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_eff1da-99[data-kb-block=\"kb-adv-heading8372_eff1da-99\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8372_eff1da-99, .wp-block-kadence-advancedheading.kt-adv-heading8372_eff1da-99[data-kb-block=\"kb-adv-heading8372_eff1da-99\"]{font-size:49px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8372_eff1da-99, .wp-block-kadence-advancedheading.kt-adv-heading8372_eff1da-99[data-kb-block=\"kb-adv-heading8372_eff1da-99\"]{font-size:30px;}}<\/style>\n<h3 class=\"kt-adv-heading8372_eff1da-99 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_eff1da-99\">Visit our Facebook profile<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_361812-18, .wp-block-kadence-advancedheading.kt-adv-heading8372_361812-18[data-kb-block=\"kb-adv-heading8372_361812-18\"]{max-width:556px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_361812-18 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_361812-18[data-kb-block=\"kb-adv-heading8372_361812-18\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_361812-18 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_361812-18[data-kb-block=\"kb-adv-heading8372_361812-18\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8372_361812-18, .wp-block-kadence-advancedheading.kt-adv-heading8372_361812-18[data-kb-block=\"kb-adv-heading8372_361812-18\"]{max-width:2000px;}}<\/style>\n<p class=\"kt-adv-heading8372_361812-18 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_361812-18\">We warmly invite you to explore the nursery and preschool events on our FB profile<\/p>\n\n\n<style>.kb-image8372_375b93-40.kb-image-is-ratio-size, .kb-image8372_375b93-40 .kb-image-is-ratio-size{max-width:235px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image8372_375b93-40.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image8372_375b93-40 .kb-image-is-ratio-size{align-self:unset;}.kb-image8372_375b93-40{max-width:235px;}.image-is-svg.kb-image8372_375b93-40{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image8372_375b93-40 img{width:100%;}.kb-image8372_375b93-40 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-right-radius:25px;border-bottom-left-radius:25px;}.kb-image8372_375b93-40 img.kb-img, .kb-image8372_375b93-40 .kb-img img{border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-right-radius:25px;border-bottom-left-radius:25px;}@media all and (max-width: 767px){.kb-image8372_375b93-40.kb-image-is-ratio-size, .kb-image8372_375b93-40 .kb-image-is-ratio-size{max-width:168px;width:100%;}.kb-image8372_375b93-40{max-width:168px;}.kb-image8372_375b93-40 .kb-image-has-overlay:after{border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-right-radius:12px;border-bottom-left-radius:12px;}.kb-image8372_375b93-40 img.kb-img, .kb-image8372_375b93-40 .kb-img img{border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-right-radius:12px;border-bottom-left-radius:12px;}}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_375b93-40 size-full is-resized\"><a href=\"https:\/\/www.facebook.com\/profile.php?id=100093465816533\" class=\"kb-advanced-image-link\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"200\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/11\/image.png\" alt=\"\" class=\"kb-img wp-image-7693\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/11\/image.png 500w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/11\/image-300x120.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_5074fe-21 > .kt-inside-inner-col,.kadence-column8372_5074fe-21 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_5074fe-21 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_5074fe-21 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_5074fe-21 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_5074fe-21 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_5074fe-21{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_5074fe-21 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_5074fe-21 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_5074fe-21\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image8372_bcaccd-3c:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:-20px;margin-right:-20px;margin-bottom:25px;margin-left:-20px;}.kb-image8372_bcaccd-3c .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_bcaccd-3c\"><img loading=\"lazy\" decoding=\"async\" width=\"820\" height=\"605\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/Frame-180-4.webp\" alt=\"\" class=\"kb-img wp-image-8215\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/Frame-180-4.webp 820w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/Frame-180-4-300x221.webp 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/Frame-180-4-768x567.webp 768w\" sizes=\"auto, (max-width: 820px) 100vw, 820px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id8372_60275a-b9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_60275a-b9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_60275a-b9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8372_60275a-b9{background-image:url('https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/Frame-183-6.svg');background-size:auto;background-position:50% 50%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id8372_60275a-b9 > .kt-row-layout-overlay{opacity:0.00;background:linear-gradient(0deg,var(--global-palette9) 0%,rgba(255,255,255,0) 49%,var(--global-palette9) 100%);}@media all and (max-width: 1024px){.kb-row-layout-id8372_60275a-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_60275a-b9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_60275a-b9 alignnone kt-row-has-bg wp-block-kadence-rowlayout\" id=\"strefa-rodzica\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column8372_a38aec-96 > .kt-inside-inner-col,.kadence-column8372_a38aec-96 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_a38aec-96 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_a38aec-96 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_a38aec-96 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_a38aec-96 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_a38aec-96{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_a38aec-96 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_a38aec-96 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}.kadence-column8372_a38aec-96 .kt-tab-title-active{    box-shadow: 0px 4px 63.9px 0px rgba(0, 0, 0, 0.15);border-radius:20px !important;}.kadence-column8372_a38aec-96 .wp-block-kadence-tab.kt-tab-inner-content {        box-shadow: 0px 4px 63.9px 0px rgba(0, 0, 0, 0.15);}.kadence-column8372_a38aec-96 strong {    color: #ff734f;}\/*ul.kt-tabs-title-list {*\/\/*    display: flex;*\/\/*    width: 2000px !important;*\/\/*}*\/\/*.kt-tabs-wrap {*\/\/*    overflow: auto;*\/\/*}*\/@media (max-width:767px) {.kadence-column8372_a38aec-96 .kt-tabs-title-list {  display: flex !important;  flex-wrap: nowrap !important;  overflow-x: auto !important;  overflow-y: visible !important; \/* WA\u017bNE *\/  padding: 20px 0 !important; \/* tylko g\u00f3ra\/d\u00f3\u0142 dla cienia *\/  scroll-snap-type: x mandatory;  -webkit-overflow-scrolling: touch;  padding-left:15px !important;    margin-left:-15px !important;  mask-image: linear-gradient(black, black); \/* hack: brak uci\u0119cia cienia *\/}.kadence-column8372_a38aec-96 .kt-tabs-title-list li {  flex: 0 0 auto;  margin-right: 20px;}.kadence-column8372_a38aec-96 .kt-tab-title-active{    box-shadow: 0px 4px 21.9px 0px rgba(0, 0, 0, 0.15);border-radius:20px !important;}.kadence-column8372_a38aec-96 .kt-tab-title-inactive .kt-tab-title{    background: #f1f1f1 !important;}.kadence-column8372_a38aec-96 .wp-block-kadence-tab.kt-tab-inner-content {        box-shadow: 0px 4px 21.9px 0px rgba(0, 0, 0, 0.15);      }.kadence-column8372_a38aec-96 .kt-tabs-title-list {  mask-image: linear-gradient(to right,    black 0,    black calc(100% - 40px),    transparent 100%  );  -webkit-mask-image: linear-gradient(to right,    black 0,    black calc(100% - 40px),    transparent 100%  );}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_a38aec-96\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_ac86b2-b6, .wp-block-kadence-advancedheading.kt-adv-heading8372_ac86b2-b6[data-kb-block=\"kb-adv-heading8372_ac86b2-b6\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left;font-size:49px;line-height:1.3;font-weight:700;font-style:normal;font-family:'Plus Jakarta Sans';}.wp-block-kadence-advancedheading.kt-adv-heading8372_ac86b2-b6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_ac86b2-b6[data-kb-block=\"kb-adv-heading8372_ac86b2-b6\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_ac86b2-b6 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_ac86b2-b6[data-kb-block=\"kb-adv-heading8372_ac86b2-b6\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8372_ac86b2-b6, .wp-block-kadence-advancedheading.kt-adv-heading8372_ac86b2-b6[data-kb-block=\"kb-adv-heading8372_ac86b2-b6\"]{font-size:49px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8372_ac86b2-b6, .wp-block-kadence-advancedheading.kt-adv-heading8372_ac86b2-b6[data-kb-block=\"kb-adv-heading8372_ac86b2-b6\"]{font-size:30px;}}<\/style>\n<h3 class=\"kt-adv-heading8372_ac86b2-b6 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_ac86b2-b6\">Parent Zone<\/h3>\n\n\n<style>.kt-tabs-id8372_0a98fa-7c > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;padding-top:40px;padding-right:40px;padding-bottom:40px;padding-left:40px;min-height:400px;background:var(--global-palette9, #ffffff);}.wp-block-kadence-tabs .kt-tabs-id8372_0a98fa-7c > .kt-tabs-title-list li{margin-top:0px;margin-right:10px;margin-bottom:30px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id8372_0a98fa-7c > .kt-tabs-title-list li:last-child{margin-right:0px;}.wp-block-kadence-tabs .kt-tabs-id8372_0a98fa-7c > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id8372_0a98fa-7c > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{line-height:1.4em;font-weight:regular;font-style:normal;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;padding-top:21px;padding-right:20px;padding-bottom:21px;padding-left:20px;border-color:var(--global-palette9, #ffffff);color:rgba(0,0,0,0.7);background:rgba(255,255,255,0);}.wp-block-kadence-tabs .kt-tabs-id8372_0a98fa-7c > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{margin-top:0px;margin-right:10px;margin-bottom:30px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id8372_0a98fa-7c > .kt-tabs-title-list li .kt-tab-title:hover, .wp-block-kadence-tabs .kt-tabs-id8372_0a98fa-7c > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title:hover{border-color:var(--global-palette8, #F7FAFC);color:#b78ef0;background:rgba(183,142,240,0.13);}.wp-block-kadence-tabs .kt-tabs-id8372_0a98fa-7c > .kt-tabs-title-list li.kt-tab-title-active .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id8372_0a98fa-7c > .kt-tabs-content-wrap > .kt-tabs-accordion-title.kt-tab-title-active .kt-tab-title{border-color:var(--global-palette7, #eeeeee);color:var(--global-palette3, #1A202C);background:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.kt-tabs-id8372_0a98fa-7c > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-tabs-id8372_0a98fa-7c > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);padding-top:40px;padding-right:20px;padding-bottom:40px;padding-left:25px;}.wp-block-kadence-tabs .kt-tabs-id8372_0a98fa-7c > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id8372_0a98fa-7c > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{padding-right:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}}<\/style>\n<div class=\"wp-block-kadence-tabs alignnone\"><div class=\"kt-tabs-wrap kt-tabs-id8372_0a98fa-7c kt-tabs-has-3-tabs kt-active-tab-1 kt-tabs-layout-tabs kt-tabs-tablet-layout-inherit kt-tabs-mobile-layout-tabs kt-tab-alignment-left \"><ul class=\"kt-tabs-title-list\"><li id=\"tab-niezbdnikprzedszkolakaobkowicza\" class=\"kt-title-item kt-title-item-1 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-active\"><a href=\"#tab-niezbdnikprzedszkolakaobkowicza\" data-tab=\"1\" class=\"kt-tab-title kt-tab-title-1 \"><span class=\"kt-title-text\">Preschooler\/Nursery Starter Kit<\/span><\/a><\/li><li id=\"tab-obiadki\" class=\"kt-title-item kt-title-item-2 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-obiadki\" data-tab=\"2\" class=\"kt-tab-title kt-tab-title-2 \"><span class=\"kt-title-text\">Meals<\/span><\/a><\/li><li id=\"tab-zajciadodatkowe\" class=\"kt-title-item kt-title-item-3 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-zajciadodatkowe\" data-tab=\"3\" class=\"kt-tab-title kt-tab-title-3 \"><span class=\"kt-title-text\">Additional activities<\/span><\/a><\/li><\/ul><div class=\"kt-tabs-content-wrap\">\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-1 kt-inner-tab8372_fed146-83\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id8372_a3f022-4b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_a3f022-4b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_a3f022-4b > .kt-row-column-wrap{column-gap:48px;row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:minmax(0, calc(36.8% - ((48px * 1 )\/2)))minmax(0, calc(63.2% - ((48px * 1 )\/2)));}.kb-row-layout-id8372_a3f022-4b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_a3f022-4b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_a3f022-4b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_a3f022-4b alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column8372_e1cc46-99 > .kt-inside-inner-col,.kadence-column8372_e1cc46-99 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_e1cc46-99 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_e1cc46-99 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_e1cc46-99 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_e1cc46-99 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_e1cc46-99{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_e1cc46-99 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_e1cc46-99 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_e1cc46-99 container-image\"><div class=\"kt-inside-inner-col\"><style>.kb-image8372_0189c1-7a .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image8372_0189c1-7a img.kb-img, .kb-image8372_0189c1-7a .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_0189c1-7a size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_493863693-1024x683.webp\" alt=\"\" class=\"kb-img wp-image-7957\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_493863693-1024x683.webp 1024w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_493863693-300x200.webp 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_493863693-768x512.webp 768w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_493863693-1536x1024.webp 1536w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_493863693.webp 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_3d24dd-49 > .kt-inside-inner-col,.kadence-column8372_3d24dd-49 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_3d24dd-49 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_3d24dd-49 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_3d24dd-49 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_3d24dd-49 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_3d24dd-49{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_3d24dd-49 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_3d24dd-49 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_3d24dd-49\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_eebc89-c2, .wp-block-kadence-advancedheading.kt-adv-heading8372_eebc89-c2[data-kb-block=\"kb-adv-heading8372_eebc89-c2\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_eebc89-c2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_eebc89-c2[data-kb-block=\"kb-adv-heading8372_eebc89-c2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_eebc89-c2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_eebc89-c2[data-kb-block=\"kb-adv-heading8372_eebc89-c2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading8372_eebc89-c2 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_eebc89-c2\">Preschooler\/Nursery Starter Kit<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_9e8f9d-c3, .wp-block-kadence-advancedheading.kt-adv-heading8372_9e8f9d-c3[data-kb-block=\"kb-adv-heading8372_9e8f9d-c3\"]{margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_9e8f9d-c3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_9e8f9d-c3[data-kb-block=\"kb-adv-heading8372_9e8f9d-c3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_9e8f9d-c3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_9e8f9d-c3[data-kb-block=\"kb-adv-heading8372_9e8f9d-c3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_9e8f9d-c3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_9e8f9d-c3\">The NURSERY starter kit should include:<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_3f5f6c-03:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_3f5f6c-03 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_3f5f6c-03 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_3f5f6c-03 .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_3f5f6c-03 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items8372_3f5f6c-03 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items8372_3f5f6c-03 kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop kt-mobile-svg-icon-list-columns-1\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-8372_1036c6-77 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_1036c6-77\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">a change of clothes,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_705ca9-cf .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_705ca9-cf\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">indoor shoes,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_a7ab79-d6 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_a7ab79-d6\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">a fitted sheet (60&#215;120), small pillow and bedding,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_7fceae-7c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_7fceae-7c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">a rubber bib,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_f2b057-8b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_f2b057-8b\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">a cup, toothbrush and toothpaste,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_77c6fe-c2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_77c6fe-c2\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">diapers, wet wipes and cream for children who require them,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_1ddcfb-38 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_1ddcfb-38\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">a favorite soft toy (optional) \u2013 attention!!!<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_ba7b48-85, .wp-block-kadence-advancedheading.kt-adv-heading8372_ba7b48-85[data-kb-block=\"kb-adv-heading8372_ba7b48-85\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_ba7b48-85 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_ba7b48-85[data-kb-block=\"kb-adv-heading8372_ba7b48-85\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_ba7b48-85 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_ba7b48-85[data-kb-block=\"kb-adv-heading8372_ba7b48-85\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_ba7b48-85 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_ba7b48-85\">The nursery is not responsible for lost toys.<br\/><br\/>Please label all the above items with your child\u2019s full name.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_e61338-4d, .wp-block-kadence-advancedheading.kt-adv-heading8372_e61338-4d[data-kb-block=\"kb-adv-heading8372_e61338-4d\"]{margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_e61338-4d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_e61338-4d[data-kb-block=\"kb-adv-heading8372_e61338-4d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_e61338-4d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_e61338-4d[data-kb-block=\"kb-adv-heading8372_e61338-4d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_e61338-4d wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_e61338-4d\">The PRESCHOOL starter kit should include:<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_d171c0-69:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_d171c0-69 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_d171c0-69 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_d171c0-69 .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_d171c0-69 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items8372_d171c0-69 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items8372_d171c0-69 kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop kt-mobile-svg-icon-list-columns-1\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-8372_70e239-1c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_70e239-1c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">a change of clothes,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_7a7c32-1c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_7a7c32-1c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">indoor shoes,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_34cc9f-03 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_34cc9f-03\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">a cup, toothbrush and toothpaste,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_6aa609-76 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_6aa609-76\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">in the youngest preschool group (where children nap): a fitted sheet (60&#215;120), small pillow and bedding.<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_6e888c-92, .wp-block-kadence-advancedheading.kt-adv-heading8372_6e888c-92[data-kb-block=\"kb-adv-heading8372_6e888c-92\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_6e888c-92 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_6e888c-92[data-kb-block=\"kb-adv-heading8372_6e888c-92\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_6e888c-92 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_6e888c-92[data-kb-block=\"kb-adv-heading8372_6e888c-92\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_6e888c-92 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_6e888c-92\">Please label all the above items with your child\u2019s full name.<br\/><\/p>\n\n\n<style>.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col{display:flex;}.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col,.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;justify-content:flex-start;}.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col > *, .kadence-column8372_8ef2e5-1c > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_8ef2e5-1c > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column8372_8ef2e5-1c{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_8ef2e5-1c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_8ef2e5-1c{position:relative;}.kadence-column8372_8ef2e5-1c, .kt-inside-inner-col > .kadence-column8372_8ef2e5-1c:not(.specificity){margin-top:10px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_8ef2e5-1c{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_8ef2e5-1c{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col{align-items:flex-start;}}@media all and (max-width: 1024px){.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;justify-content:flex-start;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col > *, .kadence-column8372_8ef2e5-1c > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_8ef2e5-1c > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_8ef2e5-1c{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_8ef2e5-1c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;justify-content:flex-start;}.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col > *, .kadence-column8372_8ef2e5-1c > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_8ef2e5-1c > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_8ef2e5-1c > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_8ef2e5-1c kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns8372_f6371b-81{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns8372_f6371b-81 .kt-button{font-weight:normal;font-style:normal;}.kt-btns8372_f6371b-81 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns8372_f6371b-81 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns8372_f6371b-81 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_f6371b-81 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns8372_f6371b-81 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns8372_f6371b-81 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_f6371b-81 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8372_f6371b-81\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn8372_00f0ca-a1.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn8372_00f0ca-a1.kb-button{padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn8372_00f0ca-a1.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_00f0ca-a1.kb-button:focus{color:var(--global-palette9, #ffffff);border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8372_00f0ca-a1.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_00f0ca-a1.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8372_00f0ca-a1.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_00f0ca-a1.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn8372_00f0ca-a1 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"#zapisz\"><span class=\"kt-btn-inner-text\">Enroll your child<\/span><\/a><\/div>\n\n\n<style>.kadence-column8372_b8bbce-71 > .kt-inside-inner-col{display:flex;}.kadence-column8372_b8bbce-71 > .kt-inside-inner-col,.kadence-column8372_b8bbce-71 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_b8bbce-71 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_b8bbce-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_b8bbce-71 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_b8bbce-71{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b8bbce-71{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b8bbce-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_b8bbce-71 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_b8bbce-71{z-index:2;position:relative;}.kadence-column8372_b8bbce-71, .kt-inside-inner-col > .kadence-column8372_b8bbce-71:not(.specificity){margin-left:-71px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_b8bbce-71{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b8bbce-71{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b8bbce-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_b8bbce-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_b8bbce-71{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b8bbce-71{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b8bbce-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_b8bbce-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_b8bbce-71 btn-icon\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons8372_d2c85a-32 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons8372_d2c85a-32{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons8372_d2c85a-32 alignnone\"><style>.kt-svg-item-8372_76ebed-62 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-8372_76ebed-62 .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:6px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-8372_76ebed-62\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-2 kt-inner-tab8372_7e33d9-af\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap{column-gap:48px;row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:minmax(0, calc(41% - ((48px * 1 )\/2)))minmax(0, calc(59% - ((48px * 1 )\/2)));}.kb-row-layout-id8372_0b8f03-9c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}@media all and (max-width: 767px){.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id8372_0b8f03-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_0b8f03-9c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-middle kt-inner-column-height-full\">\n<style>.kadence-column8372_2ed6f9-a3 > .kt-inside-inner-col,.kadence-column8372_2ed6f9-a3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_2ed6f9-a3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_2ed6f9-a3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_2ed6f9-a3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_2ed6f9-a3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_2ed6f9-a3{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_2ed6f9-a3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_2ed6f9-a3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_2ed6f9-a3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_d1ac7b-f3, .wp-block-kadence-advancedheading.kt-adv-heading8372_d1ac7b-f3[data-kb-block=\"kb-adv-heading8372_d1ac7b-f3\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_d1ac7b-f3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_d1ac7b-f3[data-kb-block=\"kb-adv-heading8372_d1ac7b-f3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_d1ac7b-f3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_d1ac7b-f3[data-kb-block=\"kb-adv-heading8372_d1ac7b-f3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading8372_d1ac7b-f3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_d1ac7b-f3\">Meals<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_bbb0a4-59, .wp-block-kadence-advancedheading.kt-adv-heading8372_bbb0a4-59[data-kb-block=\"kb-adv-heading8372_bbb0a4-59\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_bbb0a4-59 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_bbb0a4-59[data-kb-block=\"kb-adv-heading8372_bbb0a4-59\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_bbb0a4-59 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_bbb0a4-59[data-kb-block=\"kb-adv-heading8372_bbb0a4-59\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_bbb0a4-59 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_bbb0a4-59\">Meals are prepared by the experienced catering company Raf-Catering from Krak\u00f3w. We offer 5 meals a day. We provide varied diets (vegetarian, dairy-free, gluten-free, etc.) as well as individually tailored diets. The current menu is sent weekly to Parents.   <br\/><\/p>\n\n\n<style>.kadence-column8372_28eab4-47 > .kt-inside-inner-col{display:flex;}.kadence-column8372_28eab4-47 > .kt-inside-inner-col,.kadence-column8372_28eab4-47 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_28eab4-47 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_28eab4-47 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;justify-content:flex-start;}.kadence-column8372_28eab4-47 > .kt-inside-inner-col > *, .kadence-column8372_28eab4-47 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_28eab4-47 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_28eab4-47 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column8372_28eab4-47{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_28eab4-47{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_28eab4-47 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_28eab4-47 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_28eab4-47{position:relative;}.kadence-column8372_28eab4-47, .kt-inside-inner-col > .kadence-column8372_28eab4-47:not(.specificity){margin-top:10px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_28eab4-47{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_28eab4-47{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_28eab4-47 > .kt-inside-inner-col{align-items:flex-start;}}@media all and (max-width: 1024px){.kadence-column8372_28eab4-47 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;justify-content:flex-start;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column8372_28eab4-47 > .kt-inside-inner-col > *, .kadence-column8372_28eab4-47 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_28eab4-47 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_28eab4-47 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_28eab4-47{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_28eab4-47{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_28eab4-47 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_28eab4-47 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;justify-content:flex-start;}.kadence-column8372_28eab4-47 > .kt-inside-inner-col > *, .kadence-column8372_28eab4-47 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_28eab4-47 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_28eab4-47 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_28eab4-47 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns8372_d9009b-5a{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns8372_d9009b-5a .kt-button{font-weight:normal;font-style:normal;}.kt-btns8372_d9009b-5a .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns8372_d9009b-5a .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns8372_d9009b-5a .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_d9009b-5a .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns8372_d9009b-5a .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns8372_d9009b-5a .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_d9009b-5a .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8372_d9009b-5a\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn8372_41aa6a-46.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn8372_41aa6a-46.kb-button{padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn8372_41aa6a-46.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_41aa6a-46.kb-button:focus{color:var(--global-palette9, #ffffff);border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8372_41aa6a-46.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_41aa6a-46.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8372_41aa6a-46.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_41aa6a-46.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn8372_41aa6a-46 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"#zapisz\"><span class=\"kt-btn-inner-text\">Enroll your child<\/span><\/a><\/div>\n\n\n<style>.kadence-column8372_31bcc8-2d > .kt-inside-inner-col{display:flex;}.kadence-column8372_31bcc8-2d > .kt-inside-inner-col,.kadence-column8372_31bcc8-2d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_31bcc8-2d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_31bcc8-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_31bcc8-2d > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_31bcc8-2d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_31bcc8-2d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_31bcc8-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_31bcc8-2d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_31bcc8-2d{z-index:2;position:relative;}.kadence-column8372_31bcc8-2d, .kt-inside-inner-col > .kadence-column8372_31bcc8-2d:not(.specificity){margin-left:-71px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_31bcc8-2d{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_31bcc8-2d{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_31bcc8-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_31bcc8-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_31bcc8-2d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_31bcc8-2d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_31bcc8-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_31bcc8-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_31bcc8-2d btn-icon\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons8372_c0ec39-84 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons8372_c0ec39-84{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons8372_c0ec39-84 alignnone\"><style>.kt-svg-item-8372_cf861b-cd .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-8372_cf861b-cd .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:6px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-8372_cf861b-cd\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_c8161a-08 > .kt-inside-inner-col,.kadence-column8372_c8161a-08 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_c8161a-08 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_c8161a-08 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_c8161a-08 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_c8161a-08 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_c8161a-08{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_c8161a-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_c8161a-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_c8161a-08 container-image\"><div class=\"kt-inside-inner-col\"><style>.kb-image8372_b749f7-59 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image8372_b749f7-59 img.kb-img, .kb-image8372_b749f7-59 .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_b749f7-59\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/obiadki.jpg\" alt=\"\" class=\"kb-img wp-image-8423\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/obiadki.jpg 800w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/obiadki-300x200.jpg 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/obiadki-768x513.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-3 kt-inner-tab8372_aaa246-a9\"><div class=\"kt-tab-inner-content-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_cfd995-d4, .wp-block-kadence-advancedheading.kt-adv-heading8372_cfd995-d4[data-kb-block=\"kb-adv-heading8372_cfd995-d4\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_cfd995-d4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_cfd995-d4[data-kb-block=\"kb-adv-heading8372_cfd995-d4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_cfd995-d4 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_cfd995-d4[data-kb-block=\"kb-adv-heading8372_cfd995-d4\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading8372_cfd995-d4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_cfd995-d4\">Additional activities included in the tuition fee<\/h3>\n\n\n<style>.kt-tabs-id8372_d71c01-1e > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;padding-top:40px;padding-right:40px;padding-bottom:40px;padding-left:40px;min-height:400px;background:var(--global-palette9, #ffffff);}.wp-block-kadence-tabs .kt-tabs-id8372_d71c01-1e > .kt-tabs-title-list li{margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id8372_d71c01-1e > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id8372_d71c01-1e > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{line-height:1.4em;font-weight:regular;font-style:normal;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;padding-top:21px;padding-right:8px;padding-bottom:21px;padding-left:20px;border-color:var(--global-palette9, #ffffff);color:rgba(0,0,0,0.7);background:rgba(255,255,255,0);}.wp-block-kadence-tabs .kt-tabs-id8372_d71c01-1e > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id8372_d71c01-1e > .kt-tabs-title-list li .kt-tab-title:hover, .wp-block-kadence-tabs .kt-tabs-id8372_d71c01-1e > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title:hover{border-color:var(--global-palette8, #F7FAFC);color:#b78ef0;background:rgba(183,142,240,0.13);}.wp-block-kadence-tabs .kt-tabs-id8372_d71c01-1e > .kt-tabs-title-list li.kt-tab-title-active .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id8372_d71c01-1e > .kt-tabs-content-wrap > .kt-tabs-accordion-title.kt-tab-title-active .kt-tab-title{border-color:var(--global-palette7, #eeeeee);color:var(--global-palette3, #1A202C);background:var(--global-palette9, #ffffff);}@media all and (min-width: 1025px){.wp-block-kadence-tabs .kt-tabs-id8372_d71c01-1e{display:flex;}.wp-block-kadence-tabs .kt-tabs-id8372_d71c01-1e > .kt-tabs-title-list{float:none;width:30%;}.wp-block-kadence-tabs .kt-tabs-id8372_d71c01-1e > .kt-tabs-content-wrap{float:none;width:auto;-webkit-flex:1;flex:1;}}@media all and (max-width: 1024px){.kt-tabs-id8372_d71c01-1e > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (min-width: 768px) and (max-width: 1024px){.wp-block-kadence-tabs .kt-tabs-id8372_d71c01-1e{display:flex;}.wp-block-kadence-tabs .kt-tabs-id8372_d71c01-1e > .kt-tabs-title-list{float:none;width:30%;}.wp-block-kadence-tabs .kt-tabs-id8372_d71c01-1e > .kt-tabs-content-wrap{float:none;width:auto;-webkit-flex:1;flex:1;}}@media all and (max-width: 767px){.kt-tabs-id8372_d71c01-1e > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-tabs alignnone\"><div class=\"kt-tabs-wrap kt-tabs-id8372_d71c01-1e kt-tabs-has-6-tabs kt-active-tab-1 kt-tabs-layout-vtabs kt-tabs-tablet-layout-inherit kt-tabs-mobile-layout-accordion kt-tab-alignment-left kt-create-accordion\"><ul class=\"kt-tabs-title-list\"><li id=\"tab-jzykangielskiijzykhiszpaski\" class=\"kt-title-item kt-title-item-1 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-active\"><a href=\"#tab-jzykangielskiijzykhiszpaski\" data-tab=\"1\" class=\"kt-tab-title kt-tab-title-1 \"><span class=\"kt-title-text\">English and Spanish language<\/span><\/a><\/li><li id=\"tab-zajciasportowe\" class=\"kt-title-item kt-title-item-2 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-zajciasportowe\" data-tab=\"2\" class=\"kt-tab-title kt-tab-title-2 \"><span class=\"kt-title-text\">Sports activities<\/span><\/a><\/li><li id=\"tab-zajciazlogopedpsychologiem\" class=\"kt-title-item kt-title-item-3 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-zajciazlogopedpsychologiem\" data-tab=\"3\" class=\"kt-tab-title kt-tab-title-3 \"><span class=\"kt-title-text\">Speech therapist \/ psychologist sessions<\/span><\/a><\/li><li id=\"tab-zajciamuzycznerytmika\" class=\"kt-title-item kt-title-item-4 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-zajciamuzycznerytmika\" data-tab=\"4\" class=\"kt-tab-title kt-tab-title-4 \"><span class=\"kt-title-text\">Music classes \u2013 Rhythmics<\/span><\/a><\/li><li id=\"tab-zajciaruchowezumba\" class=\"kt-title-item kt-title-item-5 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-zajciaruchowezumba\" data-tab=\"5\" class=\"kt-tab-title kt-tab-title-5 \"><span class=\"kt-title-text\">Movement classes \u2013 Zumba<\/span><\/a><\/li><li id=\"tab-inne\" class=\"kt-title-item kt-title-item-6 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-inne\" data-tab=\"6\" class=\"kt-tab-title kt-tab-title-6 \"><span class=\"kt-title-text\">Other<\/span><\/a><\/li><\/ul><div class=\"kt-tabs-content-wrap\">\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-1 kt-inner-tab8372_24a1f7-8c\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id8372_5af5d6-8e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_5af5d6-8e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_5af5d6-8e > .kt-row-column-wrap{column-gap:48px;row-gap:var(--global-kb-gap-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(42.7% - ((48px * 1 )\/2)))minmax(0, calc(57.3% - ((48px * 1 )\/2)));}.kb-row-layout-id8372_5af5d6-8e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_5af5d6-8e > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id8372_5af5d6-8e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_5af5d6-8e alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column8372_7b87d5-1d > .kt-inside-inner-col,.kadence-column8372_7b87d5-1d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_7b87d5-1d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_7b87d5-1d > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_7b87d5-1d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_7b87d5-1d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_7b87d5-1d{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_7b87d5-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_7b87d5-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_7b87d5-1d container-image\"><div class=\"kt-inside-inner-col\"><style>.kb-image8372_666233-51 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image8372_666233-51 img.kb-img, .kb-image8372_666233-51 .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_666233-51 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"870\" height=\"580\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_640685760.webp\" alt=\"\" class=\"kb-img wp-image-8071\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_640685760.webp 870w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_640685760-300x200.webp 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_640685760-768x512.webp 768w\" sizes=\"auto, (max-width: 870px) 100vw, 870px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_1dede8-e6 > .kt-inside-inner-col,.kadence-column8372_1dede8-e6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_1dede8-e6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_1dede8-e6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_1dede8-e6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_1dede8-e6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_1dede8-e6{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_1dede8-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_1dede8-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_1dede8-e6\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_7a1b79-e2 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box8372_7a1b79-e2 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:20px;margin-left:0px;}.kt-info-box8372_7a1b79-e2 .kt-blocks-info-box-media{color:var(--global-palette2, #2B6CB0);background:#ffcfc3;border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;}.kt-info-box8372_7a1b79-e2 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box8372_7a1b79-e2 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:1rem;}.kt-info-box8372_7a1b79-e2 .kt-infobox-textcontent h3.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box8372_7a1b79-e2 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box8372_7a1b79-e2 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box8372_7a1b79-e2 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box8372_7a1b79-e2 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box8372_7a1b79-e2\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\"><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">English and Spanish language<\/h3><p class=\"kt-blocks-info-box-text\">Language classes in both English and Spanish are conducted by qualified instructors from Kokosowa Wyspa. Certified teachers conduct engaging lessons that encourage children to cooperate and learn. In addition to scheduled classes, our staff teach English songs and phrases throughout the day in a playful way.  <\/p><\/div><\/span><\/div>\n\n\n<style>.kadence-column8372_240ff6-10 > .kt-inside-inner-col{display:flex;}.kadence-column8372_240ff6-10 > .kt-inside-inner-col,.kadence-column8372_240ff6-10 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_240ff6-10 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_240ff6-10 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}.kadence-column8372_240ff6-10 > .kt-inside-inner-col > *, .kadence-column8372_240ff6-10 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_240ff6-10 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_240ff6-10 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column8372_240ff6-10{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_240ff6-10{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_240ff6-10 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_240ff6-10 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_240ff6-10{position:relative;}.kadence-column8372_240ff6-10, .kt-inside-inner-col > .kadence-column8372_240ff6-10:not(.specificity){margin-top:10px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_240ff6-10{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_240ff6-10{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_240ff6-10 > .kt-inside-inner-col{align-items:flex-start;}}@media all and (max-width: 1024px){.kadence-column8372_240ff6-10 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column8372_240ff6-10 > .kt-inside-inner-col > *, .kadence-column8372_240ff6-10 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_240ff6-10 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_240ff6-10 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_240ff6-10{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_240ff6-10{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_240ff6-10 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_240ff6-10 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column8372_240ff6-10 > .kt-inside-inner-col > *, .kadence-column8372_240ff6-10 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_240ff6-10 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_240ff6-10 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_240ff6-10 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns8372_d55031-3a{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns8372_d55031-3a .kt-button{font-weight:normal;font-style:normal;}.kt-btns8372_d55031-3a .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns8372_d55031-3a .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns8372_d55031-3a .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_d55031-3a .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns8372_d55031-3a .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns8372_d55031-3a .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_d55031-3a .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8372_d55031-3a\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn8372_1760da-de.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn8372_1760da-de.kb-button{background:#b78ef0;padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn8372_1760da-de.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_1760da-de.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8372_1760da-de.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_1760da-de.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8372_1760da-de.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_1760da-de.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn8372_1760da-de kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Enroll your child <\/span><\/span><\/div>\n\n\n<style>.kadence-column8372_5fd9e3-6c > .kt-inside-inner-col{display:flex;}.kadence-column8372_5fd9e3-6c > .kt-inside-inner-col,.kadence-column8372_5fd9e3-6c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_5fd9e3-6c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_5fd9e3-6c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_5fd9e3-6c > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_5fd9e3-6c{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_5fd9e3-6c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_5fd9e3-6c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_5fd9e3-6c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_5fd9e3-6c{z-index:2;position:relative;}.kadence-column8372_5fd9e3-6c, .kt-inside-inner-col > .kadence-column8372_5fd9e3-6c:not(.specificity){margin-left:-71px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_5fd9e3-6c{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_5fd9e3-6c{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_5fd9e3-6c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_5fd9e3-6c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_5fd9e3-6c{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_5fd9e3-6c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_5fd9e3-6c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_5fd9e3-6c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_5fd9e3-6c\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons8372_3a4a2e-77 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons8372_3a4a2e-77{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons8372_3a4a2e-77 alignnone\"><style>.kt-svg-item-8372_3c881a-69 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-8372_3c881a-69 .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:6px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-8372_3c881a-69\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-2 kt-inner-tab8372_0b4bf9-82\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id8372_3f7a2a-8f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_3f7a2a-8f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_3f7a2a-8f > .kt-row-column-wrap{column-gap:48px;row-gap:var(--global-kb-gap-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(42.7% - ((48px * 1 )\/2)))minmax(0, calc(57.3% - ((48px * 1 )\/2)));}.kb-row-layout-id8372_3f7a2a-8f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_3f7a2a-8f > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id8372_3f7a2a-8f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_3f7a2a-8f alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column8372_a6bb31-c4 > .kt-inside-inner-col,.kadence-column8372_a6bb31-c4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_a6bb31-c4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_a6bb31-c4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_a6bb31-c4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_a6bb31-c4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_a6bb31-c4{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_a6bb31-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_a6bb31-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_a6bb31-c4 container-image\"><div class=\"kt-inside-inner-col\"><style>.kb-image8372_dfb79c-1b .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image8372_dfb79c-1b img.kb-img, .kb-image8372_dfb79c-1b .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_dfb79c-1b size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"870\" height=\"580\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_442708625.webp\" alt=\"\" class=\"kb-img wp-image-8068\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_442708625.webp 870w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_442708625-300x200.webp 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_442708625-768x512.webp 768w\" sizes=\"auto, (max-width: 870px) 100vw, 870px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_c68275-63 > .kt-inside-inner-col,.kadence-column8372_c68275-63 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_c68275-63 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_c68275-63 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_c68275-63 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_c68275-63 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_c68275-63{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_c68275-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_c68275-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_c68275-63\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_943ef1-68 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box8372_943ef1-68 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:20px;margin-left:0px;}.kt-info-box8372_943ef1-68 .kt-blocks-info-box-media{color:var(--global-palette2, #2B6CB0);background:#ffcfc3;border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;}.kt-info-box8372_943ef1-68 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box8372_943ef1-68 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:1rem;}.kt-info-box8372_943ef1-68 .kt-infobox-textcontent h3.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box8372_943ef1-68 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box8372_943ef1-68 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box8372_943ef1-68 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box8372_943ef1-68 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box8372_943ef1-68\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\"><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Sports activities<\/h3><p class=\"kt-blocks-info-box-text\">In the preschool and the older nursery group, sports classes with a coach take place, giving children the opportunity to release energy safely and improve their coordination and motor skills.<\/p><\/div><\/span><\/div>\n\n\n<style>.kadence-column8372_ec5690-5b > .kt-inside-inner-col{display:flex;}.kadence-column8372_ec5690-5b > .kt-inside-inner-col,.kadence-column8372_ec5690-5b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_ec5690-5b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_ec5690-5b > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}.kadence-column8372_ec5690-5b > .kt-inside-inner-col > *, .kadence-column8372_ec5690-5b > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_ec5690-5b > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_ec5690-5b > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column8372_ec5690-5b{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_ec5690-5b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_ec5690-5b > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_ec5690-5b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_ec5690-5b{position:relative;}.kadence-column8372_ec5690-5b, .kt-inside-inner-col > .kadence-column8372_ec5690-5b:not(.specificity){margin-top:10px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_ec5690-5b{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_ec5690-5b{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_ec5690-5b > .kt-inside-inner-col{align-items:flex-start;}}@media all and (max-width: 1024px){.kadence-column8372_ec5690-5b > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column8372_ec5690-5b > .kt-inside-inner-col > *, .kadence-column8372_ec5690-5b > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_ec5690-5b > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_ec5690-5b > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_ec5690-5b{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_ec5690-5b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_ec5690-5b > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_ec5690-5b > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column8372_ec5690-5b > .kt-inside-inner-col > *, .kadence-column8372_ec5690-5b > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_ec5690-5b > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_ec5690-5b > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_ec5690-5b kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns8372_ce8ac8-4d{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns8372_ce8ac8-4d .kt-button{font-weight:normal;font-style:normal;}.kt-btns8372_ce8ac8-4d .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns8372_ce8ac8-4d .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns8372_ce8ac8-4d .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_ce8ac8-4d .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns8372_ce8ac8-4d .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns8372_ce8ac8-4d .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_ce8ac8-4d .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8372_ce8ac8-4d\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn8372_c16ac2-43.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn8372_c16ac2-43.kb-button{background:#b78ef0;padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn8372_c16ac2-43.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_c16ac2-43.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8372_c16ac2-43.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_c16ac2-43.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8372_c16ac2-43.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_c16ac2-43.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn8372_c16ac2-43 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Enroll your child <\/span><\/span><\/div>\n\n\n<style>.kadence-column8372_216b9b-d4 > .kt-inside-inner-col{display:flex;}.kadence-column8372_216b9b-d4 > .kt-inside-inner-col,.kadence-column8372_216b9b-d4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_216b9b-d4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_216b9b-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_216b9b-d4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_216b9b-d4{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_216b9b-d4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_216b9b-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_216b9b-d4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_216b9b-d4{z-index:2;position:relative;}.kadence-column8372_216b9b-d4, .kt-inside-inner-col > .kadence-column8372_216b9b-d4:not(.specificity){margin-left:-71px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_216b9b-d4{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_216b9b-d4{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_216b9b-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_216b9b-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_216b9b-d4{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_216b9b-d4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_216b9b-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_216b9b-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_216b9b-d4\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons8372_78aba8-e5 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons8372_78aba8-e5{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons8372_78aba8-e5 alignnone\"><style>.kt-svg-item-8372_812e10-3e .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-8372_812e10-3e .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:6px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-8372_812e10-3e\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-3 kt-inner-tab8372_7d9320-08\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id8372_998ff6-cf > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_998ff6-cf > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_998ff6-cf > .kt-row-column-wrap{column-gap:48px;row-gap:var(--global-kb-gap-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(42.7% - ((48px * 1 )\/2)))minmax(0, calc(57.3% - ((48px * 1 )\/2)));}.kb-row-layout-id8372_998ff6-cf > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_998ff6-cf > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id8372_998ff6-cf > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_998ff6-cf alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column8372_c78b1e-68 > .kt-inside-inner-col,.kadence-column8372_c78b1e-68 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_c78b1e-68 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_c78b1e-68 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_c78b1e-68 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_c78b1e-68 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_c78b1e-68{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_c78b1e-68 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_c78b1e-68 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_c78b1e-68 container-image\"><div class=\"kt-inside-inner-col\"><style>.kb-image8372_8370d2-a9 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image8372_8370d2-a9 img.kb-img, .kb-image8372_8370d2-a9 .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_8370d2-a9 size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"732\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_181768914-1024x732.webp\" alt=\"\" class=\"kb-img wp-image-7947\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_181768914-1024x732.webp 1024w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_181768914-300x214.webp 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_181768914-768x549.webp 768w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_181768914-1536x1098.webp 1536w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_181768914.webp 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_b26928-81 > .kt-inside-inner-col,.kadence-column8372_b26928-81 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_b26928-81 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_b26928-81 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_b26928-81 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_b26928-81 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_b26928-81{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_b26928-81 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_b26928-81 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_b26928-81\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_3d0683-69 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box8372_3d0683-69 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-right:20px;margin-bottom:20px;margin-left:0px;}.kt-info-box8372_3d0683-69 .kt-blocks-info-box-media{color:var(--global-palette2, #2B6CB0);background:#ffcfc3;border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;}.kt-info-box8372_3d0683-69 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box8372_3d0683-69 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:1rem;}.kt-info-box8372_3d0683-69 .kt-infobox-textcontent h3.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box8372_3d0683-69 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box8372_3d0683-69 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box8372_3d0683-69 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box8372_3d0683-69 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box8372_3d0683-69\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\"><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Speech therapist \/ psychologist sessions<\/h3><p class=\"kt-blocks-info-box-text\">We also provide group speech therapy sessions supporting speech development and communication skills, as well as psychologist-led sessions supporting social skills. Individual meetings with specialists are also available.<br\/>Each specialist ensures the most accessible form of learning in the field of ethics and related areas. <\/p><\/div><\/span><\/div>\n\n\n<style>.kadence-column8372_27d83f-69 > .kt-inside-inner-col{display:flex;}.kadence-column8372_27d83f-69 > .kt-inside-inner-col,.kadence-column8372_27d83f-69 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_27d83f-69 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_27d83f-69 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}.kadence-column8372_27d83f-69 > .kt-inside-inner-col > *, .kadence-column8372_27d83f-69 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_27d83f-69 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_27d83f-69 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column8372_27d83f-69{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_27d83f-69{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_27d83f-69 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_27d83f-69 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_27d83f-69{position:relative;}.kadence-column8372_27d83f-69, .kt-inside-inner-col > .kadence-column8372_27d83f-69:not(.specificity){margin-top:10px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_27d83f-69{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_27d83f-69{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_27d83f-69 > .kt-inside-inner-col{align-items:flex-start;}}@media all and (max-width: 1024px){.kadence-column8372_27d83f-69 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column8372_27d83f-69 > .kt-inside-inner-col > *, .kadence-column8372_27d83f-69 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_27d83f-69 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_27d83f-69 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_27d83f-69{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_27d83f-69{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_27d83f-69 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_27d83f-69 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column8372_27d83f-69 > .kt-inside-inner-col > *, .kadence-column8372_27d83f-69 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_27d83f-69 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_27d83f-69 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_27d83f-69 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns8372_208266-e0{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns8372_208266-e0 .kt-button{font-weight:normal;font-style:normal;}.kt-btns8372_208266-e0 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns8372_208266-e0 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns8372_208266-e0 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_208266-e0 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns8372_208266-e0 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns8372_208266-e0 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_208266-e0 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8372_208266-e0\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn8372_a1d52a-ad.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn8372_a1d52a-ad.kb-button{background:#b78ef0;padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn8372_a1d52a-ad.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_a1d52a-ad.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8372_a1d52a-ad.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_a1d52a-ad.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8372_a1d52a-ad.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_a1d52a-ad.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn8372_a1d52a-ad kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Enroll your child <\/span><\/span><\/div>\n\n\n<style>.kadence-column8372_9a2549-de > .kt-inside-inner-col{display:flex;}.kadence-column8372_9a2549-de > .kt-inside-inner-col,.kadence-column8372_9a2549-de > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_9a2549-de > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_9a2549-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_9a2549-de > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_9a2549-de{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_9a2549-de{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_9a2549-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_9a2549-de > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_9a2549-de{z-index:2;position:relative;}.kadence-column8372_9a2549-de, .kt-inside-inner-col > .kadence-column8372_9a2549-de:not(.specificity){margin-left:-71px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_9a2549-de{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_9a2549-de{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_9a2549-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_9a2549-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_9a2549-de{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_9a2549-de{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_9a2549-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_9a2549-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_9a2549-de\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons8372_3b519a-a7 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons8372_3b519a-a7{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons8372_3b519a-a7 alignnone\"><style>.kt-svg-item-8372_c4682b-a0 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-8372_c4682b-a0 .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:6px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-8372_c4682b-a0\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-4 kt-inner-tab8372_efd0df-0d\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id8372_34029e-82 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_34029e-82 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_34029e-82 > .kt-row-column-wrap{column-gap:48px;row-gap:var(--global-kb-gap-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(42.7% - ((48px * 1 )\/2)))minmax(0, calc(57.3% - ((48px * 1 )\/2)));}.kb-row-layout-id8372_34029e-82 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_34029e-82 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id8372_34029e-82 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_34029e-82 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column8372_fa15e2-0b > .kt-inside-inner-col,.kadence-column8372_fa15e2-0b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_fa15e2-0b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_fa15e2-0b > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_fa15e2-0b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_fa15e2-0b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_fa15e2-0b{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_fa15e2-0b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_fa15e2-0b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_fa15e2-0b container-image\"><div class=\"kt-inside-inner-col\"><style>.kb-image8372_8cd4d8-a1 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image8372_8cd4d8-a1 img.kb-img, .kb-image8372_8cd4d8-a1 .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_8cd4d8-a1 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"870\" height=\"580\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_246553435.webp\" alt=\"\" class=\"kb-img wp-image-8064\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_246553435.webp 870w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_246553435-300x200.webp 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_246553435-768x512.webp 768w\" sizes=\"auto, (max-width: 870px) 100vw, 870px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_4acda3-62 > .kt-inside-inner-col,.kadence-column8372_4acda3-62 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_4acda3-62 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_4acda3-62 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_4acda3-62 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_4acda3-62 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_4acda3-62{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_4acda3-62 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_4acda3-62 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_4acda3-62\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_1b7e8b-5f .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box8372_1b7e8b-5f .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:20px;margin-left:0px;}.kt-info-box8372_1b7e8b-5f .kt-blocks-info-box-media{color:var(--global-palette2, #2B6CB0);background:#ffcfc3;border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;}.kt-info-box8372_1b7e8b-5f .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box8372_1b7e8b-5f .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:1rem;}.kt-info-box8372_1b7e8b-5f .kt-infobox-textcontent h3.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box8372_1b7e8b-5f .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box8372_1b7e8b-5f .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box8372_1b7e8b-5f .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box8372_1b7e8b-5f .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box8372_1b7e8b-5f\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\"><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Music classes \u2013 Rhythmics<\/h3><p class=\"kt-blocks-info-box-text\">These classes stimulate musical development and enrich children\u2019s hearing. They help develop coordination between singing, breathing and movement. During classes, children have the opportunity to listen to and express themselves through live music.  <\/p><\/div><\/span><\/div>\n\n\n<style>.kadence-column8372_b3d45f-06 > .kt-inside-inner-col{display:flex;}.kadence-column8372_b3d45f-06 > .kt-inside-inner-col,.kadence-column8372_b3d45f-06 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_b3d45f-06 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_b3d45f-06 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}.kadence-column8372_b3d45f-06 > .kt-inside-inner-col > *, .kadence-column8372_b3d45f-06 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_b3d45f-06 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_b3d45f-06 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column8372_b3d45f-06{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b3d45f-06{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b3d45f-06 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_b3d45f-06 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_b3d45f-06{position:relative;}.kadence-column8372_b3d45f-06, .kt-inside-inner-col > .kadence-column8372_b3d45f-06:not(.specificity){margin-top:10px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_b3d45f-06{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b3d45f-06{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b3d45f-06 > .kt-inside-inner-col{align-items:flex-start;}}@media all and (max-width: 1024px){.kadence-column8372_b3d45f-06 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column8372_b3d45f-06 > .kt-inside-inner-col > *, .kadence-column8372_b3d45f-06 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_b3d45f-06 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_b3d45f-06 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_b3d45f-06{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b3d45f-06{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_b3d45f-06 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_b3d45f-06 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column8372_b3d45f-06 > .kt-inside-inner-col > *, .kadence-column8372_b3d45f-06 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_b3d45f-06 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_b3d45f-06 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_b3d45f-06 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns8372_0a2b09-7a{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns8372_0a2b09-7a .kt-button{font-weight:normal;font-style:normal;}.kt-btns8372_0a2b09-7a .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns8372_0a2b09-7a .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns8372_0a2b09-7a .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_0a2b09-7a .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns8372_0a2b09-7a .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns8372_0a2b09-7a .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_0a2b09-7a .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8372_0a2b09-7a\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn8372_65a07e-dc.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn8372_65a07e-dc.kb-button{background:#b78ef0;padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn8372_65a07e-dc.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_65a07e-dc.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8372_65a07e-dc.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_65a07e-dc.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8372_65a07e-dc.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_65a07e-dc.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn8372_65a07e-dc kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Enroll your child <\/span><\/span><\/div>\n\n\n<style>.kadence-column8372_eb55ef-97 > .kt-inside-inner-col{display:flex;}.kadence-column8372_eb55ef-97 > .kt-inside-inner-col,.kadence-column8372_eb55ef-97 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_eb55ef-97 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_eb55ef-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_eb55ef-97 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_eb55ef-97{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_eb55ef-97{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_eb55ef-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_eb55ef-97 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_eb55ef-97{z-index:2;position:relative;}.kadence-column8372_eb55ef-97, .kt-inside-inner-col > .kadence-column8372_eb55ef-97:not(.specificity){margin-left:-71px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_eb55ef-97{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_eb55ef-97{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_eb55ef-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_eb55ef-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_eb55ef-97{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_eb55ef-97{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_eb55ef-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_eb55ef-97 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_eb55ef-97\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons8372_a6e858-f4 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons8372_a6e858-f4{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons8372_a6e858-f4 alignnone\"><style>.kt-svg-item-8372_68b762-51 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-8372_68b762-51 .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:6px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-8372_68b762-51\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-5 kt-inner-tab8372_695316-36\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id8372_f5ed8b-8e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_f5ed8b-8e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_f5ed8b-8e > .kt-row-column-wrap{column-gap:48px;row-gap:var(--global-kb-gap-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(42.7% - ((48px * 1 )\/2)))minmax(0, calc(57.3% - ((48px * 1 )\/2)));}.kb-row-layout-id8372_f5ed8b-8e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_f5ed8b-8e > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id8372_f5ed8b-8e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_f5ed8b-8e alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column8372_a2d6b3-22 > .kt-inside-inner-col,.kadence-column8372_a2d6b3-22 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_a2d6b3-22 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_a2d6b3-22 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_a2d6b3-22 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_a2d6b3-22 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_a2d6b3-22{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_a2d6b3-22 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_a2d6b3-22 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_a2d6b3-22 container-image\"><div class=\"kt-inside-inner-col\"><style>.kb-image8372_6801b1-87 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image8372_6801b1-87 img.kb-img, .kb-image8372_6801b1-87 .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_6801b1-87 size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_179977341-1024x683.webp\" alt=\"\" class=\"kb-img wp-image-7946\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_179977341-1024x683.webp 1024w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_179977341-300x200.webp 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_179977341-768x512.webp 768w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_179977341-1536x1024.webp 1536w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_179977341.webp 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_50c65f-0f > .kt-inside-inner-col,.kadence-column8372_50c65f-0f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_50c65f-0f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_50c65f-0f > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_50c65f-0f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_50c65f-0f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_50c65f-0f{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_50c65f-0f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_50c65f-0f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_50c65f-0f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_88942d-fa .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box8372_88942d-fa .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:20px;margin-left:0px;}.kt-info-box8372_88942d-fa .kt-blocks-info-box-media{color:var(--global-palette2, #2B6CB0);background:#ffcfc3;border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;}.kt-info-box8372_88942d-fa .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box8372_88942d-fa .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:1rem;}.kt-info-box8372_88942d-fa .kt-infobox-textcontent h3.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box8372_88942d-fa .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box8372_88942d-fa .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box8372_88942d-fa .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box8372_88942d-fa .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box8372_88942d-fa\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\"><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Movement classes \u2013 Zumba<\/h3><p class=\"kt-blocks-info-box-text\">As a sports and language-oriented facility, we also offer dance and movement Zumba classes. These include various choreographies that develop coordination, self-confidence and openness among children. <\/p><\/div><\/span><\/div>\n\n\n<style>.kadence-column8372_916b7a-98 > .kt-inside-inner-col{display:flex;}.kadence-column8372_916b7a-98 > .kt-inside-inner-col,.kadence-column8372_916b7a-98 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_916b7a-98 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_916b7a-98 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}.kadence-column8372_916b7a-98 > .kt-inside-inner-col > *, .kadence-column8372_916b7a-98 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_916b7a-98 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_916b7a-98 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column8372_916b7a-98{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_916b7a-98{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_916b7a-98 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_916b7a-98 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_916b7a-98{position:relative;}.kadence-column8372_916b7a-98, .kt-inside-inner-col > .kadence-column8372_916b7a-98:not(.specificity){margin-top:10px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_916b7a-98{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_916b7a-98{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_916b7a-98 > .kt-inside-inner-col{align-items:flex-start;}}@media all and (max-width: 1024px){.kadence-column8372_916b7a-98 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column8372_916b7a-98 > .kt-inside-inner-col > *, .kadence-column8372_916b7a-98 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_916b7a-98 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_916b7a-98 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_916b7a-98{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_916b7a-98{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_916b7a-98 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_916b7a-98 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column8372_916b7a-98 > .kt-inside-inner-col > *, .kadence-column8372_916b7a-98 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_916b7a-98 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_916b7a-98 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_916b7a-98 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns8372_ccdb06-26{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns8372_ccdb06-26 .kt-button{font-weight:normal;font-style:normal;}.kt-btns8372_ccdb06-26 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns8372_ccdb06-26 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns8372_ccdb06-26 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_ccdb06-26 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns8372_ccdb06-26 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns8372_ccdb06-26 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_ccdb06-26 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8372_ccdb06-26\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn8372_dfe68b-4e.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn8372_dfe68b-4e.kb-button{background:#b78ef0;padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn8372_dfe68b-4e.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_dfe68b-4e.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8372_dfe68b-4e.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_dfe68b-4e.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8372_dfe68b-4e.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_dfe68b-4e.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn8372_dfe68b-4e kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Enroll your child <\/span><\/span><\/div>\n\n\n<style>.kadence-column8372_32fb49-08 > .kt-inside-inner-col{display:flex;}.kadence-column8372_32fb49-08 > .kt-inside-inner-col,.kadence-column8372_32fb49-08 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_32fb49-08 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_32fb49-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_32fb49-08 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_32fb49-08{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_32fb49-08{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_32fb49-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_32fb49-08 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_32fb49-08{z-index:2;position:relative;}.kadence-column8372_32fb49-08, .kt-inside-inner-col > .kadence-column8372_32fb49-08:not(.specificity){margin-left:-71px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_32fb49-08{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_32fb49-08{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_32fb49-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_32fb49-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_32fb49-08{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_32fb49-08{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_32fb49-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_32fb49-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_32fb49-08\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons8372_839658-9b .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons8372_839658-9b{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons8372_839658-9b alignnone\"><style>.kt-svg-item-8372_280b85-55 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-8372_280b85-55 .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:6px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-8372_280b85-55\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-6 kt-inner-tab8372_a4dcfe-78\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id8372_88352f-12 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_88352f-12 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_88352f-12 > .kt-row-column-wrap{column-gap:48px;row-gap:var(--global-kb-gap-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8372_88352f-12 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_88352f-12 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_88352f-12 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_88352f-12 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column8372_3e8f94-a1 > .kt-inside-inner-col,.kadence-column8372_3e8f94-a1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_3e8f94-a1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_3e8f94-a1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_3e8f94-a1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_3e8f94-a1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_3e8f94-a1{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_3e8f94-a1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_3e8f94-a1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_3e8f94-a1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_1e89a8-d2, .wp-block-kadence-advancedheading.kt-adv-heading8372_1e89a8-d2[data-kb-block=\"kb-adv-heading8372_1e89a8-d2\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_1e89a8-d2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_1e89a8-d2[data-kb-block=\"kb-adv-heading8372_1e89a8-d2\"] mark.kt-highlight{font-style:normal;color:var(--global-palette3, #1A202C);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_1e89a8-d2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_1e89a8-d2[data-kb-block=\"kb-adv-heading8372_1e89a8-d2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_1e89a8-d2 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_1e89a8-d2\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-theme-palette-3-color\">Both in the nursery and preschool we also organize:<\/mark><\/strong><\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_aec8e2-26:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_aec8e2-26 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_aec8e2-26 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_aec8e2-26 .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_aec8e2-26 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items8372_aec8e2-26 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items8372_aec8e2-26 kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop kt-mobile-svg-icon-list-columns-1\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-8372_6c3485-d1 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_6c3485-d1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">THEATRE PERFORMANCES FOR CHILDREN<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_78693b-ad .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_78693b-ad\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">PHOTO SESSIONS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_5c92fa-b5 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_5c92fa-b5\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TRIPS (outings apply to preschool)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_b4e5e5-6a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_b4e5e5-6a\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">BIRTHDAY PARTIES<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.kadence-column8372_8fcebd-3d > .kt-inside-inner-col{display:flex;}.kadence-column8372_8fcebd-3d > .kt-inside-inner-col,.kadence-column8372_8fcebd-3d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_8fcebd-3d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_8fcebd-3d > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}.kadence-column8372_8fcebd-3d > .kt-inside-inner-col > *, .kadence-column8372_8fcebd-3d > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_8fcebd-3d > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_8fcebd-3d > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column8372_8fcebd-3d{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_8fcebd-3d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_8fcebd-3d > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_8fcebd-3d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_8fcebd-3d{position:relative;}.kadence-column8372_8fcebd-3d, .kt-inside-inner-col > .kadence-column8372_8fcebd-3d:not(.specificity){margin-top:10px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_8fcebd-3d{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_8fcebd-3d{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_8fcebd-3d > .kt-inside-inner-col{align-items:flex-start;}}@media all and (max-width: 1024px){.kadence-column8372_8fcebd-3d > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column8372_8fcebd-3d > .kt-inside-inner-col > *, .kadence-column8372_8fcebd-3d > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_8fcebd-3d > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_8fcebd-3d > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_8fcebd-3d{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_8fcebd-3d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_8fcebd-3d > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_8fcebd-3d > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column8372_8fcebd-3d > .kt-inside-inner-col > *, .kadence-column8372_8fcebd-3d > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_8fcebd-3d > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_8fcebd-3d > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_8fcebd-3d kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns8372_3c2168-41{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns8372_3c2168-41 .kt-button{font-weight:normal;font-style:normal;}.kt-btns8372_3c2168-41 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns8372_3c2168-41 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns8372_3c2168-41 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_3c2168-41 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns8372_3c2168-41 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns8372_3c2168-41 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_3c2168-41 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8372_3c2168-41\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn8372_8d1f6c-08.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn8372_8d1f6c-08.kb-button{background:#b78ef0;padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn8372_8d1f6c-08.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_8d1f6c-08.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8372_8d1f6c-08.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_8d1f6c-08.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8372_8d1f6c-08.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_8d1f6c-08.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><span class=\"kb-button kt-button button kb-btn8372_8d1f6c-08 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Enroll your child <\/span><\/span><\/div>\n\n\n<style>.kadence-column8372_e8c226-63 > .kt-inside-inner-col{display:flex;}.kadence-column8372_e8c226-63 > .kt-inside-inner-col,.kadence-column8372_e8c226-63 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_e8c226-63 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_e8c226-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_e8c226-63 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_e8c226-63{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_e8c226-63{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_e8c226-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_e8c226-63 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_e8c226-63{z-index:2;position:relative;}.kadence-column8372_e8c226-63, .kt-inside-inner-col > .kadence-column8372_e8c226-63:not(.specificity){margin-left:-71px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_e8c226-63{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_e8c226-63{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_e8c226-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_e8c226-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_e8c226-63{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_e8c226-63{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_e8c226-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_e8c226-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_e8c226-63\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons8372_ffd7eb-95 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons8372_ffd7eb-95{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons8372_ffd7eb-95 alignnone\"><style>.kt-svg-item-8372_68f608-c8 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-8372_68f608-c8 .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:6px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-8372_68f608-c8\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_31b402-de, .wp-block-kadence-advancedheading.kt-adv-heading8372_31b402-de[data-kb-block=\"kb-adv-heading8372_31b402-de\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_31b402-de mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_31b402-de[data-kb-block=\"kb-adv-heading8372_31b402-de\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_31b402-de img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_31b402-de[data-kb-block=\"kb-adv-heading8372_31b402-de\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading8372_31b402-de wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_31b402-de\">Additional activities (extra paid \u2013 optional)<\/h3>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_ceafae-93:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_ceafae-93 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_ceafae-93 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_ceafae-93 .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_ceafae-93 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items8372_ceafae-93 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items8372_ceafae-93 kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop kt-mobile-svg-icon-list-columns-1\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-8372_4ff0d9-92 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_4ff0d9-92\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Judo (for preschool groups)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_3f22db-c3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_3f22db-c3\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">sensory workshops,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_a03c24-f4 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_a03c24-f4\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">workshops developing emotional and social competences,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_4a752d-4f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_4a752d-4f\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">dog therapy and feline therapy (sessions involving a dog and a cat, where children learn responsibility and animal care).<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id8372_046e82-b8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_046e82-b8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_046e82-b8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8372_046e82-b8{background-image:url('https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/Frame-183-4.svg');background-size:auto;background-position:42% 49%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id8372_046e82-b8 > .kt-row-layout-overlay{opacity:1;background:linear-gradient(174deg,var(--global-palette9) 0%,rgba(255,255,255,0) 58%);}@media all and (max-width: 1024px){.kb-row-layout-id8372_046e82-b8 > .kt-row-column-wrap{padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_046e82-b8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_046e82-b8 alignnone kt-row-has-bg wp-block-kadence-rowlayout\" id=\"kadra\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column8372_a60073-e2 > .kt-inside-inner-col,.kadence-column8372_a60073-e2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_a60073-e2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_a60073-e2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_a60073-e2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_a60073-e2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_a60073-e2{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_a60073-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_a60073-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_a60073-e2\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id8372_8037b8-e2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_8037b8-e2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_8037b8-e2 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8372_8037b8-e2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_8037b8-e2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_8037b8-e2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_8037b8-e2 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column8372_43a641-59 > .kt-inside-inner-col{display:flex;}.kadence-column8372_43a641-59 > .kt-inside-inner-col,.kadence-column8372_43a641-59 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_43a641-59 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_43a641-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_43a641-59 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_43a641-59{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_43a641-59{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_43a641-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_43a641-59 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_43a641-59{z-index:5;position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_43a641-59{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_43a641-59{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_43a641-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_43a641-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_43a641-59{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_43a641-59{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_43a641-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_43a641-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}.kadence-column8372_43a641-59 button.splide__arrow.splide__arrow--prev.slick-prev {\r    background: white;\r    color: black;\r    opacity: 100 !important;\r    width: 47px;\r    border-radius: 101px;\r}\r.kadence-column8372_43a641-59 button.splide__arrow.splide__arrow--next.slick-next {\r    background: white;\r    color: black;\r    opacity: 100 !important;\r    width: 47px;\r    border-radius: 101px;\r}\r.kadence-column8372_43a641-59 img {\r  border-radius:30px;\r}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_43a641-59\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_0d1c04-4c, .wp-block-kadence-advancedheading.kt-adv-heading8372_0d1c04-4c[data-kb-block=\"kb-adv-heading8372_0d1c04-4c\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:center;font-size:49px;line-height:1.3;font-weight:700;font-style:normal;font-family:'Plus Jakarta Sans';}.wp-block-kadence-advancedheading.kt-adv-heading8372_0d1c04-4c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_0d1c04-4c[data-kb-block=\"kb-adv-heading8372_0d1c04-4c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_0d1c04-4c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_0d1c04-4c[data-kb-block=\"kb-adv-heading8372_0d1c04-4c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8372_0d1c04-4c, .wp-block-kadence-advancedheading.kt-adv-heading8372_0d1c04-4c[data-kb-block=\"kb-adv-heading8372_0d1c04-4c\"]{font-size:49px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8372_0d1c04-4c, .wp-block-kadence-advancedheading.kt-adv-heading8372_0d1c04-4c[data-kb-block=\"kb-adv-heading8372_0d1c04-4c\"]{font-size:30px;}}<\/style>\n<h3 class=\"kt-adv-heading8372_0d1c04-4c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_0d1c04-4c\">Our team<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_a7e107-d8, .wp-block-kadence-advancedheading.kt-adv-heading8372_a7e107-d8[data-kb-block=\"kb-adv-heading8372_a7e107-d8\"]{margin-bottom:var(--global-kb-spacing-lg, 3rem);text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_a7e107-d8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_a7e107-d8[data-kb-block=\"kb-adv-heading8372_a7e107-d8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_a7e107-d8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_a7e107-d8[data-kb-block=\"kb-adv-heading8372_a7e107-d8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8372_a7e107-d8, .wp-block-kadence-advancedheading.kt-adv-heading8372_a7e107-d8[data-kb-block=\"kb-adv-heading8372_a7e107-d8\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left!important;}}<\/style>\n<p class=\"kt-adv-heading8372_a7e107-d8 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_a7e107-d8\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer non nibh mattis, sodales turpis vel, venenatis lectus. Etiam est metus, varius eget pulvinar finibus, congue nec lorem. Sed venenatis sit amet elit eu porttitor.   <\/p>\n\n\n<style>.kb-advanced-slider-8372_f796e3-3c{--kb-adv-slider-gap:76px;}.kb-advanced-slider-8372_f796e3-3c .kb-blocks-advanced-carousel .kb-blocks-advanced-slider-init:not(.is-initialized) .wp-block-kadence-slide{width:calc( 100%\/ 3 - ( ( var(--kb-adv-slider-gap) * 2 ) \/ 3 ) );}.kb-advanced-slider-8372_f796e3-3c .splide__arrow{margin-right:30px;margin-left:30px;}.kb-advanced-slider-8372_f796e3-3c .kb-slider-size-fixed .kb-advanced-slide-inner-wrap{min-height:84px;}.kb-advanced-slider-8372_f796e3-3c .kb-advanced-slide-inner-wrap{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-advanced-slider-8372_f796e3-3c .kb-slider-pause-button{color:#fff;background-color:rgba(0, 0, 0, 0.8);border:1px solid transparent;}@media all and (max-width: 1024px){.kb-advanced-slider-8372_f796e3-3c .kb-blocks-advanced-carousel .kb-blocks-advanced-slider-init:not(.is-initialized) .wp-block-kadence-slide{width:calc( 100%\/ 2 - ( ( var(--kb-adv-slider-gap) * 1 ) \/ 2 ) );}}@media all and (max-width: 767px){.kb-advanced-slider-8372_f796e3-3c .kb-blocks-advanced-carousel .kb-blocks-advanced-slider-init:not(.is-initialized) .wp-block-kadence-slide{width:100%;}}<\/style><div class=\"kb-advanced-slider kb-advanced-slider-8372_f796e3-3c wp-block-kadence-slider\"><div class=\"kb-advanced-slider-inner-contain kb-adv-slider-html-version-2\"><div class=\"kb-blocks-advanced-carousel kt-blocks-carousel kt-carousel-container-dotstyle-none\"><div class=\"kb-blocks-advanced-slider-init kb-slider-loading kb-blocks-slider kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-none kb-slider-size-fixed kb-slider-type-carousel kb-slider-ratio-12-5 kb-slider-group-arrow kb-slider-arrow-position-center kb-slider-tab-ratio-inherit kb-slider-mobile-ratio-inherit splide kb-splide  kb-slider-version-3\" aria-label=\"Slider content\" data-slider-center-mode=\"false\" data-slider-type=\"carousel\" data-loop-type=\"loop\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-fade=\"true\" data-slider-arrows=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-auto=\"false\"  data-dragging=\"true\" data-slider-speed=\"4230\" data-slider-gap=\"76\" data-slider-gap-tablet=\"76\" data-slider-gap-mobile=\"76\" data-slider-gap-unit=\"px\"><div class=\"splide__track\"><ul class=\"splide__list\">\n\n<li class=\"wp-block-kadence-slide kb-advanced-slide-item kb-slide-8372_59078b-b6\"><div class=\"kb-advanced-slide\"><div class=\"kb-advanced-slide-inner-wrap kb-slide-align-left kb-slide-valign-top\"><div class=\"kb-advanced-slide-inner\"><style>.kt-info-box8372_81e1b5-6c{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_81e1b5-6c{height:auto;align-self:stretch;}.kt-info-box8372_81e1b5-6c .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_81e1b5-6c .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box8372_81e1b5-6c .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box8372_81e1b5-6c.wp-block-kadence-infobox{max-width:100%;}.kt-info-box8372_81e1b5-6c .kadence-info-box-image-inner-intrisic-container{max-width:566px;}.kt-info-box8372_81e1b5-6c .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:566px;height:0px;max-width:100%;}.kt-info-box8372_81e1b5-6c .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box8372_81e1b5-6c .kt-info-svg-icon-flip, .kt-info-box8372_81e1b5-6c .kt-blocks-info-box-number{font-size:50px;}.kt-info-box8372_81e1b5-6c .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);background:transparent;border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box8372_81e1b5-6c .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box8372_81e1b5-6c .kt-infobox-textcontent h3.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box8372_81e1b5-6c .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box8372_81e1b5-6c .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box8372_81e1b5-6c .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box8372_81e1b5-6c .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box8372_81e1b5-6c\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-square\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3.png\" alt=\"\" width=\"566\" height=\"566\" class=\"kt-info-box-image wp-image-7457\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3.png 566w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3-300x300.png 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3-150x150.png 150w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Caregiver<\/h3><p class=\"kt-blocks-info-box-text\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer <\/p><\/div><\/span><\/div>\n<\/div><\/div><\/div><\/li>\n\n\n\n<li class=\"wp-block-kadence-slide kb-advanced-slide-item kb-slide-8372_dc55dd-56\"><div class=\"kb-advanced-slide\"><div class=\"kb-advanced-slide-inner-wrap kb-slide-align-left kb-slide-valign-top\"><div class=\"kb-advanced-slide-inner\"><style>.kt-info-box8372_8dba81-1a{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_8dba81-1a{height:auto;align-self:stretch;}.kt-info-box8372_8dba81-1a .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_8dba81-1a .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box8372_8dba81-1a .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box8372_8dba81-1a.wp-block-kadence-infobox{max-width:100%;}.kt-info-box8372_8dba81-1a .kadence-info-box-image-inner-intrisic-container{max-width:566px;}.kt-info-box8372_8dba81-1a .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:566px;height:0px;max-width:100%;}.kt-info-box8372_8dba81-1a .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box8372_8dba81-1a .kt-info-svg-icon-flip, .kt-info-box8372_8dba81-1a .kt-blocks-info-box-number{font-size:50px;}.kt-info-box8372_8dba81-1a .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);background:transparent;border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box8372_8dba81-1a .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box8372_8dba81-1a .kt-infobox-textcontent h3.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box8372_8dba81-1a .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box8372_8dba81-1a .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box8372_8dba81-1a .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box8372_8dba81-1a .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box8372_8dba81-1a\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-square\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3.png\" alt=\"\" width=\"566\" height=\"566\" class=\"kt-info-box-image wp-image-7457\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3.png 566w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3-300x300.png 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3-150x150.png 150w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Caregiver<\/h3><p class=\"kt-blocks-info-box-text\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer <\/p><\/div><\/span><\/div>\n<\/div><\/div><\/div><\/li>\n\n\n\n<li class=\"wp-block-kadence-slide kb-advanced-slide-item kb-slide-8372_257b67-67\"><div class=\"kb-advanced-slide\"><div class=\"kb-advanced-slide-inner-wrap kb-slide-align-left kb-slide-valign-top\"><div class=\"kb-advanced-slide-inner\"><style>.kt-info-box8372_d8360e-6a{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_d8360e-6a{height:auto;align-self:stretch;}.kt-info-box8372_d8360e-6a .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_d8360e-6a .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box8372_d8360e-6a .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box8372_d8360e-6a.wp-block-kadence-infobox{max-width:100%;}.kt-info-box8372_d8360e-6a .kadence-info-box-image-inner-intrisic-container{max-width:566px;}.kt-info-box8372_d8360e-6a .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:566px;height:0px;max-width:100%;}.kt-info-box8372_d8360e-6a .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box8372_d8360e-6a .kt-info-svg-icon-flip, .kt-info-box8372_d8360e-6a .kt-blocks-info-box-number{font-size:50px;}.kt-info-box8372_d8360e-6a .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);background:transparent;border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box8372_d8360e-6a .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box8372_d8360e-6a .kt-infobox-textcontent h3.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box8372_d8360e-6a .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box8372_d8360e-6a .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box8372_d8360e-6a .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box8372_d8360e-6a .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box8372_d8360e-6a\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-square\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3.png\" alt=\"\" width=\"566\" height=\"566\" class=\"kt-info-box-image wp-image-7457\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3.png 566w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3-300x300.png 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3-150x150.png 150w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Caregiver<\/h3><p class=\"kt-blocks-info-box-text\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer <\/p><\/div><\/span><\/div>\n<\/div><\/div><\/div><\/li>\n\n\n\n<li class=\"wp-block-kadence-slide kb-advanced-slide-item kb-slide-8372_cfa358-b7\"><div class=\"kb-advanced-slide\"><div class=\"kb-advanced-slide-inner-wrap kb-slide-align-left kb-slide-valign-top\"><div class=\"kb-advanced-slide-inner\"><style>.kt-info-box8372_9ec05e-1d{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_9ec05e-1d{height:auto;align-self:stretch;}.kt-info-box8372_9ec05e-1d .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_9ec05e-1d .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box8372_9ec05e-1d .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box8372_9ec05e-1d.wp-block-kadence-infobox{max-width:100%;}.kt-info-box8372_9ec05e-1d .kadence-info-box-image-inner-intrisic-container{max-width:566px;}.kt-info-box8372_9ec05e-1d .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:566px;height:0px;max-width:100%;}.kt-info-box8372_9ec05e-1d .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box8372_9ec05e-1d .kt-info-svg-icon-flip, .kt-info-box8372_9ec05e-1d .kt-blocks-info-box-number{font-size:50px;}.kt-info-box8372_9ec05e-1d .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);background:transparent;border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box8372_9ec05e-1d .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box8372_9ec05e-1d .kt-infobox-textcontent h3.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box8372_9ec05e-1d .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box8372_9ec05e-1d .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box8372_9ec05e-1d .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box8372_9ec05e-1d .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box8372_9ec05e-1d\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-square\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3.png\" alt=\"\" width=\"566\" height=\"566\" class=\"kt-info-box-image wp-image-7457\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3.png 566w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3-300x300.png 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/Frame-163-3-150x150.png 150w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Caregiver<\/h3><p class=\"kt-blocks-info-box-text\">Lorem ipsum dolor sit amet, consectetur adipiscing elit. Integer <\/p><\/div><\/span><\/div>\n<\/div><\/div><\/div><\/li>\n\n<\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id8372_88b4b6-5d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_88b4b6-5d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_88b4b6-5d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, calc(60% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(40% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id8372_88b4b6-5d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_88b4b6-5d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_88b4b6-5d > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_88b4b6-5d alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column8372_61a21e-6b > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kadence-column8372_61a21e-6b > .kt-inside-inner-col,.kadence-column8372_61a21e-6b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_61a21e-6b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_61a21e-6b > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_61a21e-6b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_61a21e-6b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_61a21e-6b{z-index:5;position:relative;}@media all and (max-width: 1024px){.kadence-column8372_61a21e-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_61a21e-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}.kadence-column8372_61a21e-6b button.splide__arrow.splide__arrow--prev.slick-prev {\r    background: white;\r    color: black;\r    opacity: 100 !important;\r    width: 47px;\r    border-radius: 101px;\r        box-shadow: 0px 4px 22.9px 0px rgba(0, 0, 0, 0.12);\r}\r.kadence-column8372_61a21e-6b button.splide__arrow.splide__arrow--next.slick-next {\r    background: white;\r    color: black;\r    opacity: 100 !important;\r    width: 47px;\r    border-radius: 101px;\r        box-shadow: 0px 4px 22.9px 0px rgba(0, 0, 0, 0.12);\r}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_61a21e-6b\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_6fdba7-11, .wp-block-kadence-advancedheading.kt-adv-heading8372_6fdba7-11[data-kb-block=\"kb-adv-heading8372_6fdba7-11\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left;font-size:49px;line-height:1.3;font-weight:700;font-style:normal;font-family:'Plus Jakarta Sans';}.wp-block-kadence-advancedheading.kt-adv-heading8372_6fdba7-11 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_6fdba7-11[data-kb-block=\"kb-adv-heading8372_6fdba7-11\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_6fdba7-11 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_6fdba7-11[data-kb-block=\"kb-adv-heading8372_6fdba7-11\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8372_6fdba7-11, .wp-block-kadence-advancedheading.kt-adv-heading8372_6fdba7-11[data-kb-block=\"kb-adv-heading8372_6fdba7-11\"]{font-size:49px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8372_6fdba7-11, .wp-block-kadence-advancedheading.kt-adv-heading8372_6fdba7-11[data-kb-block=\"kb-adv-heading8372_6fdba7-11\"]{font-size:30px;}}<\/style>\n<h3 class=\"kt-adv-heading8372_6fdba7-11 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_6fdba7-11\">Child Protection Standards<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_2e9322-f9, .wp-block-kadence-advancedheading.kt-adv-heading8372_2e9322-f9[data-kb-block=\"kb-adv-heading8372_2e9322-f9\"]{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_2e9322-f9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_2e9322-f9[data-kb-block=\"kb-adv-heading8372_2e9322-f9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_2e9322-f9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_2e9322-f9[data-kb-block=\"kb-adv-heading8372_2e9322-f9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_2e9322-f9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_2e9322-f9\">At our facility, we strictly follow child protection rules and standards.<br\/>These are a set of principles that help create a safe and friendly environment in nurseries, preschools and other institutions working for children. In a facility that follows child protection standards: <br\/><\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_0c001c-da:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_0c001c-da ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_0c001c-da ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_0c001c-da .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}.wp-block-kadence-iconlist.kt-svg-icon-list-items8372_0c001c-da ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items8372_0c001c-da ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items8372_0c001c-da kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop kt-mobile-svg-icon-list-columns-1\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-8372_0df0d9-dc .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_0df0d9-dc\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">individuals posing a threat to a child\u2019s safety cannot be employed,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_872673-62 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_872673-62\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">staff are able to recognize symptoms of child abuse,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_133137-b4 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_133137-b4\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">staff are able to intervene if there is suspicion that a child is a victim of violence \u2013 at the facility or in the family,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_928bd3-58 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_928bd3-58\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">children learn how to avoid risks in contacts with adults and peers \u2013 in real life and online,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_8faa95-6c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_8faa95-6c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">children have constant access to information about where to seek help in difficult life situations,<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-8372_afd15c-52 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-8372_afd15c-52\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">staff support parents in raising children without violence.<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_85f35a-2e, .wp-block-kadence-advancedheading.kt-adv-heading8372_85f35a-2e[data-kb-block=\"kb-adv-heading8372_85f35a-2e\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_85f35a-2e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_85f35a-2e[data-kb-block=\"kb-adv-heading8372_85f35a-2e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_85f35a-2e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_85f35a-2e[data-kb-block=\"kb-adv-heading8372_85f35a-2e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_85f35a-2e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_85f35a-2e\">All staff members are required to act in accordance with the law, within their competences, and comply with the principles set out in the document below.<br\/><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_ff1196-c7 > .kt-inside-inner-col,.kadence-column8372_ff1196-c7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_ff1196-c7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_ff1196-c7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_ff1196-c7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_ff1196-c7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_ff1196-c7{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_ff1196-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_ff1196-c7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_ff1196-c7 container-image\"><div class=\"kt-inside-inner-col\"><style>.kb-image8372_6f3865-0c .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image8372_6f3865-0c img.kb-img, .kb-image8372_6f3865-0c .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_6f3865-0c\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/1.jpg\" alt=\"\" class=\"kb-img wp-image-8428\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/1.jpg 800w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/1-300x188.jpg 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/1-768x480.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id8372_4d5803-a8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_4d5803-a8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_4d5803-a8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8372_4d5803-a8{background-image:url('https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/11\/Frame-183-1-1-1.svg');background-size:cover;background-position:52% 49%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id8372_4d5803-a8 > .kt-row-layout-overlay{opacity:1;background:linear-gradient(180deg,var(--global-palette9) 0%,rgb(255,255,255) 12%,rgba(255,255,255,0) 81%,var(--global-palette9) 100%);}@media all and (max-width: 1024px){.kb-row-layout-id8372_4d5803-a8 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_4d5803-a8 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8372_4d5803-a8 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:1;}.kb-row-layout-id8372_4d5803-a8 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:11;}.kb-row-layout-id8372_4d5803-a8 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:21;}.kb-row-layout-id8372_4d5803-a8 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:31;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_4d5803-a8 alignnone kt-row-has-bg wp-block-kadence-rowlayout\" id=\"cennik\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column8372_27bd66-86 > .kt-inside-inner-col,.kadence-column8372_27bd66-86 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_27bd66-86 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_27bd66-86 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_27bd66-86 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_27bd66-86 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_27bd66-86{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_27bd66-86 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_27bd66-86 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}.kadence-column8372_27bd66-86 .kt-tab-title-active{    box-shadow: 0px 4px 63.9px 0px rgba(0, 0, 0, 0.15);border-radius:20px !important;}.kadence-column8372_27bd66-86 .wp-block-kadence-tab.kt-tab-inner-content {        box-shadow: 0px 4px 63.9px 0px rgba(0, 0, 0, 0.15);}.kadence-column8372_27bd66-86 strong {    color: #B78EF0;}\/*ul.kt-tabs-title-list {*\/\/*    display: flex;*\/\/*    width: 2000px !important;*\/\/*}*\/\/*.kt-tabs-wrap {*\/\/*    overflow: auto;*\/\/*}*\/@media (max-width:767px) {.kadence-column8372_27bd66-86 .kt-tabs-title-list {  display: flex !important;  flex-wrap: nowrap !important;  overflow-x: auto !important;  overflow-y: visible !important; \/* WA\u017bNE *\/  padding: 20px 0 !important; \/* tylko g\u00f3ra\/d\u00f3\u0142 dla cienia *\/  scroll-snap-type: x mandatory;  -webkit-overflow-scrolling: touch;  padding-left:15px !important;    margin-left:-15px !important;  mask-image: linear-gradient(black, black); \/* hack: brak uci\u0119cia cienia *\/}.kadence-column8372_27bd66-86 .kt-tabs-title-list li {  flex: 0 0 auto;  margin-right: 20px;}.kadence-column8372_27bd66-86 .kt-tab-title-active{    box-shadow: 0px 4px 21.9px 0px rgba(0, 0, 0, 0.15);border-radius:20px !important;}.kadence-column8372_27bd66-86 .kt-tab-title-inactive .kt-tab-title{    background: #f1f1f1 !important;}.kadence-column8372_27bd66-86 .wp-block-kadence-tab.kt-tab-inner-content {        box-shadow: 0px 4px 21.9px 0px rgba(0, 0, 0, 0.15);      }.kadence-column8372_27bd66-86 .kt-tabs-title-list {  mask-image: linear-gradient(to right,    black 0,    black calc(100% - 40px),    transparent 100%  );  -webkit-mask-image: linear-gradient(to right,    black 0,    black calc(100% - 40px),    transparent 100%  );}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_27bd66-86\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_412446-3e, .wp-block-kadence-advancedheading.kt-adv-heading8372_412446-3e[data-kb-block=\"kb-adv-heading8372_412446-3e\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left;font-size:49px;line-height:1.3;font-weight:700;font-style:normal;font-family:'Plus Jakarta Sans';}.wp-block-kadence-advancedheading.kt-adv-heading8372_412446-3e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_412446-3e[data-kb-block=\"kb-adv-heading8372_412446-3e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_412446-3e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_412446-3e[data-kb-block=\"kb-adv-heading8372_412446-3e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8372_412446-3e, .wp-block-kadence-advancedheading.kt-adv-heading8372_412446-3e[data-kb-block=\"kb-adv-heading8372_412446-3e\"]{font-size:49px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8372_412446-3e, .wp-block-kadence-advancedheading.kt-adv-heading8372_412446-3e[data-kb-block=\"kb-adv-heading8372_412446-3e\"]{font-size:30px;}}<\/style>\n<h3 class=\"kt-adv-heading8372_412446-3e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_412446-3e\">Price list<\/h3>\n\n\n<style>.kt-tabs-id8372_abce6d-2b > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;padding-top:40px;padding-right:40px;padding-bottom:40px;padding-left:40px;min-height:122px;background:var(--global-palette9, #ffffff);}.wp-block-kadence-tabs .kt-tabs-id8372_abce6d-2b > .kt-tabs-title-list li{margin-top:0px;margin-right:10px;margin-bottom:30px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id8372_abce6d-2b > .kt-tabs-title-list li:last-child{margin-right:0px;}.wp-block-kadence-tabs .kt-tabs-id8372_abce6d-2b > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id8372_abce6d-2b > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{line-height:1.4em;font-weight:regular;font-style:normal;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;padding-top:21px;padding-right:20px;padding-bottom:21px;padding-left:20px;border-color:var(--global-palette9, #ffffff);color:rgba(0,0,0,0.7);background:rgba(255,255,255,0);}.wp-block-kadence-tabs .kt-tabs-id8372_abce6d-2b > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{margin-top:0px;margin-right:10px;margin-bottom:30px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id8372_abce6d-2b > .kt-tabs-title-list li .kt-tab-title:hover, .wp-block-kadence-tabs .kt-tabs-id8372_abce6d-2b > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title:hover{border-color:var(--global-palette8, #F7FAFC);color:#b78ef0;background:rgba(183,142,240,0.13);}.wp-block-kadence-tabs .kt-tabs-id8372_abce6d-2b > .kt-tabs-title-list li.kt-tab-title-active .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id8372_abce6d-2b > .kt-tabs-content-wrap > .kt-tabs-accordion-title.kt-tab-title-active .kt-tab-title{border-color:var(--global-palette7, #eeeeee);color:var(--global-palette3, #1A202C);background:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.kt-tabs-id8372_abce6d-2b > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-tabs-id8372_abce6d-2b > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);padding-top:40px;padding-right:20px;padding-bottom:40px;padding-left:25px;}.wp-block-kadence-tabs .kt-tabs-id8372_abce6d-2b > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id8372_abce6d-2b > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{padding-right:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}}<\/style>\n<div class=\"wp-block-kadence-tabs alignnone\"><div class=\"kt-tabs-wrap kt-tabs-id8372_abce6d-2b kt-tabs-has-3-tabs kt-active-tab-1 kt-tabs-layout-tabs kt-tabs-tablet-layout-inherit kt-tabs-mobile-layout-tabs kt-tab-alignment-left \"><ul class=\"kt-tabs-title-list\"><li id=\"tab-cennikprzedszkola\" class=\"kt-title-item kt-title-item-1 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-active\"><a href=\"#tab-cennikprzedszkola\" data-tab=\"1\" class=\"kt-tab-title kt-tab-title-1 \"><span class=\"kt-title-text\">Preschool price list<\/span><\/a><\/li><li id=\"tab-cennikobka\" class=\"kt-title-item kt-title-item-2 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-cennikobka\" data-tab=\"2\" class=\"kt-tab-title kt-tab-title-2 \"><span class=\"kt-title-text\">Nursery price list<\/span><\/a><\/li><li id=\"tab-danedowpaty\" class=\"kt-title-item kt-title-item-3 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-danedowpaty\" data-tab=\"3\" class=\"kt-tab-title kt-tab-title-3 \"><span class=\"kt-title-text\">Payment details<\/span><\/a><\/li><\/ul><div class=\"kt-tabs-content-wrap\">\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-1 kt-inner-tab8372_b8c853-a3\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id8372_c9307e-d9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_c9307e-d9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_c9307e-d9 > .kt-row-column-wrap{column-gap:76px;row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:minmax(0, calc(43.3% - ((76px * 1 )\/2)))minmax(0, calc(56.7% - ((76px * 1 )\/2)));}.kb-row-layout-id8372_c9307e-d9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_c9307e-d9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_c9307e-d9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_c9307e-d9 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column8372_c778a0-18 > .kt-inside-inner-col,.kadence-column8372_c778a0-18 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_c778a0-18 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_c778a0-18 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_c778a0-18 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_c778a0-18 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_c778a0-18{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_c778a0-18 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_c778a0-18 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_c778a0-18 container-image\"><div class=\"kt-inside-inner-col\"><style>.kb-image8372_a85e74-9c .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image8372_a85e74-9c img.kb-img, .kb-image8372_a85e74-9c .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_a85e74-9c\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1282\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_224261626.webp\" alt=\"\" class=\"kb-img wp-image-7948\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_224261626.webp 1920w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_224261626-300x200.webp 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_224261626-1024x684.webp 1024w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_224261626-768x513.webp 768w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_224261626-1536x1026.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_386f17-ea > .kt-inside-inner-col,.kadence-column8372_386f17-ea > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_386f17-ea > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_386f17-ea > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_386f17-ea > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_386f17-ea > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_386f17-ea{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_386f17-ea > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_386f17-ea > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_386f17-ea\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_f4fa52-f7, .wp-block-kadence-advancedheading.kt-adv-heading8372_f4fa52-f7[data-kb-block=\"kb-adv-heading8372_f4fa52-f7\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_f4fa52-f7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_f4fa52-f7[data-kb-block=\"kb-adv-heading8372_f4fa52-f7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_f4fa52-f7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_f4fa52-f7[data-kb-block=\"kb-adv-heading8372_f4fa52-f7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading8372_f4fa52-f7 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_f4fa52-f7\">Preschool price list<\/h3>\n\n\n<style>.kb-count-up-8372_70bb6d-84 .kb-count-up-number{color:#000000;font-size:80px;line-height:100px;letter-spacing:-4px;font-family:'Plus Jakarta Sans';font-weight:600;}.kb-count-up-8372_70bb6d-84 .kb-count-up-number{margin-top:0px;margin-bottom:0px;}<\/style>\n<div class=\"wp-block-kadence-countup kb-count-up-8372_70bb6d-84 kb-count-up\" data-start=\"0\" data-end=\"299\" data-prefix=\"\" data-suffix=\"z\u0142\" data-duration=\"2.5\" data-separator=\"\"><div class=\"kb-count-up-process kb-count-up-number\"><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_6676ee-0c, .wp-block-kadence-advancedheading.kt-adv-heading8372_6676ee-0c[data-kb-block=\"kb-adv-heading8372_6676ee-0c\"]{margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_6676ee-0c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_6676ee-0c[data-kb-block=\"kb-adv-heading8372_6676ee-0c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_6676ee-0c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_6676ee-0c[data-kb-block=\"kb-adv-heading8372_6676ee-0c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_6676ee-0c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_6676ee-0c\">One-time enrollment fee \u2013 500 PLN<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_30ae43-0f, .wp-block-kadence-advancedheading.kt-adv-heading8372_30ae43-0f[data-kb-block=\"kb-adv-heading8372_30ae43-0f\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_30ae43-0f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_30ae43-0f[data-kb-block=\"kb-adv-heading8372_30ae43-0f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_30ae43-0f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_30ae43-0f[data-kb-block=\"kb-adv-heading8372_30ae43-0f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_30ae43-0f wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_30ae43-0f\">The enrollment fee is NON-REFUNDABLE in case of resignation from the reserved place.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_b9208c-1b, .wp-block-kadence-advancedheading.kt-adv-heading8372_b9208c-1b[data-kb-block=\"kb-adv-heading8372_b9208c-1b\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_b9208c-1b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_b9208c-1b[data-kb-block=\"kb-adv-heading8372_b9208c-1b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_b9208c-1b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_b9208c-1b[data-kb-block=\"kb-adv-heading8372_b9208c-1b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_b9208c-1b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_b9208c-1b\">Monthly tuition: 299 PLN<br\/><br\/><\/p>\n\n\n<style>.kadence-column8372_499074-c9 > .kt-inside-inner-col{display:flex;}.kadence-column8372_499074-c9 > .kt-inside-inner-col,.kadence-column8372_499074-c9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_499074-c9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_499074-c9 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;justify-content:flex-start;}.kadence-column8372_499074-c9 > .kt-inside-inner-col > *, .kadence-column8372_499074-c9 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_499074-c9 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_499074-c9 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column8372_499074-c9{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_499074-c9{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_499074-c9 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_499074-c9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_499074-c9{position:relative;}.kadence-column8372_499074-c9, .kt-inside-inner-col > .kadence-column8372_499074-c9:not(.specificity){margin-top:10px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_499074-c9{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_499074-c9{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_499074-c9 > .kt-inside-inner-col{align-items:flex-start;}}@media all and (max-width: 1024px){.kadence-column8372_499074-c9 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;justify-content:flex-start;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column8372_499074-c9 > .kt-inside-inner-col > *, .kadence-column8372_499074-c9 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_499074-c9 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_499074-c9 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_499074-c9{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_499074-c9{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_499074-c9 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_499074-c9 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;justify-content:flex-start;}.kadence-column8372_499074-c9 > .kt-inside-inner-col > *, .kadence-column8372_499074-c9 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_499074-c9 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_499074-c9 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_499074-c9 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns8372_3e3df3-8a{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns8372_3e3df3-8a .kt-button{font-weight:normal;font-style:normal;}.kt-btns8372_3e3df3-8a .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns8372_3e3df3-8a .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns8372_3e3df3-8a .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_3e3df3-8a .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns8372_3e3df3-8a .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns8372_3e3df3-8a .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_3e3df3-8a .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8372_3e3df3-8a\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn8372_995258-53.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn8372_995258-53.kb-button{padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn8372_995258-53.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_995258-53.kb-button:focus{color:var(--global-palette9, #ffffff);border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8372_995258-53.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_995258-53.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8372_995258-53.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_995258-53.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn8372_995258-53 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"#zapisz\"><span class=\"kt-btn-inner-text\">Enroll your child<\/span><\/a><\/div>\n\n\n<style>.kadence-column8372_c15a91-b1 > .kt-inside-inner-col{display:flex;}.kadence-column8372_c15a91-b1 > .kt-inside-inner-col,.kadence-column8372_c15a91-b1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_c15a91-b1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_c15a91-b1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_c15a91-b1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_c15a91-b1{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c15a91-b1{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c15a91-b1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_c15a91-b1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_c15a91-b1{z-index:2;position:relative;}.kadence-column8372_c15a91-b1, .kt-inside-inner-col > .kadence-column8372_c15a91-b1:not(.specificity){margin-left:-71px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_c15a91-b1{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c15a91-b1{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c15a91-b1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_c15a91-b1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_c15a91-b1{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c15a91-b1{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_c15a91-b1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_c15a91-b1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_c15a91-b1 btn-icon\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons8372_9fe6d8-00 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons8372_9fe6d8-00{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons8372_9fe6d8-00 alignnone\"><style>.kt-svg-item-8372_efecc6-16 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-8372_efecc6-16 .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:6px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-8372_efecc6-16\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-2 kt-inner-tab8372_6ce180-d3\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id8372_8358ea-e0 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_8358ea-e0 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_8358ea-e0 > .kt-row-column-wrap{column-gap:76px;row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:minmax(0, calc(43.3% - ((76px * 1 )\/2)))minmax(0, calc(56.7% - ((76px * 1 )\/2)));}.kb-row-layout-id8372_8358ea-e0 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_8358ea-e0 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_8358ea-e0 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_8358ea-e0 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column8372_ee7711-8d > .kt-inside-inner-col,.kadence-column8372_ee7711-8d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_ee7711-8d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_ee7711-8d > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_ee7711-8d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_ee7711-8d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_ee7711-8d{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_ee7711-8d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_ee7711-8d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_ee7711-8d container-image\"><div class=\"kt-inside-inner-col\"><style>.kb-image8372_cffa1d-81 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image8372_cffa1d-81 img.kb-img, .kb-image8372_cffa1d-81 .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_cffa1d-81 size-full\"><img decoding=\"async\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_187335480.webp\" alt=\"\" class=\"kb-img wp-image-8061\"\/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_207a61-8c > .kt-inside-inner-col,.kadence-column8372_207a61-8c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_207a61-8c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_207a61-8c > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_207a61-8c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_207a61-8c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_207a61-8c{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_207a61-8c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_207a61-8c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_207a61-8c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_8aba6a-7a, .wp-block-kadence-advancedheading.kt-adv-heading8372_8aba6a-7a[data-kb-block=\"kb-adv-heading8372_8aba6a-7a\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_8aba6a-7a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_8aba6a-7a[data-kb-block=\"kb-adv-heading8372_8aba6a-7a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_8aba6a-7a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_8aba6a-7a[data-kb-block=\"kb-adv-heading8372_8aba6a-7a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading8372_8aba6a-7a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_8aba6a-7a\">Nursery price list<\/h3>\n\n\n<style>.kb-count-up-8372_1cd0ac-f4 .kb-count-up-number{color:#000000;font-size:80px;line-height:100px;letter-spacing:-4px;font-family:'Plus Jakarta Sans';font-weight:600;}.kb-count-up-8372_1cd0ac-f4 .kb-count-up-number{margin-top:0px;margin-bottom:0px;}<\/style>\n<div class=\"wp-block-kadence-countup kb-count-up-8372_1cd0ac-f4 kb-count-up\" data-start=\"0\" data-end=\"90\" data-prefix=\"\" data-suffix=\"z\u0142\" data-duration=\"2.5\" data-separator=\"\"><div class=\"kb-count-up-process kb-count-up-number\"><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_e86b2b-63, .wp-block-kadence-advancedheading.kt-adv-heading8372_e86b2b-63[data-kb-block=\"kb-adv-heading8372_e86b2b-63\"]{margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_e86b2b-63 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_e86b2b-63[data-kb-block=\"kb-adv-heading8372_e86b2b-63\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_e86b2b-63 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_e86b2b-63[data-kb-block=\"kb-adv-heading8372_e86b2b-63\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_e86b2b-63 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_e86b2b-63\">One-time enrollment fee \u2013 500 PLN<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_c1da11-53, .wp-block-kadence-advancedheading.kt-adv-heading8372_c1da11-53[data-kb-block=\"kb-adv-heading8372_c1da11-53\"]{margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_c1da11-53 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_c1da11-53[data-kb-block=\"kb-adv-heading8372_c1da11-53\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_c1da11-53 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_c1da11-53[data-kb-block=\"kb-adv-heading8372_c1da11-53\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_c1da11-53 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_c1da11-53\">The nursery participates in the government program \u201cACTIVE IN NURSERY\u201d<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_a942ea-da, .wp-block-kadence-advancedheading.kt-adv-heading8372_a942ea-da[data-kb-block=\"kb-adv-heading8372_a942ea-da\"]{margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_a942ea-da mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_a942ea-da[data-kb-block=\"kb-adv-heading8372_a942ea-da\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_a942ea-da img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_a942ea-da[data-kb-block=\"kb-adv-heading8372_a942ea-da\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_a942ea-da wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_a942ea-da\">The enrollment fee is NON-REFUNDABLE in case of resignation from the reserved place.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_89a650-82, .wp-block-kadence-advancedheading.kt-adv-heading8372_89a650-82[data-kb-block=\"kb-adv-heading8372_89a650-82\"]{margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_89a650-82 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_89a650-82[data-kb-block=\"kb-adv-heading8372_89a650-82\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_89a650-82 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_89a650-82[data-kb-block=\"kb-adv-heading8372_89a650-82\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_89a650-82 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_89a650-82\">Nursery tuition is 1590 PLN (paid in advance by the 10th of each month) \u2013 the amount will be reduced by the ZUS subsidy of 1500 PLN.<br\/><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_47b4dc-e1, .wp-block-kadence-advancedheading.kt-adv-heading8372_47b4dc-e1[data-kb-block=\"kb-adv-heading8372_47b4dc-e1\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_47b4dc-e1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_47b4dc-e1[data-kb-block=\"kb-adv-heading8372_47b4dc-e1\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_47b4dc-e1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_47b4dc-e1[data-kb-block=\"kb-adv-heading8372_47b4dc-e1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_47b4dc-e1 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_47b4dc-e1\">To the above tuition amounts (299 PLN for preschool and 90 PLN for nursery after deducting the \u201cActive in Nursery\u201d benefit), the cost of meals must be added.<\/p>\n\n\n<style>.kadence-column8372_d29357-f9 > .kt-inside-inner-col{display:flex;}.kadence-column8372_d29357-f9 > .kt-inside-inner-col,.kadence-column8372_d29357-f9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_d29357-f9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_d29357-f9 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;justify-content:flex-start;}.kadence-column8372_d29357-f9 > .kt-inside-inner-col > *, .kadence-column8372_d29357-f9 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_d29357-f9 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_d29357-f9 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column8372_d29357-f9{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d29357-f9{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d29357-f9 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_d29357-f9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_d29357-f9{position:relative;}.kadence-column8372_d29357-f9, .kt-inside-inner-col > .kadence-column8372_d29357-f9:not(.specificity){margin-top:10px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_d29357-f9{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d29357-f9{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d29357-f9 > .kt-inside-inner-col{align-items:flex-start;}}@media all and (max-width: 1024px){.kadence-column8372_d29357-f9 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;justify-content:flex-start;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column8372_d29357-f9 > .kt-inside-inner-col > *, .kadence-column8372_d29357-f9 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_d29357-f9 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_d29357-f9 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_d29357-f9{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d29357-f9{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d29357-f9 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_d29357-f9 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;justify-content:flex-start;}.kadence-column8372_d29357-f9 > .kt-inside-inner-col > *, .kadence-column8372_d29357-f9 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_d29357-f9 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_d29357-f9 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_d29357-f9 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns8372_0852f1-80{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns8372_0852f1-80 .kt-button{font-weight:normal;font-style:normal;}.kt-btns8372_0852f1-80 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns8372_0852f1-80 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns8372_0852f1-80 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_0852f1-80 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns8372_0852f1-80 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns8372_0852f1-80 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_0852f1-80 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8372_0852f1-80\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn8372_c843fb-12.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn8372_c843fb-12.kb-button{padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn8372_c843fb-12.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_c843fb-12.kb-button:focus{color:var(--global-palette9, #ffffff);border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8372_c843fb-12.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_c843fb-12.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8372_c843fb-12.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_c843fb-12.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn8372_c843fb-12 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"#zapisz\"><span class=\"kt-btn-inner-text\">Enroll your child<\/span><\/a><\/div>\n\n\n<style>.kadence-column8372_d475bc-ff > .kt-inside-inner-col{display:flex;}.kadence-column8372_d475bc-ff > .kt-inside-inner-col,.kadence-column8372_d475bc-ff > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_d475bc-ff > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_d475bc-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_d475bc-ff > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_d475bc-ff{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d475bc-ff{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d475bc-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_d475bc-ff > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_d475bc-ff{z-index:2;position:relative;}.kadence-column8372_d475bc-ff, .kt-inside-inner-col > .kadence-column8372_d475bc-ff:not(.specificity){margin-left:-71px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_d475bc-ff{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d475bc-ff{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d475bc-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_d475bc-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_d475bc-ff{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d475bc-ff{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d475bc-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_d475bc-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_d475bc-ff btn-icon\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons8372_30a75b-32 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons8372_30a75b-32{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons8372_30a75b-32 alignnone\"><style>.kt-svg-item-8372_8934b2-51 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-8372_8934b2-51 .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:6px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-8372_8934b2-51\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-3 kt-inner-tab8372_e18929-fa\"><div class=\"kt-tab-inner-content-inner\"><style>.kb-row-layout-id8372_b5ba84-ef > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_b5ba84-ef > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_b5ba84-ef > .kt-row-column-wrap{column-gap:76px;row-gap:var(--global-kb-gap-md, 2rem);grid-template-columns:minmax(0, calc(43.3% - ((76px * 1 )\/2)))minmax(0, calc(56.7% - ((76px * 1 )\/2)));}.kb-row-layout-id8372_b5ba84-ef > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_b5ba84-ef > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_b5ba84-ef > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_b5ba84-ef alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column8372_cb78a7-04 > .kt-inside-inner-col,.kadence-column8372_cb78a7-04 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_cb78a7-04 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_cb78a7-04 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_cb78a7-04 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_cb78a7-04 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_cb78a7-04{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_cb78a7-04 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_cb78a7-04 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_cb78a7-04\"><div class=\"kt-inside-inner-col\"><style>.kb-image8372_a2ee9e-b2 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image8372_a2ee9e-b2 img.kb-img, .kb-image8372_a2ee9e-b2 .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image8372_a2ee9e-b2\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1372\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_181768914.webp\" alt=\"\" class=\"kb-img wp-image-7947\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_181768914.webp 1920w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_181768914-300x214.webp 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_181768914-1024x732.webp 1024w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_181768914-768x549.webp 768w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_181768914-1536x1098.webp 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_2b25ca-be > .kt-inside-inner-col{display:flex;}.kadence-column8372_2b25ca-be > .kt-inside-inner-col,.kadence-column8372_2b25ca-be > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_2b25ca-be > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_2b25ca-be > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_2b25ca-be > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_2b25ca-be{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_2b25ca-be{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_2b25ca-be > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_2b25ca-be > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_2b25ca-be{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_2b25ca-be{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_2b25ca-be{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_2b25ca-be > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_2b25ca-be > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_2b25ca-be{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_2b25ca-be{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_2b25ca-be > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_2b25ca-be > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_2b25ca-be\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_10b795-dd, .wp-block-kadence-advancedheading.kt-adv-heading8372_10b795-dd[data-kb-block=\"kb-adv-heading8372_10b795-dd\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_10b795-dd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_10b795-dd[data-kb-block=\"kb-adv-heading8372_10b795-dd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_10b795-dd img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_10b795-dd[data-kb-block=\"kb-adv-heading8372_10b795-dd\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading8372_10b795-dd wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_10b795-dd\">Payment details<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_08db9d-40, .wp-block-kadence-advancedheading.kt-adv-heading8372_08db9d-40[data-kb-block=\"kb-adv-heading8372_08db9d-40\"]{margin-bottom:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_08db9d-40 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_08db9d-40[data-kb-block=\"kb-adv-heading8372_08db9d-40\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_08db9d-40 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_08db9d-40[data-kb-block=\"kb-adv-heading8372_08db9d-40\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_08db9d-40 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_08db9d-40\">Payments can only be made via the LiveKids application.<\/p>\n\n\n<style>.kadence-column8372_d6de13-39 > .kt-inside-inner-col{display:flex;}.kadence-column8372_d6de13-39 > .kt-inside-inner-col,.kadence-column8372_d6de13-39 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_d6de13-39 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_d6de13-39 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;justify-content:flex-start;}.kadence-column8372_d6de13-39 > .kt-inside-inner-col > *, .kadence-column8372_d6de13-39 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_d6de13-39 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_d6de13-39 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column8372_d6de13-39{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d6de13-39{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d6de13-39 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_d6de13-39 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_d6de13-39{position:relative;}.kadence-column8372_d6de13-39, .kt-inside-inner-col > .kadence-column8372_d6de13-39:not(.specificity){margin-top:10px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_d6de13-39{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d6de13-39{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d6de13-39 > .kt-inside-inner-col{align-items:flex-start;}}@media all and (max-width: 1024px){.kadence-column8372_d6de13-39 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-start;justify-content:flex-start;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column8372_d6de13-39 > .kt-inside-inner-col > *, .kadence-column8372_d6de13-39 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_d6de13-39 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_d6de13-39 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_d6de13-39{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d6de13-39{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_d6de13-39 > .kt-inside-inner-col{align-items:flex-start;}.kadence-column8372_d6de13-39 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;justify-content:flex-start;}.kadence-column8372_d6de13-39 > .kt-inside-inner-col > *, .kadence-column8372_d6de13-39 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_d6de13-39 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_d6de13-39 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_d6de13-39 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns8372_272569-6b{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns8372_272569-6b .kt-button{font-weight:normal;font-style:normal;}.kt-btns8372_272569-6b .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns8372_272569-6b .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns8372_272569-6b .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_272569-6b .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns8372_272569-6b .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns8372_272569-6b .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_272569-6b .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8372_272569-6b\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn8372_111f03-f1.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn8372_111f03-f1.kb-button{padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn8372_111f03-f1.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_111f03-f1.kb-button:focus{color:var(--global-palette9, #ffffff);border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8372_111f03-f1.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_111f03-f1.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8372_111f03-f1.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_111f03-f1.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn8372_111f03-f1 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"#zapisz\"><span class=\"kt-btn-inner-text\">Enroll your child<\/span><\/a><\/div>\n\n\n<style>.kadence-column8372_e4b8c4-06 > .kt-inside-inner-col{display:flex;}.kadence-column8372_e4b8c4-06 > .kt-inside-inner-col,.kadence-column8372_e4b8c4-06 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_e4b8c4-06 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_e4b8c4-06 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_e4b8c4-06 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_e4b8c4-06{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_e4b8c4-06{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_e4b8c4-06 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_e4b8c4-06 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_e4b8c4-06{z-index:2;position:relative;}.kadence-column8372_e4b8c4-06, .kt-inside-inner-col > .kadence-column8372_e4b8c4-06:not(.specificity){margin-left:-71px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_e4b8c4-06{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_e4b8c4-06{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_e4b8c4-06 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_e4b8c4-06 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_e4b8c4-06{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_e4b8c4-06{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_e4b8c4-06 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_e4b8c4-06 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_e4b8c4-06 btn-icon\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons8372_c4faae-ea .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons8372_c4faae-ea{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons8372_c4faae-ea alignnone\"><style>.kt-svg-item-8372_162ce5-af .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-8372_162ce5-af .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:6px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-8372_162ce5-af\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id8372_b9054e-90 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_b9054e-90 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_b9054e-90 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8372_b9054e-90{background-image:url('https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/Frame-183-3.svg');background-size:auto;background-position:70% 49%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id8372_b9054e-90 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_b9054e-90 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_b9054e-90 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_b9054e-90 alignnone kt-row-has-bg wp-block-kadence-rowlayout\" id=\"doc-do-pobrania\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column8372_6492e2-de > .kt-inside-inner-col,.kadence-column8372_6492e2-de > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_6492e2-de > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_6492e2-de > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_6492e2-de > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_6492e2-de > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_6492e2-de{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_6492e2-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_6492e2-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_6492e2-de\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_e860db-e5, .wp-block-kadence-advancedheading.kt-adv-heading8372_e860db-e5[data-kb-block=\"kb-adv-heading8372_e860db-e5\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:center;font-size:49px;line-height:1.3;font-weight:700;font-style:normal;font-family:'Plus Jakarta Sans';}.wp-block-kadence-advancedheading.kt-adv-heading8372_e860db-e5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_e860db-e5[data-kb-block=\"kb-adv-heading8372_e860db-e5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_e860db-e5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_e860db-e5[data-kb-block=\"kb-adv-heading8372_e860db-e5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8372_e860db-e5, .wp-block-kadence-advancedheading.kt-adv-heading8372_e860db-e5[data-kb-block=\"kb-adv-heading8372_e860db-e5\"]{font-size:49px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8372_e860db-e5, .wp-block-kadence-advancedheading.kt-adv-heading8372_e860db-e5[data-kb-block=\"kb-adv-heading8372_e860db-e5\"]{font-size:30px;}}<\/style>\n<h3 class=\"kt-adv-heading8372_e860db-e5 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_e860db-e5\">Documents to download<\/h3>\n\n\n<style>.kb-row-layout-id8372_a6d1e5-0c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_a6d1e5-0c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_a6d1e5-0c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id8372_a6d1e5-0c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_a6d1e5-0c > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id8372_a6d1e5-0c > .kt-row-column-wrap{row-gap:var(--global-kb-gap-sm, 1rem);grid-template-columns:minmax(0, 1fr);}}.kb-row-layout-id8372_a6d1e5-0c a{color:black;text-decoration: none;text-transform: uppercase;font-size:20px !important;  }.kb-row-layout-id8372_a6d1e5-0c .wp-block-file{  margin-bottom: 0px !important;  padding-bottom: 0px !important;}.kb-row-layout-id8372_a6d1e5-0c a.wp-block-file__button.wp-element-button {    border-radius: 100px;    background:#F4ECFF}    .kb-row-layout-id8372_a6d1e5-0c a.wp-block-file__button.wp-element-button:hover {          background:#B78EF0;}    @media (max-width:767px) {  .kb-row-layout-id8372_a6d1e5-0c .wp-block-file {    border:1px solid lightgray;    padding: 10px;    font-size:16px !important;    border-radius: 10px;}.kb-row-layout-id8372_a6d1e5-0c .wp-block-file * {  font-size:17px !important;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_a6d1e5-0c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column8372_40fc4e-04 > .kt-inside-inner-col{display:flex;}.kadence-column8372_40fc4e-04 > .kt-inside-inner-col,.kadence-column8372_40fc4e-04 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_40fc4e-04 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-sm, 1rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_40fc4e-04 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_40fc4e-04 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_40fc4e-04 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_40fc4e-04{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_40fc4e-04 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_40fc4e-04 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_40fc4e-04\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-file\" style=\"padding-top:0;padding-bottom:0\"><a id=\"wp-block-file--media-96c7dbb0-1da7-437b-8a30-7233c77b7bd7\" href=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/polityka-ochrony-dzieci-przed-krzywdzeniem-1-1.pdf\">child-protection-policy-1<\/a><a href=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/polityka-ochrony-dzieci-przed-krzywdzeniem-1-1.pdf\" class=\"wp-block-file__button wp-element-button\" download=\"\" aria-describedby=\"wp-block-file--media-96c7dbb0-1da7-437b-8a30-7233c77b7bd7\">Download<\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_368296-e5 > .kt-inside-inner-col{display:flex;}.kadence-column8372_368296-e5 > .kt-inside-inner-col,.kadence-column8372_368296-e5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_368296-e5 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-sm, 1rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_368296-e5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_368296-e5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_368296-e5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_368296-e5{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_368296-e5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_368296-e5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_368296-e5\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-file\" style=\"padding-top:0;padding-bottom:0\"><a id=\"wp-block-file--media-40cb2bc9-fff2-4e31-97e4-fadb8f7dd731\" href=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/Nowa-Karta-zgoszeniowa-zobek-L-ednica-o-kontroli-1.doc\">New-Application-Form-Nursery-Lednica-with-control-1<\/a><a href=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/Nowa-Karta-zgoszeniowa-zobek-L-ednica-o-kontroli-1.doc\" class=\"wp-block-file__button wp-element-button\" download=\"\" aria-describedby=\"wp-block-file--media-40cb2bc9-fff2-4e31-97e4-fadb8f7dd731\">Download<\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_96b856-89 > .kt-inside-inner-col{display:flex;}.kadence-column8372_96b856-89 > .kt-inside-inner-col,.kadence-column8372_96b856-89 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_96b856-89 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-sm, 1rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_96b856-89 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_96b856-89 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_96b856-89 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_96b856-89{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_96b856-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_96b856-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_96b856-89\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-file\" style=\"padding-top:0;padding-bottom:0\"><a id=\"wp-block-file--media-ea5e74ef-da2c-4746-8cc8-3b63793d59cf\" href=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/STANDARDY_OCHRONY_MALOLETNICH_W-PRZEDSZKOLU-FAIR-PLAY-W-LEDNICY-GORNEJ.docx\">CHILD PROTECTION STANDARDS<\/a><a href=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/STANDARDY_OCHRONY_MALOLETNICH_W-PRZEDSZKOLU-FAIR-PLAY-W-LEDNICY-GORNEJ.docx\" class=\"wp-block-file__button wp-element-button\" download=\"\" aria-describedby=\"wp-block-file--media-ea5e74ef-da2c-4746-8cc8-3b63793d59cf\">Download<\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, calc(45% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(55% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id8372_0d013d-25 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}}@media all and (max-width: 1024px){.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}@media all and (max-width: 767px){.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id8372_0d013d-25 > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_0d013d-25 alignnone wp-block-kadence-rowlayout\" id=\"lokalizacja\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column8372_d6f670-e6 > .kt-inside-inner-col,.kadence-column8372_d6f670-e6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_d6f670-e6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_d6f670-e6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_d6f670-e6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_d6f670-e6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_d6f670-e6{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_d6f670-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_d6f670-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_d6f670-e6 container-image\"><div class=\"kt-inside-inner-col\"><style>.kb-google-maps-container8372_da1a31-4a{height:650px;}<\/style><div class=\"kb-google-maps-container kb-google-maps-container8372_da1a31-4a wp-block-kadence-googlemaps\" data-mapid=\"8372_da1a314a\"><iframe width=\"100%\" height=\"100%\"\n\t\t\t\t\t\t\tstyle=\"border:0\" loading=\"lazy\"\n\t\t\t\t\t\t\tsrc=\"https:\/\/www.google.com\/maps\/embed\/v1\/place?key=AIzaSyBAM2o7PiQqwk15LC1XRH2e_KJ-jUa7KYk&#038;zoom=11&#038;maptype=roadmap&#038;q=Niepubliczny+%C5%BB%C5%82obek+i+Przedszkole+Fair+Play+Lednica+G%C3%B3rna+207\"\n\t\t\t\t\t\t\ttitle=\"Google map of Niepubliczny \u017b\u0142obek i Przedszkole Fair Play Lednica G\u00f3rna 207\"><\/iframe><\/div><script>function kb_google_map8372_da1a314a() { let center = { lat: 37.8201, lng: -122.4781}; let map = new google.maps.Map(document.getElementById(\"kb-google-map8372_da1a314a\"), {\n\t\t\t\t\t    zoom: 11,\n\t\t\t\t\t    center: center,});let marker = new google.maps.Marker({   position: { lat: 37.8201, lng: -122.4781},    map: map,  });}<\/script><\/div><\/div>\n\n\n<style>.kadence-column8372_f1d917-4f > .kt-inside-inner-col,.kadence-column8372_f1d917-4f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_f1d917-4f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_f1d917-4f > .kt-inside-inner-col{flex-direction:column;}.kadence-column8372_f1d917-4f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_f1d917-4f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_f1d917-4f{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_f1d917-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column8372_f1d917-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}.kadence-column8372_f1d917-4f .kt-accordion-header-wrap>button{\r  \r  border-radius:20px !important;\r    box-shadow: 0px 4px 63.9px 0px rgba(0, 0, 0, 0.15);\r}\r.kadence-column8372_f1d917-4f .kt-accordion-panel-inner {\r    background: transparent !important;\r}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_f1d917-4f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_240cc6-78, .wp-block-kadence-advancedheading.kt-adv-heading8372_240cc6-78[data-kb-block=\"kb-adv-heading8372_240cc6-78\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left;font-size:49px;line-height:1.3;font-weight:700;font-style:normal;font-family:'Plus Jakarta Sans';}.wp-block-kadence-advancedheading.kt-adv-heading8372_240cc6-78 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_240cc6-78[data-kb-block=\"kb-adv-heading8372_240cc6-78\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_240cc6-78 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_240cc6-78[data-kb-block=\"kb-adv-heading8372_240cc6-78\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8372_240cc6-78, .wp-block-kadence-advancedheading.kt-adv-heading8372_240cc6-78[data-kb-block=\"kb-adv-heading8372_240cc6-78\"]{font-size:49px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8372_240cc6-78, .wp-block-kadence-advancedheading.kt-adv-heading8372_240cc6-78[data-kb-block=\"kb-adv-heading8372_240cc6-78\"]{font-size:30px;}}<\/style>\n<h3 class=\"kt-adv-heading8372_240cc6-78 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_240cc6-78\">Contact<\/h3>\n\n\n<style>.kadence-column8372_dd9710-44 > .kt-inside-inner-col{display:flex;}.kadence-column8372_dd9710-44 > .kt-inside-inner-col,.kadence-column8372_dd9710-44 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_dd9710-44 > .kt-inside-inner-col{column-gap:77px;}.kadence-column8372_dd9710-44 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}.kadence-column8372_dd9710-44 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column8372_dd9710-44 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column8372_dd9710-44 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_dd9710-44 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_dd9710-44{position:relative;}.kadence-column8372_dd9710-44, .kt-inside-inner-col > .kadence-column8372_dd9710-44:not(.specificity){margin-bottom:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kadence-column8372_dd9710-44 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}@media all and (max-width: 767px){.kadence-column8372_dd9710-44 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}.kadence-column8372_dd9710-44, .kt-inside-inner-col > .kadence-column8372_dd9710-44:not(.specificity){margin-bottom:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_dd9710-44 kb-section-dir-vertical\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_7bcf62-17, .wp-block-kadence-advancedheading.kt-adv-heading8372_7bcf62-17[data-kb-block=\"kb-adv-heading8372_7bcf62-17\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_7bcf62-17 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_7bcf62-17[data-kb-block=\"kb-adv-heading8372_7bcf62-17\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_7bcf62-17 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_7bcf62-17[data-kb-block=\"kb-adv-heading8372_7bcf62-17\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading8372_7bcf62-17 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_7bcf62-17\">Director<\/h3>\n\n\n<style>.kt-info-box8372_879ef4-c3{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_879ef4-c3{height:auto;align-self:stretch;}.kt-info-box8372_879ef4-c3 .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_879ef4-c3 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box8372_879ef4-c3 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box8372_879ef4-c3 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box8372_879ef4-c3 .kt-info-svg-icon-flip, .kt-info-box8372_879ef4-c3 .kt-blocks-info-box-number{font-size:30px;}.kt-info-box8372_879ef4-c3 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);background:var(--global-palette6, #718096);border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:13px;margin-right:15px;margin-bottom:16px;margin-left:0px;}.kt-info-box8372_879ef4-c3 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:1rem;}.kt-info-box8372_879ef4-c3 .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:10px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box8372_879ef4-c3 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box8372_879ef4-c3 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box8372_879ef4-c3 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box8372_879ef4-c3 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box8372_879ef4-c3\"><a class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\" href=\"tel:+48 574 442 544\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_phoneCall kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M15.05 5A5 5 0 0 1 19 8.95M15.05 1A9 9 0 0 1 23 8.94m-1 7.98v3a2 2 0 0 1-2.18 2 19.79 19.79 0 0 1-8.63-3.07 19.5 19.5 0 0 1-6-6 19.79 19.79 0 0 1-3.07-8.67A2 2 0 0 1 4.11 2h3a2 2 0 0 1 2 1.72 12.84 12.84 0 0 0 .7 2.81 2 2 0 0 1-.45 2.11L8.09 9.91a16 16 0 0 0 6 6l1.27-1.27a2 2 0 0 1 2.11-.45 12.84 12.84 0 0 0 2.81.7A2 2 0 0 1 22 16.92z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">Budek Gabriela<\/h4><p class=\"kt-blocks-info-box-text\">+48 574 442 544<\/p><\/div><\/a><\/div>\n\n\n<style>.kt-info-box8372_cc6774-de{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_cc6774-de{height:auto;align-self:stretch;}.kt-info-box8372_cc6774-de .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_cc6774-de .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box8372_cc6774-de .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-right:0px;}.kt-info-box8372_cc6774-de .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box8372_cc6774-de .kt-info-svg-icon-flip, .kt-info-box8372_cc6774-de .kt-blocks-info-box-number{font-size:30px;}.kt-info-box8372_cc6774-de .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);background:var(--global-palette6, #718096);border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:13px;margin-right:15px;margin-bottom:16px;margin-left:0px;}.kt-info-box8372_cc6774-de .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:1rem;}.kt-info-box8372_cc6774-de .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:10px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box8372_cc6774-de .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box8372_cc6774-de .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box8372_cc6774-de .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box8372_cc6774-de .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box8372_cc6774-de\"><a class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\" href=\"mailto:g.budek@fairplay-lednicagorna.pl\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mail kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M4 4h16c1.1 0 2 .9 2 2v12c0 1.1-.9 2-2 2H4c-1.1 0-2-.9-2-2V6c0-1.1.9-2 2-2z\"\/><polyline points=\"22,6 12,13 2,6\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">Send an email<\/h4><p class=\"kt-blocks-info-box-text\">g.budek@fairplay-lednicagorna.pl<\/p><\/div><\/a><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-8372_6a4b35-7e .kt-block-spacer{height:7px;}.wp-block-kadence-spacer.kt-block-spacer-8372_6a4b35-7e .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-8372_6a4b35-7e\"><div class=\"kt-block-spacer kt-block-spacer-halign-left\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_11747e-22, .wp-block-kadence-advancedheading.kt-adv-heading8372_11747e-22[data-kb-block=\"kb-adv-heading8372_11747e-22\"]{margin-top:var(--global-kb-spacing-xs, 1rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_11747e-22 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_11747e-22[data-kb-block=\"kb-adv-heading8372_11747e-22\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_11747e-22 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_11747e-22[data-kb-block=\"kb-adv-heading8372_11747e-22\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading8372_11747e-22 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_11747e-22\">Owner<\/h3>\n\n\n<style>.kt-info-box8372_e9c488-cd{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_e9c488-cd{height:auto;align-self:stretch;}.kt-info-box8372_e9c488-cd .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_e9c488-cd .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box8372_e9c488-cd .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box8372_e9c488-cd .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box8372_e9c488-cd .kt-info-svg-icon-flip, .kt-info-box8372_e9c488-cd .kt-blocks-info-box-number{font-size:30px;}.kt-info-box8372_e9c488-cd .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);background:var(--global-palette6, #718096);border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:13px;margin-right:15px;margin-bottom:16px;margin-left:0px;}.kt-info-box8372_e9c488-cd .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:1rem;}.kt-info-box8372_e9c488-cd .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:10px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box8372_e9c488-cd .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box8372_e9c488-cd .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box8372_e9c488-cd .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box8372_e9c488-cd .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box8372_e9c488-cd\"><a class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\" href=\"tel:+48 570 100 237\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_phoneCall kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M15.05 5A5 5 0 0 1 19 8.95M15.05 1A9 9 0 0 1 23 8.94m-1 7.98v3a2 2 0 0 1-2.18 2 19.79 19.79 0 0 1-8.63-3.07 19.5 19.5 0 0 1-6-6 19.79 19.79 0 0 1-3.07-8.67A2 2 0 0 1 4.11 2h3a2 2 0 0 1 2 1.72 12.84 12.84 0 0 0 .7 2.81 2 2 0 0 1-.45 2.11L8.09 9.91a16 16 0 0 0 6 6l1.27-1.27a2 2 0 0 1 2.11-.45 12.84 12.84 0 0 0 2.81.7A2 2 0 0 1 22 16.92z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">Manijak Sebastian<\/h4><p class=\"kt-blocks-info-box-text\">+48 570 100 237<\/p><\/div><\/a><\/div>\n\n\n<style>.kt-info-box8372_4785a8-94{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_4785a8-94{height:auto;align-self:stretch;}.kt-info-box8372_4785a8-94 .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_4785a8-94 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box8372_4785a8-94 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-right:0px;}.kt-info-box8372_4785a8-94 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box8372_4785a8-94 .kt-info-svg-icon-flip, .kt-info-box8372_4785a8-94 .kt-blocks-info-box-number{font-size:30px;}.kt-info-box8372_4785a8-94 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);background:var(--global-palette6, #718096);border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:13px;margin-right:15px;margin-bottom:16px;margin-left:0px;}.kt-info-box8372_4785a8-94 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:1rem;}.kt-info-box8372_4785a8-94 .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:10px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box8372_4785a8-94 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box8372_4785a8-94 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box8372_4785a8-94 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box8372_4785a8-94 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box8372_4785a8-94\"><a class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\" href=\"mailto:biuro@fairplay-lednicagorna.pl\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mail kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M4 4h16c1.1 0 2 .9 2 2v12c0 1.1-.9 2-2 2H4c-1.1 0-2-.9-2-2V6c0-1.1.9-2 2-2z\"\/><polyline points=\"22,6 12,13 2,6\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h4 class=\"kt-blocks-info-box-title\">Send an email<\/h4><p class=\"kt-blocks-info-box-text\">biuro@fairplay-lednicagorna.pl<\/p><\/div><\/a><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-8372_ac4c36-18 .kt-block-spacer{height:7px;}.wp-block-kadence-spacer.kt-block-spacer-8372_ac4c36-18 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-8372_ac4c36-18\"><div class=\"kt-block-spacer kt-block-spacer-halign-left\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kt-info-box8372_60ed8d-21{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_60ed8d-21{height:auto;align-self:stretch;}.kt-info-box8372_60ed8d-21 .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box8372_60ed8d-21 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box8372_60ed8d-21 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-right:0px;}.kt-info-box8372_60ed8d-21 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box8372_60ed8d-21 .kt-info-svg-icon-flip, .kt-info-box8372_60ed8d-21 .kt-blocks-info-box-number{font-size:30px;}.kt-info-box8372_60ed8d-21 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);background:var(--global-palette6, #718096);border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:13px;margin-right:15px;margin-bottom:16px;margin-left:0px;}.kt-info-box8372_60ed8d-21 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:1rem;}.kt-info-box8372_60ed8d-21 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:22px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:10px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box8372_60ed8d-21 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box8372_60ed8d-21 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box8372_60ed8d-21 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box8372_60ed8d-21 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box8372_60ed8d-21\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mapPin kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M21 10c0 7-9 13-9 13s-9-6-9-13a9 9 0 0 1 18 0z\"\/><circle cx=\"12\" cy=\"10\" r=\"3\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Address<\/h3><p class=\"kt-blocks-info-box-text\">Non-Public Nursery and Preschool<br\/>Fair Play<br\/>Lednica G\u00f3rna 207, 32-020 Wieliczka<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column8372_cf1662-d9 > .kt-inside-inner-col{display:flex;}.kadence-column8372_cf1662-d9 > .kt-inside-inner-col,.kadence-column8372_cf1662-d9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_cf1662-d9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_cf1662-d9 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column8372_cf1662-d9 > .kt-inside-inner-col > *, .kadence-column8372_cf1662-d9 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_cf1662-d9 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_cf1662-d9 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column8372_cf1662-d9{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_cf1662-d9{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_cf1662-d9 > .kt-inside-inner-col{align-items:center;}.kadence-column8372_cf1662-d9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_cf1662-d9{position:relative;}.kadence-column8372_cf1662-d9, .kt-inside-inner-col > .kadence-column8372_cf1662-d9:not(.specificity){margin-top:10px;margin-bottom:30px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_cf1662-d9{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_cf1662-d9{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_cf1662-d9 > .kt-inside-inner-col{align-items:center;}}@media all and (max-width: 1024px){.kadence-column8372_cf1662-d9 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column8372_cf1662-d9 > .kt-inside-inner-col > *, .kadence-column8372_cf1662-d9 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_cf1662-d9 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_cf1662-d9 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_cf1662-d9{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_cf1662-d9{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_cf1662-d9 > .kt-inside-inner-col{align-items:center;}.kadence-column8372_cf1662-d9 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column8372_cf1662-d9 > .kt-inside-inner-col > *, .kadence-column8372_cf1662-d9 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column8372_cf1662-d9 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column8372_cf1662-d9 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_cf1662-d9 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns8372_f648f7-2c{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns8372_f648f7-2c .kt-button{font-weight:normal;font-style:normal;}.kt-btns8372_f648f7-2c .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns8372_f648f7-2c .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns8372_f648f7-2c .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_f648f7-2c .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns8372_f648f7-2c .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns8372_f648f7-2c .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns8372_f648f7-2c .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns8372_f648f7-2c\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn8372_c5bdc4-11.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn8372_c5bdc4-11.kb-button{padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn8372_c5bdc4-11.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_c5bdc4-11.kb-button:focus{color:var(--global-palette9, #ffffff);border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn8372_c5bdc4-11.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_c5bdc4-11.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn8372_c5bdc4-11.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn8372_c5bdc4-11.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn8372_c5bdc4-11 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"#zapisz\"><span class=\"kt-btn-inner-text\">Enroll your child<\/span><\/a><\/div>\n\n\n<style>.kadence-column8372_5fd465-0f > .kt-inside-inner-col{display:flex;}.kadence-column8372_5fd465-0f{max-width:45px;margin-left:auto;margin-right:auto;}.wp-block-kadence-column.kb-section-dir-horizontal:not(.kb-section-md-dir-vertical)>.kt-inside-inner-col>.kadence-column8372_5fd465-0f{-webkit-flex:0 1 45px;flex:0 1 45px;max-width:unset;margin-left:unset;margin-right:unset;}.kadence-column8372_5fd465-0f > .kt-inside-inner-col,.kadence-column8372_5fd465-0f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_5fd465-0f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_5fd465-0f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_5fd465-0f > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column8372_5fd465-0f{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_5fd465-0f{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_5fd465-0f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column8372_5fd465-0f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_5fd465-0f{z-index:2;position:relative;}.kadence-column8372_5fd465-0f, .kt-inside-inner-col > .kadence-column8372_5fd465-0f:not(.specificity){margin-left:-71px;}@media all and (min-width: 1025px){.wp-block-kadence-column.kb-section-dir-horizontal>.kt-inside-inner-col>.kadence-column8372_5fd465-0f{-webkit-flex:0 1 45px;flex:0 1 45px;max-width:unset;margin-left:unset;margin-right:unset;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column8372_5fd465-0f{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_5fd465-0f{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_5fd465-0f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column8372_5fd465-0f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column8372_5fd465-0f{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_5fd465-0f{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column8372_5fd465-0f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.wp-block-kadence-column.kb-section-sm-dir-vertical:not(.kb-section-sm-dir-horizontal):not(.kb-section-sm-dir-specificity)>.kt-inside-inner-col>.kadence-column8372_5fd465-0f{max-width:45px;-webkit-flex:1;flex:1;margin-left:auto;margin-right:auto;}.kadence-column8372_5fd465-0f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_5fd465-0f btn-icon\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons8372_eb7675-7c .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons8372_eb7675-7c{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons8372_eb7675-7c alignnone\"><style>.kt-svg-item-8372_70053f-db .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-8372_70053f-db .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:0px;margin-left:-75px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-8372_70053f-db\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id8372_345004-33 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id8372_345004-33 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id8372_345004-33 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id8372_345004-33{background-image:url('https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/Frame-183-3.svg');background-size:auto;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id8372_345004-33 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id8372_345004-33 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id8372_345004-33 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id8372_345004-33 alignnone kt-row-has-bg wp-block-kadence-rowlayout\" id=\"galeria\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column8372_2b4668-1c > .kt-inside-inner-col{display:flex;}.kadence-column8372_2b4668-1c > .kt-inside-inner-col,.kadence-column8372_2b4668-1c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column8372_2b4668-1c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column8372_2b4668-1c > .kt-inside-inner-col{flex-direction:column;align-items:center;}.kadence-column8372_2b4668-1c > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column8372_2b4668-1c > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column8372_2b4668-1c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column8372_2b4668-1c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column8372_2b4668-1c{position:relative;}@media all and (max-width: 1024px){.kadence-column8372_2b4668-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kadence-column8372_2b4668-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}.kadence-column8372_2b4668-1c button.splide__arrow.splide__arrow--prev.slick-prev {\r    background: white;\r    color: black;\r    opacity: 100 !important;\r    width: 47px;\r    border-radius: 101px;\r}\r.kadence-column8372_2b4668-1c button.splide__arrow.splide__arrow--next.slick-next {\r    background: white;\r    color: black;\r    opacity: 100 !important;\r    width: 47px;\r    border-radius: 101px;\r}<\/style>\n<div class=\"wp-block-kadence-column kadence-column8372_2b4668-1c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading8372_d211c8-b8, .wp-block-kadence-advancedheading.kt-adv-heading8372_d211c8-b8[data-kb-block=\"kb-adv-heading8372_d211c8-b8\"]{margin-bottom:var(--global-kb-spacing-lg, 3rem);text-align:center;font-size:49px;line-height:1.3;font-weight:700;font-style:normal;font-family:'Plus Jakarta Sans';}.wp-block-kadence-advancedheading.kt-adv-heading8372_d211c8-b8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_d211c8-b8[data-kb-block=\"kb-adv-heading8372_d211c8-b8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_d211c8-b8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_d211c8-b8[data-kb-block=\"kb-adv-heading8372_d211c8-b8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading8372_d211c8-b8, .wp-block-kadence-advancedheading.kt-adv-heading8372_d211c8-b8[data-kb-block=\"kb-adv-heading8372_d211c8-b8\"]{font-size:49px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading8372_d211c8-b8, .wp-block-kadence-advancedheading.kt-adv-heading8372_d211c8-b8[data-kb-block=\"kb-adv-heading8372_d211c8-b8\"]{font-size:30px;}}<\/style>\n<h3 class=\"kt-adv-heading8372_d211c8-b8 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_d211c8-b8\">Gallery<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading8372_13b94b-bc, .wp-block-kadence-advancedheading.kt-adv-heading8372_13b94b-bc[data-kb-block=\"kb-adv-heading8372_13b94b-bc\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading8372_13b94b-bc mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading8372_13b94b-bc[data-kb-block=\"kb-adv-heading8372_13b94b-bc\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading8372_13b94b-bc img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading8372_13b94b-bc[data-kb-block=\"kb-adv-heading8372_13b94b-bc\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading8372_13b94b-bc wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading8372_13b94b-bc\">[materials under construction&#8230;]<br\/><\/p>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"<!-- Google Tag Manager -->\n<script>\n(function(w,d,s,l,i){w[l]=w[l]||[];w[l].push({'gtm.start':\nnew Date().getTime(),event:'gtm.js'});\nvar f=d.getElementsByTagName(s)[0],\nj=d.createElement(s),dl=l!='dataLayer'?'&l='+l:'';\nj.async=true;j.src=\n'https:\/\/www.googletagmanager.com\/gtm.js?id=GTM-NT6F6D6H'+dl;\nf.parentNode.insertBefore(j,f);\n})(window,document,'script','dataLayer','GTM-NT6F6D6H');\n<\/script>\n<!-- End Google Tag Manager -->","_kad_blocks_body_custom_js":"<!-- Google Tag Manager (noscript) -->\n<noscript>\n<iframe src=\"https:\/\/www.googletagmanager.com\/ns.html?id=GTM-NT6F6D6H\" height=\"0\" width=\"0\" style=\"display:none;visibility:hidden\"><\/iframe>\n<\/noscript>\n<!-- End Google Tag Manager (noscript) -->","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"typ_placowki":[47,45],"miasto":[31],"class_list":["post-12086","placowki","type-placowki","status-publish","hentry","typ_placowki-kindergarten","typ_placowki-nursery","miasto-wieliczka"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wieliczka Lednica G\u00f3rna 207 - FairPlay Kindergarten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/przedszkolefairplay.info.pl\/en\/facilities\/non-public-sports-language-nursery-preschool\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wieliczka Lednica G\u00f3rna 207 - FairPlay Kindergarten\" \/>\n<meta property=\"og:description\" content=\"Non-Public Sports &amp; Language Nursery\u2013Preschool Wieliczka, Lednica G\u00f3rna 207 We raise children in the spirit of fair play \u2013 with movement, joy and passion Our facility is located in Lednica G\u00f3rna in a newly constructed building with a total area of approx. 500 sq m. There are playgrounds next to the facility with designated safety...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/przedszkolefairplay.info.pl\/en\/facilities\/non-public-sports-language-nursery-preschool\/\" \/>\n<meta property=\"og:site_name\" content=\"FairPlay Kindergarten\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T12:08:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/poznan-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/facilities\\\/non-public-sports-language-nursery-preschool\\\/\",\"url\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/facilities\\\/non-public-sports-language-nursery-preschool\\\/\",\"name\":\"Wieliczka Lednica G\u00f3rna 207 - FairPlay Kindergarten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/facilities\\\/non-public-sports-language-nursery-preschool\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/facilities\\\/non-public-sports-language-nursery-preschool\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/AdobeStock_320819860.webp\",\"datePublished\":\"2026-01-12T12:08:17+00:00\",\"dateModified\":\"2026-03-02T12:08:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/facilities\\\/non-public-sports-language-nursery-preschool\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/facilities\\\/non-public-sports-language-nursery-preschool\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/facilities\\\/non-public-sports-language-nursery-preschool\\\/#primaryimage\",\"url\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/AdobeStock_320819860.webp\",\"contentUrl\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/AdobeStock_320819860.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/facilities\\\/non-public-sports-language-nursery-preschool\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Non-Public Sports &amp; Language Nursery\u2013Preschool\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/#website\",\"url\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/\",\"name\":\"FairPlay Kindergarten\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/#organization\",\"name\":\"FairPlay Kindergarten\",\"url\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo-7.png\",\"contentUrl\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo-7.png\",\"width\":260,\"height\":122,\"caption\":\"FairPlay Kindergarten\"},\"image\":{\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wieliczka Lednica G\u00f3rna 207 - FairPlay Kindergarten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/przedszkolefairplay.info.pl\/en\/facilities\/non-public-sports-language-nursery-preschool\/","og_locale":"en_US","og_type":"article","og_title":"Wieliczka Lednica G\u00f3rna 207 - FairPlay Kindergarten","og_description":"Non-Public Sports &amp; Language Nursery\u2013Preschool Wieliczka, Lednica G\u00f3rna 207 We raise children in the spirit of fair play \u2013 with movement, joy and passion Our facility is located in Lednica G\u00f3rna in a newly constructed building with a total area of approx. 500 sq m. There are playgrounds next to the facility with designated safety...","og_url":"https:\/\/przedszkolefairplay.info.pl\/en\/facilities\/non-public-sports-language-nursery-preschool\/","og_site_name":"FairPlay Kindergarten","article_modified_time":"2026-03-02T12:08:02+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/poznan-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/przedszkolefairplay.info.pl\/en\/facilities\/non-public-sports-language-nursery-preschool\/","url":"https:\/\/przedszkolefairplay.info.pl\/en\/facilities\/non-public-sports-language-nursery-preschool\/","name":"Wieliczka Lednica G\u00f3rna 207 - FairPlay Kindergarten","isPartOf":{"@id":"https:\/\/przedszkolefairplay.info.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/przedszkolefairplay.info.pl\/en\/facilities\/non-public-sports-language-nursery-preschool\/#primaryimage"},"image":{"@id":"https:\/\/przedszkolefairplay.info.pl\/en\/facilities\/non-public-sports-language-nursery-preschool\/#primaryimage"},"thumbnailUrl":"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_320819860.webp","datePublished":"2026-01-12T12:08:17+00:00","dateModified":"2026-03-02T12:08:02+00:00","breadcrumb":{"@id":"https:\/\/przedszkolefairplay.info.pl\/en\/facilities\/non-public-sports-language-nursery-preschool\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/przedszkolefairplay.info.pl\/en\/facilities\/non-public-sports-language-nursery-preschool\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/przedszkolefairplay.info.pl\/en\/facilities\/non-public-sports-language-nursery-preschool\/#primaryimage","url":"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_320819860.webp","contentUrl":"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_320819860.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/przedszkolefairplay.info.pl\/en\/facilities\/non-public-sports-language-nursery-preschool\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/przedszkolefairplay.info.pl\/en\/"},{"@type":"ListItem","position":2,"name":"Non-Public Sports &amp; Language Nursery\u2013Preschool"}]},{"@type":"WebSite","@id":"https:\/\/przedszkolefairplay.info.pl\/#website","url":"https:\/\/przedszkolefairplay.info.pl\/","name":"FairPlay Kindergarten","description":"","publisher":{"@id":"https:\/\/przedszkolefairplay.info.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/przedszkolefairplay.info.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/przedszkolefairplay.info.pl\/#organization","name":"FairPlay Kindergarten","url":"https:\/\/przedszkolefairplay.info.pl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/przedszkolefairplay.info.pl\/#\/schema\/logo\/image\/","url":"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/logo-7.png","contentUrl":"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/logo-7.png","width":260,"height":122,"caption":"FairPlay Kindergarten"},"image":{"@id":"https:\/\/przedszkolefairplay.info.pl\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":{"typ_placowki":[{"value":47,"label":"Kindergarten"},{"value":45,"label":"Nursery"}],"miasto":[{"value":31,"label":"Wieliczka"}]},"featured_image_src_large":false,"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/przedszkolefairplay.info.pl\/en\/wp-json\/wp\/v2\/placowki\/12086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/przedszkolefairplay.info.pl\/en\/wp-json\/wp\/v2\/placowki"}],"about":[{"href":"https:\/\/przedszkolefairplay.info.pl\/en\/wp-json\/wp\/v2\/types\/placowki"}],"wp:attachment":[{"href":"https:\/\/przedszkolefairplay.info.pl\/en\/wp-json\/wp\/v2\/media?parent=12086"}],"wp:term":[{"taxonomy":"typ_placowki","embeddable":true,"href":"https:\/\/przedszkolefairplay.info.pl\/en\/wp-json\/wp\/v2\/typ_placowki?post=12086"},{"taxonomy":"miasto","embeddable":true,"href":"https:\/\/przedszkolefairplay.info.pl\/en\/wp-json\/wp\/v2\/miasto?post=12086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}