{"id":12441,"date":"2025-11-27T14:09:31","date_gmt":"2025-11-27T14:09:31","guid":{"rendered":"https:\/\/przedszkolefairplay.info.pl\/art-classes\/"},"modified":"2026-02-17T06:59:19","modified_gmt":"2026-02-17T06:59:19","slug":"art-classes","status":"publish","type":"page","link":"https:\/\/przedszkolefairplay.info.pl\/en\/art-classes\/","title":{"rendered":"Art classes"},"content":{"rendered":"<style>.kb-row-layout-id7266_0e7e4f-a0 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id7266_0e7e4f-a0 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id7266_0e7e4f-a0 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:140px;padding-bottom:63px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id7266_0e7e4f-a0{background-image:url('https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_366737023-Przekonwertowany-01-16.svg');background-size:cover;background-position:75% 30%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id7266_0e7e4f-a0 > .kt-row-layout-overlay{opacity:0.56;background:radial-gradient(ellipse at right top,rgba(255,255,255,0.84) undefined%,rgba(255,255,255,0) 39%);}@media all and (max-width: 1024px){.kb-row-layout-id7266_0e7e4f-a0 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id7266_0e7e4f-a0 > .kt-row-column-wrap{padding-top:140px;padding-bottom:30px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id7266_0e7e4f-a0{background-image:url('https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_366737023-Przekonwertowany-01-17.svg');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id7266_0e7e4f-a0 > .kt-row-layout-overlay{opacity:1;background:linear-gradient(0deg,var(--global-palette9) 0%,rgba(255,255,255,0.12) 23%);}}.main-navigation .primary-menu-container > ul > li.menu-item.current-menu-item > a{  background: #B78EF065;}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id7266_0e7e4f-a0 alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column7266_b900e5-ee > .kt-inside-inner-col,.kadence-column7266_b900e5-ee > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column7266_b900e5-ee > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_b900e5-ee > .kt-inside-inner-col{flex-direction:column;}.kadence-column7266_b900e5-ee > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column7266_b900e5-ee > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_b900e5-ee{position:relative;}@media all and (max-width: 1024px){.kadence-column7266_b900e5-ee > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column7266_b900e5-ee > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_b900e5-ee\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading7266_25a169-ec, .wp-block-kadence-advancedheading.kt-adv-heading7266_25a169-ec[data-kb-block=\"kb-adv-heading7266_25a169-ec\"]{line-height:1.3;font-style:normal;text-shadow:1px 1px 30px #ffffff;}.wp-block-kadence-advancedheading.kt-adv-heading7266_25a169-ec mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading7266_25a169-ec[data-kb-block=\"kb-adv-heading7266_25a169-ec\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading7266_25a169-ec img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading7266_25a169-ec[data-kb-block=\"kb-adv-heading7266_25a169-ec\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading7266_25a169-ec, .wp-block-kadence-advancedheading.kt-adv-heading7266_25a169-ec[data-kb-block=\"kb-adv-heading7266_25a169-ec\"]{text-shadow:1px 1px 30px #ffffff;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading7266_25a169-ec, .wp-block-kadence-advancedheading.kt-adv-heading7266_25a169-ec[data-kb-block=\"kb-adv-heading7266_25a169-ec\"]{text-shadow:1px 1px 30px #ffffff;}}<\/style>\n<h1 class=\"kt-adv-heading7266_25a169-ec wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading7266_25a169-ec\">Art classes<\/h1>\n\n\n<style>.kadence-column7266_de47f4-a4 > .kt-inside-inner-col{display:flex;}.kadence-column7266_de47f4-a4 > .kt-inside-inner-col,.kadence-column7266_de47f4-a4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column7266_de47f4-a4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_de47f4-a4 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column7266_de47f4-a4 > .kt-inside-inner-col > *, .kadence-column7266_de47f4-a4 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column7266_de47f4-a4 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column7266_de47f4-a4 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column7266_de47f4-a4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_de47f4-a4{position:relative;}@media all and (max-width: 1024px){.kadence-column7266_de47f4-a4 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column7266_de47f4-a4 > .kt-inside-inner-col > *, .kadence-column7266_de47f4-a4 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column7266_de47f4-a4 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column7266_de47f4-a4 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column7266_de47f4-a4 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column7266_de47f4-a4 > .kt-inside-inner-col > *, .kadence-column7266_de47f4-a4 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column7266_de47f4-a4 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column7266_de47f4-a4 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_de47f4-a4 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column7266_369eb6-8d > .kt-inside-inner-col{display:flex;}.kadence-column7266_369eb6-8d > .kt-inside-inner-col,.kadence-column7266_369eb6-8d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column7266_369eb6-8d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_369eb6-8d > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column7266_369eb6-8d > .kt-inside-inner-col > *, .kadence-column7266_369eb6-8d > .kt-inside-inner-col > figure.wp-block-image, .kadence-column7266_369eb6-8d > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column7266_369eb6-8d > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column7266_369eb6-8d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_369eb6-8d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_369eb6-8d > .kt-inside-inner-col{align-items:center;}.kadence-column7266_369eb6-8d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_369eb6-8d{position:relative;}.kadence-column7266_369eb6-8d, .kt-inside-inner-col > .kadence-column7266_369eb6-8d:not(.specificity){margin-top:10px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column7266_369eb6-8d{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_369eb6-8d{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_369eb6-8d > .kt-inside-inner-col{align-items:center;}}@media all and (max-width: 1024px){.kadence-column7266_369eb6-8d > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column7266_369eb6-8d > .kt-inside-inner-col > *, .kadence-column7266_369eb6-8d > .kt-inside-inner-col > figure.wp-block-image, .kadence-column7266_369eb6-8d > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column7266_369eb6-8d > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column7266_369eb6-8d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_369eb6-8d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_369eb6-8d > .kt-inside-inner-col{align-items:center;}.kadence-column7266_369eb6-8d > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column7266_369eb6-8d > .kt-inside-inner-col > *, .kadence-column7266_369eb6-8d > .kt-inside-inner-col > figure.wp-block-image, .kadence-column7266_369eb6-8d > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column7266_369eb6-8d > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_369eb6-8d kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns7266_933675-f2{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns7266_933675-f2 .kt-button{font-weight:normal;font-style:normal;}.kt-btns7266_933675-f2 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns7266_933675-f2 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns7266_933675-f2 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns7266_933675-f2 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns7266_933675-f2 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns7266_933675-f2 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns7266_933675-f2 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns7266_933675-f2\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn7266_ac9f7a-40.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn7266_ac9f7a-40.kb-button{padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn7266_ac9f7a-40.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn7266_ac9f7a-40.kb-button:focus{color:var(--global-palette9, #ffffff);border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn7266_ac9f7a-40.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn7266_ac9f7a-40.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn7266_ac9f7a-40.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn7266_ac9f7a-40.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn7266_ac9f7a-40 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/przedszkolefairplay.info.pl\/en\/kontakt\/\"><span class=\"kt-btn-inner-text\">Enroll your child<\/span><\/a><\/div>\n\n\n<style>.kadence-column7266_a4798b-ea > .kt-inside-inner-col{display:flex;}.kadence-column7266_a4798b-ea{max-width:45px;margin-left:auto;margin-right:auto;}.wp-block-kadence-column.kb-section-dir-horizontal:not(.kb-section-md-dir-vertical)>.kt-inside-inner-col>.kadence-column7266_a4798b-ea{-webkit-flex:0 1 45px;flex:0 1 45px;max-width:unset;margin-left:unset;margin-right:unset;}.kadence-column7266_a4798b-ea > .kt-inside-inner-col,.kadence-column7266_a4798b-ea > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column7266_a4798b-ea > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_a4798b-ea > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column7266_a4798b-ea > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column7266_a4798b-ea{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_a4798b-ea{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_a4798b-ea > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column7266_a4798b-ea > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_a4798b-ea{z-index:2;position:relative;}.kadence-column7266_a4798b-ea, .kt-inside-inner-col > .kadence-column7266_a4798b-ea:not(.specificity){margin-left:-71px;}@media all and (min-width: 1025px){.wp-block-kadence-column.kb-section-dir-horizontal>.kt-inside-inner-col>.kadence-column7266_a4798b-ea{-webkit-flex:0 1 45px;flex:0 1 45px;max-width:unset;margin-left:unset;margin-right:unset;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column7266_a4798b-ea{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_a4798b-ea{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_a4798b-ea > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column7266_a4798b-ea > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column7266_a4798b-ea{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_a4798b-ea{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_a4798b-ea > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.wp-block-kadence-column.kb-section-sm-dir-vertical:not(.kb-section-sm-dir-horizontal):not(.kb-section-sm-dir-specificity)>.kt-inside-inner-col>.kadence-column7266_a4798b-ea{max-width:45px;-webkit-flex:1;flex:1;margin-left:auto;margin-right:auto;}.kadence-column7266_a4798b-ea > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_a4798b-ea btn-icon\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons7266_57d838-b1 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons7266_57d838-b1{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons7266_57d838-b1 alignnone\"><style>.kt-svg-item-7266_f8c39f-97 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-7266_f8c39f-97 .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:0px;margin-left:-75px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-7266_f8c39f-97\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading7266_e1e88b-b3, .wp-block-kadence-advancedheading.kt-adv-heading7266_e1e88b-b3[data-kb-block=\"kb-adv-heading7266_e1e88b-b3\"]{max-width:848px;margin-left:-30px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading7266_e1e88b-b3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading7266_e1e88b-b3[data-kb-block=\"kb-adv-heading7266_e1e88b-b3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading7266_e1e88b-b3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading7266_e1e88b-b3[data-kb-block=\"kb-adv-heading7266_e1e88b-b3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading7266_e1e88b-b3, .wp-block-kadence-advancedheading.kt-adv-heading7266_e1e88b-b3[data-kb-block=\"kb-adv-heading7266_e1e88b-b3\"]{margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading7266_e1e88b-b3, .wp-block-kadence-advancedheading.kt-adv-heading7266_e1e88b-b3[data-kb-block=\"kb-adv-heading7266_e1e88b-b3\"]{margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}}<\/style>\n<p class=\"kt-adv-heading7266_e1e88b-b3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading7266_e1e88b-b3\">Creativity and expression are inseparable elements of every child\u2019s development; kindergartens with art classes become oases of creativity and imagination.<\/p>\n<\/div><\/div>\n\n\n<style>.kb-row-layout-id7266_1e0cef-f9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id7266_1e0cef-f9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id7266_1e0cef-f9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);min-height:419px;grid-template-columns:minmax(0, calc(56.1% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(43.9% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id7266_1e0cef-f9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id7266_1e0cef-f9 > .kt-row-column-wrap{padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id7266_1e0cef-f9 > .kt-row-column-wrap{row-gap:var(--global-kb-gap-none, 0rem );grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id7266_1e0cef-f9 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column7266_37920e-4d > .kt-inside-inner-col{display:flex;}.kadence-column7266_37920e-4d > .kt-inside-inner-col,.kadence-column7266_37920e-4d > .kt-inside-inner-col:before{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kadence-column7266_37920e-4d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_37920e-4d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column7266_37920e-4d > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column7266_37920e-4d{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_37920e-4d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_37920e-4d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column7266_37920e-4d > .kt-inside-inner-col{background-image:url('https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_334175078.webp');background-size:cover;background-position:69% 78%;background-attachment:scroll;background-repeat:no-repeat;}.kadence-column7266_37920e-4d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_37920e-4d{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column7266_37920e-4d{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_37920e-4d{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_37920e-4d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column7266_37920e-4d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 767px){.kadence-column7266_37920e-4d > .kt-inside-inner-col{min-height:357px;flex-direction:column;justify-content:flex-end;}.kadence-column7266_37920e-4d > .kt-inside-inner-col,.kadence-column7266_37920e-4d > .kt-inside-inner-col:before{border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kt-row-column-wrap > .kadence-column7266_37920e-4d{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_37920e-4d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_37920e-4d > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column7266_37920e-4d, .kt-inside-inner-col > .kadence-column7266_37920e-4d:not(.specificity){margin-bottom:-40px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_37920e-4d\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column7266_98dea7-b5 > .kt-inside-inner-col{display:flex;}.kadence-column7266_98dea7-b5 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column7266_98dea7-b5 > .kt-inside-inner-col{box-shadow:0px 4px 63.9px 0px var(--global-palette1, #3182CE);}.kadence-column7266_98dea7-b5 > .kt-inside-inner-col,.kadence-column7266_98dea7-b5 > .kt-inside-inner-col:before{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kadence-column7266_98dea7-b5 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-sm, 1rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_98dea7-b5 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}.kadence-column7266_98dea7-b5 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column7266_98dea7-b5 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column7266_98dea7-b5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column7266_98dea7-b5 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column7266_98dea7-b5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_98dea7-b5{position:relative;}@media all and (max-width: 1024px){.kadence-column7266_98dea7-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}@media all and (max-width: 767px){.kadence-column7266_98dea7-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_98dea7-b5\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading7266_463f51-78, .wp-block-kadence-advancedheading.kt-adv-heading7266_463f51-78[data-kb-block=\"kb-adv-heading7266_463f51-78\"]{max-width:264px;padding-top:8px;padding-right:15px;padding-bottom:8px;padding-left:15px;margin-top:-60px;margin-bottom:15px;text-align:left;font-style:normal;font-family:var( --global-heading-font-family, inherit );border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}.wp-block-kadence-advancedheading.kt-adv-heading7266_463f51-78[data-kb-block=\"kb-adv-heading7266_463f51-78\"]{display:flex;gap:0.25em;justify-content:left;align-items:center;}.wp-block-kadence-advancedheading.kt-adv-heading7266_463f51-78[data-kb-block=\"kb-adv-heading7266_463f51-78\"] .kb-adv-heading-icon svg{width:1em;height:1em;}.wp-block-kadence-advancedheading.kt-adv-heading7266_463f51-78[data-kb-block=\"kb-adv-heading7266_463f51-78\"] .kb-adv-heading-icon{padding-right:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-advancedheading.kt-adv-heading7266_463f51-78 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading7266_463f51-78[data-kb-block=\"kb-adv-heading7266_463f51-78\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading7266_463f51-78 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading7266_463f51-78[data-kb-block=\"kb-adv-heading7266_463f51-78\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style><p class=\"kt-adv-heading7266_463f51-78 wp-block-kadence-advancedheading kt-adv-heading-has-icon has-theme-palette9-color has-text-color has-theme-palette1-background-color has-background\" data-kb-block=\"kb-adv-heading7266_463f51-78\"><span class=\"kb-svg-icon-wrap kb-adv-heading-icon kb-svg-icon-fas_star-of-life kb-adv-heading-icon-side-left\"><svg viewBox=\"0 0 480 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M471.99 334.43L336.06 256l135.93-78.43c7.66-4.42 10.28-14.2 5.86-21.86l-32.02-55.43c-4.42-7.65-14.21-10.28-21.87-5.86l-135.93 78.43V16c0-8.84-7.17-16-16.01-16h-64.04c-8.84 0-16.01 7.16-16.01 16v156.86L56.04 94.43c-7.66-4.42-17.45-1.79-21.87 5.86L2.15 155.71c-4.42 7.65-1.8 17.44 5.86 21.86L143.94 256 8.01 334.43c-7.66 4.42-10.28 14.21-5.86 21.86l32.02 55.43c4.42 7.65 14.21 10.27 21.87 5.86l135.93-78.43V496c0 8.84 7.17 16 16.01 16h64.04c8.84 0 16.01-7.16 16.01-16V339.14l135.93 78.43c7.66 4.42 17.45 1.8 21.87-5.86l32.02-55.43c4.42-7.65 1.8-17.43-5.86-21.85z\"\/><\/svg><\/span><span class=\"kb-adv-text-inner\"><strong>The role of art in life<\/strong><\/span><\/p>\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box7266_1db969-ff .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box7266_1db969-ff .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:-15px;}.kt-info-box7266_1db969-ff .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box7266_1db969-ff .kt-info-svg-icon-flip, .kt-info-box7266_1db969-ff .kt-blocks-info-box-number{font-size:50px;}.kt-info-box7266_1db969-ff .kt-blocks-info-box-media{color:#8ce70c;background:#dfffb3;border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;}.kt-info-box7266_1db969-ff .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box7266_1db969-ff .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:1rem;}.kt-info-box7266_1db969-ff .kt-infobox-textcontent p.kt-blocks-info-box-title{font-size:30px;line-height:36px;font-family:var( --global-heading-font-family, inherit );font-style:normal;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box7266_1db969-ff .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box7266_1db969-ff .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box7266_1db969-ff .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box7266_1db969-ff .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box7266_1db969-ff\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\"><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-title\">Young minds need space <\/p><p class=\"kt-blocks-info-box-text\">to explore and experiment with various forms of art in order to develop their perception and self-expression skills. An educational offer that includes diverse art classes becomes the key to discovering the talents and passions of the youngest, making each day bring new inspiration and experiences. <\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id7266_2011a2-c6 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id7266_2011a2-c6 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id7266_2011a2-c6 > .kt-row-column-wrap{column-gap:84px;row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, calc(51.7% - ((84px * 1 )\/2)))minmax(0, calc(48.3% - ((84px * 1 )\/2)));}.kb-row-layout-id7266_2011a2-c6{background-image:url('https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/Frame-183-4.svg');background-size:auto;background-position:52% 98%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id7266_2011a2-c6 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id7266_2011a2-c6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id7266_2011a2-c6 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id7266_2011a2-c6 alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column7266_f3753b-3e > .kt-inside-inner-col{display:flex;}.kadence-column7266_f3753b-3e > .kt-inside-inner-col,.kadence-column7266_f3753b-3e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column7266_f3753b-3e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_f3753b-3e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column7266_f3753b-3e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column7266_f3753b-3e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_f3753b-3e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_f3753b-3e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column7266_f3753b-3e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_f3753b-3e{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column7266_f3753b-3e{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_f3753b-3e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_f3753b-3e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column7266_f3753b-3e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column7266_f3753b-3e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_f3753b-3e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_f3753b-3e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column7266_f3753b-3e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_f3753b-3e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading7266_ea21db-e0, .wp-block-kadence-advancedheading.kt-adv-heading7266_ea21db-e0[data-kb-block=\"kb-adv-heading7266_ea21db-e0\"]{line-height:1.3;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading7266_ea21db-e0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading7266_ea21db-e0[data-kb-block=\"kb-adv-heading7266_ea21db-e0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading7266_ea21db-e0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading7266_ea21db-e0[data-kb-block=\"kb-adv-heading7266_ea21db-e0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading7266_ea21db-e0 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading7266_ea21db-e0\">Kindergarten with art classes<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading7266_27e1aa-20, .wp-block-kadence-advancedheading.kt-adv-heading7266_27e1aa-20[data-kb-block=\"kb-adv-heading7266_27e1aa-20\"]{max-width:599px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading7266_27e1aa-20 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading7266_27e1aa-20[data-kb-block=\"kb-adv-heading7266_27e1aa-20\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading7266_27e1aa-20 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading7266_27e1aa-20[data-kb-block=\"kb-adv-heading7266_27e1aa-20\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading7266_27e1aa-20 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading7266_27e1aa-20\">Our kindergartens with art classes open the door for children to a world full of colors, sounds and shapes, helping them bring out their natural abilities and talents. Through art workshops, music classes or dance lessons, children not only learn important skills but also explore their own passions and interests. <\/p>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box7266_d712bf-53 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box7266_d712bf-53 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;}.kt-info-box7266_d712bf-53 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box7266_d712bf-53 .kt-info-svg-icon-flip, .kt-info-box7266_d712bf-53 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box7266_d712bf-53 .kt-blocks-info-box-media{color:var(--global-palette2, #2B6CB0);background:var(--global-palette5, #4A5568);border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:30px;margin-bottom:16px;margin-left:0px;}.kt-info-box7266_d712bf-53 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:1rem;}.kt-info-box7266_d712bf-53 .kt-infobox-textcontent h3.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box7266_d712bf-53 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box7266_d712bf-53 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box7266_d712bf-53 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box7266_d712bf-53 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);display:block;}.kt-info-box7266_d712bf-53 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box7266_d712bf-53\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-kb-custom-2560 kt-info-svg-icon\"><svg viewBox=\"0 0 54 45\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M9.59989 36.5195C8.77163 36.0588 8.12246 35.437 7.65238 34.6541C7.1823 33.8713 6.94726 32.9932 6.94726 32.0198V19.8319L1.34001 16.7312C0.878826 16.468 0.540311 16.148 0.324467 15.7711C0.108156 15.3947 0 14.9761 0 14.5154C0 14.0547 0.108156 13.6363 0.324467 13.2603C0.540311 12.8839 0.878826 12.5641 1.34001 12.301L22.7886 0.614522C23.1692 0.402893 23.5614 0.247447 23.965 0.148187C24.3686 0.0493949 24.7827 0 25.2074 0C25.632 0 26.0461 0.0493949 26.4497 0.148187C26.8533 0.247447 27.2459 0.402658 27.6275 0.613819L51.8516 13.7976C52.2838 14.0317 52.6153 14.3482 52.8461 14.7471C53.0765 15.1465 53.1916 15.5773 53.1916 16.0394V32.6139C53.1916 33.2109 52.9896 33.7114 52.5856 34.1155C52.1815 34.5191 51.681 34.7209 51.084 34.7209C50.4866 34.7209 49.9863 34.5191 49.5832 34.1155C49.1796 33.7114 48.9778 33.2109 48.9778 32.6139V16.8498L43.4674 19.8319V32.0198C43.4674 32.9932 43.2324 33.8713 42.7623 34.6541C42.2922 35.437 41.6431 36.0588 40.8148 36.5195L27.6331 43.6458C27.2478 43.8617 26.8533 44.0192 26.4497 44.1185C26.0461 44.2173 25.632 44.2667 25.2074 44.2667C24.7827 44.2667 24.3686 44.2173 23.965 44.1185C23.5614 44.0192 23.1669 43.8617 22.7816 43.6458L9.59989 36.5195ZM24.8829 24.748C25.0093 24.8201 25.1219 24.8562 25.2207 24.8562C25.32 24.8562 25.4326 24.8201 25.5585 24.748L44.424 14.5161L25.5585 4.31079C25.4326 4.23868 25.32 4.20263 25.2207 4.20263C25.1219 4.20263 25.0093 4.23868 24.8829 4.31079L5.99072 14.5161L24.8829 24.748ZM24.8562 39.9987C24.9821 40.0708 25.0992 40.1069 25.2074 40.1069C25.3155 40.1069 25.4326 40.0708 25.5585 39.9987L38.8483 32.819C38.9926 32.7291 39.096 32.6256 39.1588 32.5086C39.222 32.3915 39.2536 32.2429 39.2536 32.0626V22.0793L27.676 28.438C27.2906 28.6538 26.891 28.8114 26.4771 28.9106C26.0628 29.0099 25.6395 29.0595 25.2074 29.0595C24.7752 29.0595 24.3519 29.0099 23.9376 28.9106C23.5237 28.8114 23.1241 28.6538 22.7387 28.438L11.1611 22.0793V32.0626C11.1611 32.2068 11.1927 32.3466 11.2559 32.4819C11.3187 32.6167 11.4222 32.7291 11.5664 32.819L24.8562 39.9987Z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-text\">Many of our facilities are located in Ma\u0142opolska. Krak\u00f3w, as a city with a rich cultural tradition, provides an extremely valuable background, inspiring the youngest to think creatively and express themselves through art. Educational trips for the youngest. In a kindergarten with art classes, every child has the chance to experience a small adventure with art, engaging in various forms of expression and communication.    <\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column7266_b20ea6-e0 > .kt-inside-inner-col,.kadence-column7266_b20ea6-e0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column7266_b20ea6-e0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_b20ea6-e0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column7266_b20ea6-e0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column7266_b20ea6-e0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_b20ea6-e0{position:relative;}@media all and (max-width: 1024px){.kadence-column7266_b20ea6-e0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column7266_b20ea6-e0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_b20ea6-e0\"><div class=\"kt-inside-inner-col\"><style>.kadence-column7266_47131c-72 > .kt-inside-inner-col{padding-right:10px;}.kadence-column7266_47131c-72 > .kt-inside-inner-col,.kadence-column7266_47131c-72 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column7266_47131c-72 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_47131c-72 > .kt-inside-inner-col{flex-direction:column;}.kadence-column7266_47131c-72 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column7266_47131c-72 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_47131c-72{position:relative;}@media all and (max-width: 1024px){.kadence-column7266_47131c-72 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column7266_47131c-72 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_47131c-72 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id7266_e8b4a6-5c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id7266_e8b4a6-5c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id7266_e8b4a6-5c > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id7266_e8b4a6-5c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id7266_e8b4a6-5c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id7266_e8b4a6-5c > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xxs, 0.5rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id7266_e8b4a6-5c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column7266_8bdc9a-2a > .kt-inside-inner-col,.kadence-column7266_8bdc9a-2a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column7266_8bdc9a-2a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_8bdc9a-2a > .kt-inside-inner-col{flex-direction:column;}.kadence-column7266_8bdc9a-2a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column7266_8bdc9a-2a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_8bdc9a-2a{position:relative;}@media all and (max-width: 1024px){.kadence-column7266_8bdc9a-2a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column7266_8bdc9a-2a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_8bdc9a-2a inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-image7266_8a8f99-83 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image7266_8a8f99-83 img.kb-img, .kb-image7266_8a8f99-83 .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image7266_8a8f99-83 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" width=\"910\" height=\"607\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_91745108.webp\" alt=\"\" class=\"kb-img wp-image-9175\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_91745108.webp 910w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_91745108-300x200.webp 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_91745108-768x512.webp 768w\" sizes=\"auto, (max-width: 910px) 100vw, 910px\" \/><\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column7266_1e53bc-25 > .kt-inside-inner-col,.kadence-column7266_1e53bc-25 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column7266_1e53bc-25 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_1e53bc-25 > .kt-inside-inner-col{flex-direction:column;}.kadence-column7266_1e53bc-25 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column7266_1e53bc-25 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_1e53bc-25{position:relative;}@media all and (max-width: 1024px){.kadence-column7266_1e53bc-25 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column7266_1e53bc-25 > .kt-inside-inner-col{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_1e53bc-25 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-image7266_1056e0-3d .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image7266_1056e0-3d img.kb-img, .kb-image7266_1056e0-3d .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;object-position:38% 91%;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image7266_1056e0-3d kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-port23\"><img loading=\"lazy\" decoding=\"async\" width=\"910\" height=\"1364\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_299580831.webp\" alt=\"\" class=\"kb-img wp-image-9173\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_299580831.webp 910w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_299580831-200x300.webp 200w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_299580831-683x1024.webp 683w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_299580831-768x1151.webp 768w\" sizes=\"auto, (max-width: 910px) 100vw, 910px\" \/><\/div><\/figure>\n\n\n<style>.kadence-column7266_2d7ef7-05 > .kt-inside-inner-col{padding-top:40px;padding-right:50px;padding-bottom:40px;padding-left:50px;}.kadence-column7266_2d7ef7-05 > .kt-inside-inner-col{box-shadow:0px 0px 60px 5px rgba(0, 0, 0, 0.2);}.kadence-column7266_2d7ef7-05 > .kt-inside-inner-col,.kadence-column7266_2d7ef7-05 > .kt-inside-inner-col:before{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kadence-column7266_2d7ef7-05 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_2d7ef7-05 > .kt-inside-inner-col{flex-direction:column;}.kadence-column7266_2d7ef7-05 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column7266_2d7ef7-05 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column7266_2d7ef7-05 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_2d7ef7-05{z-index:4;position:relative;}.kadence-column7266_2d7ef7-05, .kt-inside-inner-col > .kadence-column7266_2d7ef7-05:not(.specificity){margin-top:-150px;margin-right:0px;margin-left:-370px;}@media all and (max-width: 1024px){.kadence-column7266_2d7ef7-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column7266_2d7ef7-05, .kt-inside-inner-col > .kadence-column7266_2d7ef7-05:not(.specificity){margin-right:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column7266_2d7ef7-05 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);flex-direction:column;justify-content:center;}.kadence-column7266_2d7ef7-05, .kt-inside-inner-col > .kadence-column7266_2d7ef7-05:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);margin-right:0px;margin-left:0px;}}@media (min-width:1024px) and (max-width:1265px) {  .kadence-column7266_2d7ef7-05 {    margin-left:-250px !important;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_2d7ef7-05\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading7266_fb3702-fd, .wp-block-kadence-advancedheading.kt-adv-heading7266_fb3702-fd[data-kb-block=\"kb-adv-heading7266_fb3702-fd\"]{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom:0px;font-size:23px;line-height:35px;font-style:normal;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.wp-block-kadence-advancedheading.kt-adv-heading7266_fb3702-fd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading7266_fb3702-fd[data-kb-block=\"kb-adv-heading7266_fb3702-fd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading7266_fb3702-fd img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading7266_fb3702-fd[data-kb-block=\"kb-adv-heading7266_fb3702-fd\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading7266_fb3702-fd, .wp-block-kadence-advancedheading.kt-adv-heading7266_fb3702-fd[data-kb-block=\"kb-adv-heading7266_fb3702-fd\"]{margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;text-align:center!important;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading7266_fb3702-fd, .wp-block-kadence-advancedheading.kt-adv-heading7266_fb3702-fd[data-kb-block=\"kb-adv-heading7266_fb3702-fd\"]{margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:18px;line-height:28px;text-align:left!important;}}<\/style>\n<p class=\"kt-adv-heading7266_fb3702-fd wp-block-kadence-advancedheading has-theme-palette-9-background-color has-background\" data-kb-block=\"kb-adv-heading7266_fb3702-fd\">From drawing, through dance, to small musical performances \u2013 children have the opportunity to discover and develop their skills, while learning values such as cooperation, support and mutual inspiration. Children also have the chance to participate in unique events such as theatre performances, educational trips or themed workshops. <\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id7266_9f9034-8f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id7266_9f9034-8f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id7266_9f9034-8f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id7266_9f9034-8f{background-image:url('https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/Frame-183-3.svg');background-size:auto;background-position:50% 74%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id7266_9f9034-8f > .kt-row-layout-overlay{opacity:1;background:linear-gradient(180deg,var(--global-palette9) 0%,rgba(255,255,255,0) 12%,rgba(255,255,255,0) 88%,var(--global-palette9) 100%);}@media all and (max-width: 1024px){.kb-row-layout-id7266_9f9034-8f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id7266_9f9034-8f > .kt-row-column-wrap{padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id7266_9f9034-8f alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column7266_8854b4-a0 > .kt-inside-inner-col,.kadence-column7266_8854b4-a0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column7266_8854b4-a0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_8854b4-a0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column7266_8854b4-a0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column7266_8854b4-a0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_8854b4-a0{position:relative;}@media all and (max-width: 1024px){.kadence-column7266_8854b4-a0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column7266_8854b4-a0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_8854b4-a0\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, calc(35% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(65% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id7266_b9ec13-9c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}}@media all and (max-width: 1024px){.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}}@media all and (max-width: 1024px){.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}}@media all and (max-width: 1024px){.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}}@media all and (max-width: 1024px){.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}}@media all and (max-width: 1024px){.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}}@media all and (max-width: 1024px){.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}}@media all and (max-width: 1024px){.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}@media all and (max-width: 767px){.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(1 of *:not(style)){order:2;}.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(2 of *:not(style)){order:1;}.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(3 of *:not(style)){order:12;}.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(4 of *:not(style)){order:11;}.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(5 of *:not(style)){order:22;}.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(6 of *:not(style)){order:21;}.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(7 of *:not(style)){order:32;}.kb-row-layout-id7266_b9ec13-9c > .kt-row-column-wrap > .wp-block-kadence-column:nth-child(8 of *:not(style)){order:31;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id7266_b9ec13-9c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column7266_52d7d1-e1 > .kt-inside-inner-col,.kadence-column7266_52d7d1-e1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column7266_52d7d1-e1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_52d7d1-e1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column7266_52d7d1-e1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column7266_52d7d1-e1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_52d7d1-e1{position:relative;}@media all and (max-width: 1024px){.kadence-column7266_52d7d1-e1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column7266_52d7d1-e1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_52d7d1-e1 container-image\"><div class=\"kt-inside-inner-col\"><style>.kb-image7266_56c63b-e2 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kb-image7266_56c63b-e2 img.kb-img, .kb-image7266_56c63b-e2 .kb-img img{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image7266_56c63b-e2\"><img loading=\"lazy\" decoding=\"async\" width=\"910\" height=\"607\" src=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_257163137.webp\" alt=\"\" class=\"kb-img wp-image-9174\" title=\"container-image\" srcset=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_257163137.webp 910w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_257163137-300x200.webp 300w, https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_257163137-768x512.webp 768w\" sizes=\"auto, (max-width: 910px) 100vw, 910px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column7266_47ec45-b5 > .kt-inside-inner-col{display:flex;}.kadence-column7266_47ec45-b5 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);}.kadence-column7266_47ec45-b5 > .kt-inside-inner-col,.kadence-column7266_47ec45-b5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column7266_47ec45-b5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_47ec45-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column7266_47ec45-b5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column7266_47ec45-b5{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_47ec45-b5{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_47ec45-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column7266_47ec45-b5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_47ec45-b5{z-index:5;position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column7266_47ec45-b5{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_47ec45-b5{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_47ec45-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column7266_47ec45-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column7266_47ec45-b5 > .kt-inside-inner-col{padding-bottom:0px;flex-direction:column;justify-content:center;}.kt-row-column-wrap > .kadence-column7266_47ec45-b5{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_47ec45-b5{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_47ec45-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}.kadence-column7266_47ec45-b5 button.splide__arrow.splide__arrow--prev.slick-prev {\r    background: white;\r    color: black;\r    opacity: 100 !important;\r    width: 47px;\r    border-radius: 101px;\r        box-shadow: 0px 4px 22.9px 0px rgba(0, 0, 0, 0.12);\r}\r.kadence-column7266_47ec45-b5 button.splide__arrow.splide__arrow--next.slick-next {\r    background: white;\r    color: black;\r    opacity: 100 !important;\r    width: 47px;\r    border-radius: 101px;\r        box-shadow: 0px 4px 22.9px 0px rgba(0, 0, 0, 0.12);\r}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_47ec45-b5\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading7266_f251f6-9b, .wp-block-kadence-advancedheading.kt-adv-heading7266_f251f6-9b[data-kb-block=\"kb-adv-heading7266_f251f6-9b\"]{text-align:left;line-height:1.3;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading7266_f251f6-9b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading7266_f251f6-9b[data-kb-block=\"kb-adv-heading7266_f251f6-9b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading7266_f251f6-9b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading7266_f251f6-9b[data-kb-block=\"kb-adv-heading7266_f251f6-9b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading7266_f251f6-9b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading7266_f251f6-9b\">A little one on the path of artistic development<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading7266_b8ce58-29, .wp-block-kadence-advancedheading.kt-adv-heading7266_b8ce58-29[data-kb-block=\"kb-adv-heading7266_b8ce58-29\"]{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading7266_b8ce58-29 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading7266_b8ce58-29[data-kb-block=\"kb-adv-heading7266_b8ce58-29\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading7266_b8ce58-29 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading7266_b8ce58-29[data-kb-block=\"kb-adv-heading7266_b8ce58-29\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading7266_b8ce58-29 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading7266_b8ce58-29\">Nurseries and kindergartens with art classes are places where even the youngest explorers can step onto the path of creative development. Classes such as rhythmics or simple art workshops are adapted to the age and abilities of little ones, providing not only joy but also stimulating their motor and emotional development.  <\/p>\n\n\n<style>.kt-info-box7266_ba5161-10{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box7266_ba5161-10{height:auto;align-self:stretch;}.kt-info-box7266_ba5161-10 .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box7266_ba5161-10 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box7266_ba5161-10 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);margin-right:var(--global-kb-spacing-xl, 4rem);}.kt-info-box7266_ba5161-10 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box7266_ba5161-10 .kt-info-svg-icon-flip, .kt-info-box7266_ba5161-10 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box7266_ba5161-10 .kt-blocks-info-box-media{color:var(--global-palette1, #3182CE);background:var(--global-palette6, #718096);border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:13px;margin-right:30px;margin-bottom:16px;margin-left:0px;}.kt-info-box7266_ba5161-10 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:1rem;}.kt-info-box7266_ba5161-10 .kt-infobox-textcontent h3.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box7266_ba5161-10 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box7266_ba5161-10 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box7266_ba5161-10 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box7266_ba5161-10 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-right:0px;display:block;}.kt-info-box7266_ba5161-10 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-media{display:inline-block;max-width:100%;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box7266_ba5161-10\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-kb-custom-2641 kt-info-svg-icon\"><svg viewBox=\"0 0 35 36\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M12.8578 35.0836C11.2298 35.0836 9.82973 34.5198 8.65764 33.3922C7.48556 32.2647 6.84074 30.8972 6.72319 29.2899C4.85465 29.0052 3.29968 28.1508 2.05829 26.7266C0.816893 25.3021 0.196197 23.6322 0.196197 21.7167C0.196197 21.0478 0.283169 20.3868 0.457114 19.7339C0.630719 19.0809 0.891295 18.4678 1.23884 17.8947C0.826066 17.2961 0.516398 16.6487 0.309839 15.9526C0.10328 15.2562 0 14.525 0 13.7593C0 11.8038 0.643628 10.1127 1.93089 8.68618C3.2178 7.25963 4.81133 6.43 6.71147 6.19728C6.69822 6.14496 6.6916 6.09264 6.6916 6.04032V5.864C6.75445 4.22274 7.38228 2.83509 8.57509 1.70105C9.76824 0.567018 11.1958 0 12.8578 0C13.7934 0 14.6271 0.182945 15.3589 0.54884C16.0907 0.914395 16.7858 1.43181 17.4442 2.10109C18.0948 1.43181 18.7848 0.914395 19.5142 0.54884C20.2433 0.182945 21.0821 0 22.0306 0C23.6743 0 25.0888 0.56498 26.2741 1.69494C27.4591 2.82524 28.083 4.20456 28.1459 5.83291V6.00924C28.1459 6.06156 28.1393 6.11388 28.126 6.1662C30.0261 6.39857 31.6282 7.23024 32.9321 8.66121C34.2363 10.0918 34.8884 11.7912 34.8884 13.7593C34.8884 14.525 34.7819 15.2562 34.5689 15.9526C34.3559 16.6487 34.0428 17.2961 33.6297 17.8947C33.9773 18.4672 34.2412 19.0799 34.4216 19.7328C34.602 20.3862 34.6922 21.0475 34.6922 21.7167C34.6922 23.6661 34.0663 25.3478 32.8143 26.7618C31.5628 28.1754 29.9961 29.0181 28.1143 29.2899C27.9967 30.8972 27.3604 32.2647 26.2053 33.3922C25.0502 34.5198 23.6587 35.0836 22.0306 35.0836C21.0899 35.0836 20.253 34.9059 19.5198 34.5506C18.7867 34.1952 18.0948 33.6764 17.4442 32.9942C16.7726 33.6764 16.0722 34.1952 15.3431 34.5506C14.6141 34.9059 13.7856 35.0836 12.8578 35.0836ZM18.973 6.11523V28.9689C18.973 29.825 19.2694 30.5487 19.8623 31.1398C20.4551 31.7309 21.1806 32.0265 22.0388 32.0265C22.8565 32.0265 23.5574 31.7219 24.1414 31.1128C24.7258 30.504 25.0414 29.7944 25.0883 28.9842C24.2311 28.8041 23.4399 28.4781 22.7145 28.0062C21.9895 27.5347 21.3631 26.9303 20.8351 26.1931C20.5739 25.8353 20.4753 25.4543 20.5395 25.05C20.6038 24.6458 20.8159 24.3174 21.176 24.065C21.5341 23.8034 21.9177 23.7049 22.3267 23.7694C22.7361 23.8336 23.0685 24.0458 23.324 24.4059C23.7456 25.0191 24.2822 25.4886 24.9338 25.8144C25.5855 26.1403 26.2902 26.3032 27.0482 26.3032C28.3263 26.3032 29.4102 25.8583 30.3 24.9685C31.1897 24.0784 31.6346 22.9945 31.6346 21.7167C31.6346 21.4595 31.6098 21.2025 31.5602 20.9457C31.5106 20.6889 31.4321 20.4363 31.3248 20.1879C30.7472 20.58 30.1102 20.8805 29.4138 21.0894C28.7173 21.2983 27.9942 21.4028 27.2444 21.4028C26.8112 21.4028 26.4481 21.2564 26.1549 20.9635C25.862 20.6703 25.7156 20.307 25.7156 19.8735C25.7156 19.4403 25.862 19.0773 26.1549 18.7845C26.4481 18.492 26.8112 18.3457 27.2444 18.3457C28.5221 18.3457 29.6061 17.9007 30.4962 17.0105C31.3859 16.1208 31.8308 15.037 31.8308 13.7593C31.8308 12.5016 31.3924 11.4345 30.5155 10.558C29.6387 9.68144 28.5745 9.21957 27.3229 9.17234C26.975 9.79712 26.5168 10.3421 25.9485 10.8071C25.3801 11.2722 24.7458 11.6407 24.0456 11.9125C23.6457 12.064 23.2554 12.0514 22.8745 11.8748C22.4937 11.6981 22.2399 11.4076 22.1132 11.0033C21.9824 10.6035 21.998 10.2107 22.1601 9.82514C22.3221 9.43988 22.6096 9.18186 23.0223 9.05106C23.6366 8.84212 24.1345 8.47096 24.516 7.93758C24.8975 7.40453 25.0883 6.79369 25.0883 6.10504C25.0883 5.25434 24.7925 4.53377 24.201 3.94331C23.6099 3.35251 22.8861 3.05711 22.0296 3.05711C21.1732 3.05711 20.4495 3.35268 19.8587 3.94382C19.2683 4.53496 18.973 5.25876 18.973 6.11523ZM15.9154 28.9689V6.11523C15.9154 5.25876 15.6197 4.53496 15.0282 3.94382C14.4371 3.35268 13.7132 3.05711 12.8568 3.05711C12.0003 3.05711 11.2767 3.35268 10.6859 3.94382C10.0954 4.53496 9.80017 5.25876 9.80017 6.11523C9.80017 6.77636 9.98567 7.37871 10.3567 7.92229C10.728 8.46586 11.2206 8.84212 11.8345 9.05106C12.2344 9.18186 12.5271 9.43666 12.7126 9.81546C12.898 10.1943 12.9266 10.5851 12.7982 10.9881C12.6443 11.3906 12.3747 11.6799 11.9894 11.8559C11.6042 12.0322 11.205 12.0446 10.7919 11.8931C10.0917 11.6213 9.45738 11.2561 8.889 10.7975C8.32063 10.3388 7.86249 9.79712 7.5146 9.17234C6.29699 9.21957 5.24976 9.68806 4.3729 10.5778C3.49605 11.4676 3.05762 12.5301 3.05762 13.7654C3.05762 15.0391 3.5025 16.1208 4.39227 17.0105C5.28237 17.9007 6.3663 18.3457 7.64404 18.3457C8.07721 18.3457 8.44038 18.4921 8.73357 18.785C9.02643 19.0782 9.17285 19.4415 9.17285 19.875C9.17285 20.3082 9.02643 20.6712 8.73357 20.964C8.44038 21.2566 8.07721 21.4028 7.64404 21.4028C6.89425 21.4028 6.17112 21.2983 5.47466 21.0894C4.77821 20.8805 4.1412 20.58 3.56365 20.1879C3.4563 20.4363 3.37782 20.6889 3.32822 20.9457C3.27862 21.2025 3.25381 21.4595 3.25381 21.7167C3.25381 22.9945 3.6987 24.0784 4.58846 24.9685C5.47823 25.8583 6.56216 26.3032 7.84024 26.3032C8.60193 26.3032 9.30654 26.1392 9.95407 25.8114C10.6016 25.4832 11.1384 25.0147 11.5644 24.4059C11.8199 24.0458 12.1523 23.8336 12.5617 23.7694C12.9708 23.7049 13.3543 23.8 13.7124 24.0548C14.0705 24.3096 14.2821 24.6401 14.3474 25.0465C14.4126 25.4531 14.3146 25.8353 14.0533 26.1931C13.5125 26.9303 12.8741 27.54 12.1382 28.022C11.4027 28.5041 10.6064 28.8354 9.74921 29.0158C9.7961 29.826 10.1202 30.5303 10.7215 31.1286C11.3225 31.7272 12.0319 32.0265 12.8496 32.0265C13.7078 32.0265 14.4333 31.7309 15.0262 31.1398C15.619 30.5487 15.9154 29.825 15.9154 28.9689Z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">With holistic development in mind<\/h3><p class=\"kt-blocks-info-box-text\">the nurseries and kindergartens with art classes we run provide diverse experiences that entertain, educate and inspire, all in an atmosphere of safety and care.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id7266_f53df4-77 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id7266_f53df4-77 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id7266_f53df4-77 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1390px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id7266_f53df4-77{background-image:url('https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/Frame-182-2.png');background-size:auto;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id7266_f53df4-77 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id7266_f53df4-77 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id7266_f53df4-77 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id7266_f53df4-77 alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column7266_f30abf-83 > .kt-inside-inner-col,.kadence-column7266_f30abf-83 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column7266_f30abf-83 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_f30abf-83 > .kt-inside-inner-col{flex-direction:column;}.kadence-column7266_f30abf-83 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column7266_f30abf-83 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_f30abf-83{position:relative;}@media all and (max-width: 1024px){.kadence-column7266_f30abf-83 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column7266_f30abf-83 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_f30abf-83\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading7266_e7b42c-1a, .wp-block-kadence-advancedheading.kt-adv-heading7266_e7b42c-1a[data-kb-block=\"kb-adv-heading7266_e7b42c-1a\"]{max-width:931px;margin-right:auto;margin-left:auto;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading7266_e7b42c-1a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading7266_e7b42c-1a[data-kb-block=\"kb-adv-heading7266_e7b42c-1a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading7266_e7b42c-1a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading7266_e7b42c-1a[data-kb-block=\"kb-adv-heading7266_e7b42c-1a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading7266_e7b42c-1a, .wp-block-kadence-advancedheading.kt-adv-heading7266_e7b42c-1a[data-kb-block=\"kb-adv-heading7266_e7b42c-1a\"]{text-align:left!important;}}<\/style>\n<h2 class=\"kt-adv-heading7266_e7b42c-1a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading7266_e7b42c-1a\">Nurseries and kindergartens with engaging art classes<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading7266_79c0ad-4c, .wp-block-kadence-advancedheading.kt-adv-heading7266_79c0ad-4c[data-kb-block=\"kb-adv-heading7266_79c0ad-4c\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading7266_79c0ad-4c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading7266_79c0ad-4c[data-kb-block=\"kb-adv-heading7266_79c0ad-4c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading7266_79c0ad-4c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading7266_79c0ad-4c[data-kb-block=\"kb-adv-heading7266_79c0ad-4c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading7266_79c0ad-4c, .wp-block-kadence-advancedheading.kt-adv-heading7266_79c0ad-4c[data-kb-block=\"kb-adv-heading7266_79c0ad-4c\"]{text-align:left!important;}}<\/style>\n<p class=\"kt-adv-heading7266_79c0ad-4c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading7266_79c0ad-4c\">In these places, young children have the opportunity to encounter various forms of artistic expression while learning fundamental values and skills that will serve them throughout their lives<\/p>\n\n\n<style>.kb-row-layout-id7266_594787-e3 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id7266_594787-e3 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id7266_594787-e3 > .kt-row-column-wrap{column-gap:30px;row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(35% - ((30px * 1 )\/2)))minmax(0, calc(65% - ((30px * 1 )\/2)));}.kb-row-layout-id7266_594787-e3 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id7266_594787-e3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id7266_594787-e3 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xxs, 0.5rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id7266_594787-e3 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column7266_357583-e0 > .kt-inside-inner-col{display:flex;}.kadence-column7266_357583-e0 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column7266_357583-e0 > .kt-inside-inner-col{box-shadow:0px 4px 63.9px 0px rgba(0, 0, 0, 0.25);}.kadence-column7266_357583-e0 > .kt-inside-inner-col,.kadence-column7266_357583-e0 > .kt-inside-inner-col:before{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kadence-column7266_357583-e0 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-sm, 1rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_357583-e0 > .kt-inside-inner-col{flex-direction:column;align-items:flex-start;}.kadence-column7266_357583-e0 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column7266_357583-e0 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column7266_357583-e0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column7266_357583-e0 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column7266_357583-e0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_357583-e0{position:relative;}@media all and (max-width: 1024px){.kadence-column7266_357583-e0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}@media all and (max-width: 767px){.kadence-column7266_357583-e0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_357583-e0\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box7266_283af9-d0 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box7266_283af9-d0 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:rgba(255,255,255,0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;}.kt-info-box7266_283af9-d0 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box7266_283af9-d0 .kt-info-svg-icon-flip, .kt-info-box7266_283af9-d0 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box7266_283af9-d0 .kt-blocks-info-box-media{color:#8ce70c;background:#dfffb3;border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;}.kt-info-box7266_283af9-d0 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box7266_283af9-d0 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:1rem;}.kt-info-box7266_283af9-d0 .kt-infobox-textcontent h3.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box7266_283af9-d0 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box7266_283af9-d0 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box7266_283af9-d0 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box7266_283af9-d0 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box7266_283af9-d0\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_music kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M9 17H5a2 2 0 0 0-2 2 2 2 0 0 0 2 2h2a2 2 0 0 0 2-2zm12-2h-4a2 2 0 0 0-2 2 2 2 0 0 0 2 2h2a2 2 0 0 0 2-2z\"\/><polyline points=\"9 17 9 5 21 3 21 15\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong> Participation in music therapy<\/strong><\/h3><p class=\"kt-blocks-info-box-text\">or movement classes introduces them to the world of art and creativity in an accessible and engaging way. <\/p><\/div><\/span><\/div>\n\n\n<style>.kadence-column7266_194407-03 > .kt-inside-inner-col{display:flex;}.kadence-column7266_194407-03 > .kt-inside-inner-col,.kadence-column7266_194407-03 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column7266_194407-03 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_194407-03 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column7266_194407-03 > .kt-inside-inner-col > *, .kadence-column7266_194407-03 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column7266_194407-03 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column7266_194407-03 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column7266_194407-03 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_194407-03{position:relative;}.kadence-column7266_194407-03, .kt-inside-inner-col > .kadence-column7266_194407-03:not(.specificity){margin-top:10px;}@media all and (max-width: 1024px){.kadence-column7266_194407-03 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column7266_194407-03 > .kt-inside-inner-col > *, .kadence-column7266_194407-03 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column7266_194407-03 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column7266_194407-03 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column7266_194407-03 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column7266_194407-03 > .kt-inside-inner-col > *, .kadence-column7266_194407-03 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column7266_194407-03 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column7266_194407-03 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_194407-03 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kt-btns7266_107b9e-17, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns7266_107b9e-17, .wp-block-kadence-advancedbtn.kb-btns7266_107b9e-17, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns7266_107b9e-17{margin-right:-80px;}.wp-block-kadence-advancedbtn.kb-btns7266_107b9e-17{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns7266_107b9e-17 .kt-button{font-weight:normal;font-style:normal;}.kt-btns7266_107b9e-17 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns7266_107b9e-17 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns7266_107b9e-17 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns7266_107b9e-17 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns7266_107b9e-17 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns7266_107b9e-17 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns7266_107b9e-17 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns7266_107b9e-17\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn7266_de04ab-b3.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn7266_de04ab-b3.kb-button{padding-right:74px;}.wp-block-kadence-advancedbtn .kb-btn7266_de04ab-b3.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn7266_de04ab-b3.kb-button:focus{color:var(--global-palette9, #ffffff);border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn7266_de04ab-b3.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn7266_de04ab-b3.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn7266_de04ab-b3.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn7266_de04ab-b3.kb-button:focus{border-top-color:#800020;border-top-style:solid;border-right-color:#800020;border-right-style:solid;border-bottom-color:#800020;border-bottom-style:solid;border-left-color:#800020;border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn7266_de04ab-b3 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/przedszkolefairplay.info.pl\/en\/kontakt\/\"><span class=\"kt-btn-inner-text\">Enroll your child<\/span><\/a><\/div>\n\n\n<style>.kadence-column7266_f5e305-40 > .kt-inside-inner-col{display:flex;}.kadence-column7266_f5e305-40{max-width:45px;margin-left:auto;margin-right:auto;}.wp-block-kadence-column.kb-section-dir-horizontal:not(.kb-section-md-dir-vertical)>.kt-inside-inner-col>.kadence-column7266_f5e305-40{-webkit-flex:0 1 45px;flex:0 1 45px;max-width:unset;margin-left:unset;margin-right:unset;}.kadence-column7266_f5e305-40 > .kt-inside-inner-col,.kadence-column7266_f5e305-40 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column7266_f5e305-40 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_f5e305-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column7266_f5e305-40 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column7266_f5e305-40{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_f5e305-40{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_f5e305-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column7266_f5e305-40 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_f5e305-40{z-index:2;position:relative;}.kadence-column7266_f5e305-40, .kt-inside-inner-col > .kadence-column7266_f5e305-40:not(.specificity){margin-left:-71px;}@media all and (min-width: 1025px){.wp-block-kadence-column.kb-section-dir-horizontal>.kt-inside-inner-col>.kadence-column7266_f5e305-40{-webkit-flex:0 1 45px;flex:0 1 45px;max-width:unset;margin-left:unset;margin-right:unset;}}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column7266_f5e305-40{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_f5e305-40{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_f5e305-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column7266_f5e305-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column7266_f5e305-40{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_f5e305-40{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_f5e305-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.wp-block-kadence-column.kb-section-sm-dir-vertical:not(.kb-section-sm-dir-horizontal):not(.kb-section-sm-dir-specificity)>.kt-inside-inner-col>.kadence-column7266_f5e305-40{max-width:45px;-webkit-flex:1;flex:1;margin-left:auto;margin-right:auto;}.kadence-column7266_f5e305-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_f5e305-40 btn-icon\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons7266_1d7179-94 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons7266_1d7179-94{justify-content:flex-start;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons7266_1d7179-94 alignnone\"><style>.kt-svg-item-7266_76ba2d-00 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-7266_76ba2d-00 .kb-svg-icon-wrap{color:var(--global-palette3, #1A202C);font-size:25px;margin-top:0px;background:var(--global-palette9, #ffffff);border-width:0px;border-radius:50%;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-stacked kt-svg-icon-wrap kt-svg-item-7266_76ba2d-00\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column7266_5d7600-cb > .kt-inside-inner-col{display:flex;}.kadence-column7266_5d7600-cb > .kt-inside-inner-col{box-shadow:0px 4px 63.9px 0px rgba(0, 0, 0, 0.25);}.kadence-column7266_5d7600-cb > .kt-inside-inner-col,.kadence-column7266_5d7600-cb > .kt-inside-inner-col:before{border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;}.kadence-column7266_5d7600-cb > .kt-inside-inner-col{row-gap:var(--global-kb-gap-sm, 1rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column7266_5d7600-cb > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;align-items:center;}.kadence-column7266_5d7600-cb > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column7266_5d7600-cb > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column7266_5d7600-cb > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column7266_5d7600-cb{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_5d7600-cb{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_5d7600-cb > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column7266_5d7600-cb > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);background-image:url('https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_779461891-1.webp');background-size:cover;background-position:4% 37%;background-attachment:scroll;background-repeat:no-repeat;}.kadence-column7266_5d7600-cb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column7266_5d7600-cb{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column7266_5d7600-cb{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_5d7600-cb{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_5d7600-cb > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}}@media all and (max-width: 1024px){.kadence-column7266_5d7600-cb > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column7266_5d7600-cb{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_5d7600-cb{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column7266_5d7600-cb > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;}.kadence-column7266_5d7600-cb > .kt-inside-inner-col{flex-direction:column;justify-content:flex-end;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column7266_5d7600-cb kb-section-has-overlay\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box7266_c99ae2-5e .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box7266_c99ae2-5e .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:50px;border-top-right-radius:50px;border-bottom-right-radius:50px;border-bottom-left-radius:50px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);margin-top:var(--global-kb-spacing-xs, 1rem);margin-right:var(--global-kb-spacing-xs, 1rem);margin-bottom:var(--global-kb-spacing-xs, 1rem);margin-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box7266_c99ae2-5e .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box7266_c99ae2-5e .kt-info-svg-icon-flip, .kt-info-box7266_c99ae2-5e .kt-blocks-info-box-number{font-size:50px;}.kt-info-box7266_c99ae2-5e .kt-blocks-info-box-media{color:#8ce70c;background:#dfffb3;border-color:var(--global-palette7, #eeeeee);border-radius:1rem;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;}.kt-info-box7266_c99ae2-5e .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box7266_c99ae2-5e .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:1rem;}.kt-info-box7266_c99ae2-5e .kt-infobox-textcontent h3.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box7266_c99ae2-5e .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box7266_c99ae2-5e .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box7266_c99ae2-5e .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}@media all and (max-width: 767px){.kt-info-box7266_c99ae2-5e .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box7266_c99ae2-5e\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\"><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-text\">In our nurseries and kindergartens with art classes, your little one will take their first steps into the world of art.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Art classes Creativity and expression are inseparable elements of every child\u2019s development; kindergartens with art classes become oases of creativity and imagination. The role of art in life Kindergarten with art classes Our kindergartens with art classes open the door for children to a world full of colors, sounds and shapes, helping them bring out&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-12441","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Art classes - FairPlay Kindergarten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/przedszkolefairplay.info.pl\/en\/art-classes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Art classes - FairPlay Kindergarten\" \/>\n<meta property=\"og:description\" content=\"Art classes Creativity and expression are inseparable elements of every child\u2019s development; kindergartens with art classes become oases of creativity and imagination. The role of art in life Kindergarten with art classes Our kindergartens with art classes open the door for children to a world full of colors, sounds and shapes, helping them bring out...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/przedszkolefairplay.info.pl\/en\/art-classes\/\" \/>\n<meta property=\"og:site_name\" content=\"FairPlay Kindergarten\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-17T06:59:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_91745108.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"910\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/art-classes\\\/\",\"url\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/art-classes\\\/\",\"name\":\"Art classes - FairPlay Kindergarten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/art-classes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/art-classes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/AdobeStock_91745108.webp\",\"datePublished\":\"2025-11-27T14:09:31+00:00\",\"dateModified\":\"2026-02-17T06:59:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/art-classes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/art-classes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/art-classes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/AdobeStock_91745108.webp\",\"contentUrl\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/AdobeStock_91745108.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/art-classes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Art classes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/#website\",\"url\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/\",\"name\":\"FairPlay Kindergarten\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/#organization\",\"name\":\"FairPlay Kindergarten\",\"url\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo-7.png\",\"contentUrl\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo-7.png\",\"width\":260,\"height\":122,\"caption\":\"FairPlay Kindergarten\"},\"image\":{\"@id\":\"https:\\\/\\\/przedszkolefairplay.info.pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Art classes - FairPlay Kindergarten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/przedszkolefairplay.info.pl\/en\/art-classes\/","og_locale":"en_US","og_type":"article","og_title":"Art classes - FairPlay Kindergarten","og_description":"Art classes Creativity and expression are inseparable elements of every child\u2019s development; kindergartens with art classes become oases of creativity and imagination. The role of art in life Kindergarten with art classes Our kindergartens with art classes open the door for children to a world full of colors, sounds and shapes, helping them bring out...","og_url":"https:\/\/przedszkolefairplay.info.pl\/en\/art-classes\/","og_site_name":"FairPlay Kindergarten","article_modified_time":"2026-02-17T06:59:19+00:00","og_image":[{"width":910,"height":607,"url":"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_91745108.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/przedszkolefairplay.info.pl\/en\/art-classes\/","url":"https:\/\/przedszkolefairplay.info.pl\/en\/art-classes\/","name":"Art classes - FairPlay Kindergarten","isPartOf":{"@id":"https:\/\/przedszkolefairplay.info.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/przedszkolefairplay.info.pl\/en\/art-classes\/#primaryimage"},"image":{"@id":"https:\/\/przedszkolefairplay.info.pl\/en\/art-classes\/#primaryimage"},"thumbnailUrl":"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_91745108.webp","datePublished":"2025-11-27T14:09:31+00:00","dateModified":"2026-02-17T06:59:19+00:00","breadcrumb":{"@id":"https:\/\/przedszkolefairplay.info.pl\/en\/art-classes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/przedszkolefairplay.info.pl\/en\/art-classes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/przedszkolefairplay.info.pl\/en\/art-classes\/#primaryimage","url":"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_91745108.webp","contentUrl":"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2026\/01\/AdobeStock_91745108.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/przedszkolefairplay.info.pl\/en\/art-classes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/przedszkolefairplay.info.pl\/en\/"},{"@type":"ListItem","position":2,"name":"Art classes"}]},{"@type":"WebSite","@id":"https:\/\/przedszkolefairplay.info.pl\/#website","url":"https:\/\/przedszkolefairplay.info.pl\/","name":"FairPlay Kindergarten","description":"","publisher":{"@id":"https:\/\/przedszkolefairplay.info.pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/przedszkolefairplay.info.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/przedszkolefairplay.info.pl\/#organization","name":"FairPlay Kindergarten","url":"https:\/\/przedszkolefairplay.info.pl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/przedszkolefairplay.info.pl\/#\/schema\/logo\/image\/","url":"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/logo-7.png","contentUrl":"https:\/\/przedszkolefairplay.info.pl\/wp-content\/uploads\/2025\/10\/logo-7.png","width":260,"height":122,"caption":"FairPlay Kindergarten"},"image":{"@id":"https:\/\/przedszkolefairplay.info.pl\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"katarzyna","author_link":"https:\/\/przedszkolefairplay.info.pl\/en\/author\/katarzyna\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/przedszkolefairplay.info.pl\/en\/wp-json\/wp\/v2\/pages\/12441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/przedszkolefairplay.info.pl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/przedszkolefairplay.info.pl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/przedszkolefairplay.info.pl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/przedszkolefairplay.info.pl\/en\/wp-json\/wp\/v2\/comments?post=12441"}],"version-history":[{"count":1,"href":"https:\/\/przedszkolefairplay.info.pl\/en\/wp-json\/wp\/v2\/pages\/12441\/revisions"}],"predecessor-version":[{"id":12449,"href":"https:\/\/przedszkolefairplay.info.pl\/en\/wp-json\/wp\/v2\/pages\/12441\/revisions\/12449"}],"wp:attachment":[{"href":"https:\/\/przedszkolefairplay.info.pl\/en\/wp-json\/wp\/v2\/media?parent=12441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}